{"id":136,"date":"2008-11-28T11:58:09","date_gmt":"2008-11-28T11:58:09","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/?p=136"},"modified":"2008-11-28T11:58:09","modified_gmt":"2008-11-28T11:58:09","slug":"ajustes-cuentas","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/2008\/11\/28\/ajustes-cuentas\/","title":{"rendered":"Ajustes de cuentas"},"content":{"rendered":"\n<p style=\"margin-bottom: 0cm;\">Leo que Alfredo Landa en sus memorias reparte estopa en todas las direcciones. No he le\u00eddo el libro. Tan s\u00f3lo lo que de \u00e9l se ha escrito en los medios. Incluidas las declaraciones del protagonista que, por cierto, no ha censurado &#8211;\u00bfo ha sido idea suya?\u2014que se titulen \u2018Alfredo el Grande\u2019. Vale.  <\/p>\n<p style=\"margin-bottom: 0cm;\">Lo que ha trascendido, supongo, con su benepl\u00e1cito, son las miserias del oficio que parecen ocupar una parte sustancial de la obra. (El mal car\u00e1cter rayano en la crueldad de un inmenso actor que fue Fernando Fern\u00e1n-G\u00f3mez, el divismo de Imperio Argentina, la racaner\u00eda de Jos\u00e9 Luis Dibildos, la cicater\u00eda personal de Garci, las malas artes profesionales de Jos\u00e9 Luis L\u00f3pez V\u00e1zquez, el egocentrismo de Gracita Morales\u2026 Y as\u00ed sucesivamente. No s\u00e9 si se salva alguien, pero si la grandeza se mide por algo m\u00e1s que el tama\u00f1o f\u00edsico, como parece sugerir el t\u00edtulo de las memorias, su protagonista queda en estas entrevistas y rese\u00f1as bastante disminuido.<\/p>\n<p style=\"margin-bottom: 0cm;\">No descarto que el libro sea m\u00e1s que lo que parece: un ajuste de cuentas de alguien que ha llegado al final de su carrera con amarguras o rencores no resueltos, que bien podr\u00eda haber titulado la obra \u2018\u00a1Os vais a enterar!\u2019. Tampoco hay que descartar que, siguiendo el libro de estilo que imponen las nuevas tendencias, tanto las rese\u00f1as period\u00edsticas como las preguntas hayan hecho hincapi\u00e9 en los m\u00e1s amarillento de sus p\u00e1ginas, lo que a la postre reportar\u00e1 ping\u00fces beneficios en taquilla., y que dentro haya alguna idea, emoci\u00f3n positiva, relaci\u00f3n amistosa o experiencia digna de ser contada en un oficio no siempre bien tratado. Por supuesto que no se esperaban grandes elucubraciones ni descubrimientos acerca de tan apasionante profesi\u00f3n.<\/p>\n<p style=\"margin-bottom: 0cm;\">Pero al hilo de sus declaraciones pienso \u00a1qu\u00e9 necesidad!. Al fin y al cabo, Alfredo Landa hab\u00eda redimido su pasado de actor insignia de la Espa\u00f1a m\u00e1s cutre de la Transici\u00f3n. Hab\u00eda conseguido gracias a la confianza de algunos directores y personajes que era un actor capaz de hacer m\u00e1s cosas aparte de saltar de cama en cama en calzoncillos, como el mismo dice de sus a\u00f1os m\u00e1s locos profesionalmente hablando. Y ahora que estaba rehabilitado y que se hab\u00eda retirado por la puerta grande y con la bendici\u00f3n de un Goya honor\u00edfico &#8211;cuyo discurso de agradecimiento tuvo en vilo a media Espa\u00f1a y humaniz\u00f3 a\u00fan m\u00e1s al personaje\u2014va y arremete sin pudor contra tirios y troyanos sum\u00e1ndose a esa corrala de vecindonas en la que algunos se empe\u00f1an en convertir la vida pseudo cultural espa\u00f1ola.<\/p>\n<p style=\"margin-bottom: 0cm;\">Hace falta haber hecho cosas muy grandes e importantes como para que algunos asuntillos de orden casi dom\u00e9stico tengan inter\u00e9s en un libro de recuerdos. Aunque ahora lo que priva es sacar alg\u00fan trapo sucio que pueda ensombrecer carreras ilustres <strong><\/strong><strong><\/strong><strong><\/strong>en el orden que sea. Lastima que los grandes hechos no sean noticia y s\u00ed las peque\u00f1as miserias con las que al parecer muchos se pueden identificar. \u00a1As\u00ed nos va!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Leo que Alfredo Landa en sus memorias reparte estopa en todas las direcciones. No he le\u00eddo el libro. Tan s\u00f3lo lo que de \u00e9l se ha escrito en los medios. Incluidas las declaraciones del protagonista que, por cierto, no ha censurado &#8211;\u00bfo ha sido idea suya?\u2014que se titulen \u2018Alfredo el Grande\u2019. Vale. Lo que ha [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-136","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/posts\/136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/comments?post=136"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/posts\/136\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/media?parent=136"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/categories?post=136"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/tags?post=136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}