{"id":171,"date":"2009-05-19T13:34:00","date_gmt":"2009-05-19T13:34:00","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/?p=171"},"modified":"2009-05-19T13:34:00","modified_gmt":"2009-05-19T13:34:00","slug":"benedetti","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/2009\/05\/19\/benedetti\/","title":{"rendered":"Benedetti"},"content":{"rendered":"<p><BIG>Este &#8216;post&#8217; responde a la invitaci\u00f3n de un comunicante an\u00f3nimo que lo pidi\u00f3 en un comentario de la entrada anterior. Y va para todos los que dsfrut\u00e1bais de la poes\u00eda de Benedetti, un autor que tuvo el m\u00e9rito de saber llegar a mucha gente, incluida la que no suele frecuentar la poes\u00eda. De ah\u00ed que muchos poemas se convirtieran f\u00e1cilmente en canciones que acabaron formando parte de la banda sonora de nuestras vidas. Yo me quedo con su compromiso vital y con una imagen que se me viene a la cabeza cuando pienso en \u00e9l. (Aparte del par de ocasiones en que pude entrevistarle). Me refiero a su &#8216;cameo&#8217; en la pel\u00edcula &#8216;El lado oscuro del coraz\u00f3n&#8217;, maravillosa pel\u00edcula de Eliseo Subiela, en la que una buena parte de los di\u00e1logos estaba compuesta por poemas suyos. \u00bfQui\u00e9n dijo que los poetas comprometidos no tienen sentido del humor?<\/BIG><\/p>\n<p><BIG>En cualquier caso, el mejor homenaje que le podemos hacer a un poeta es recordar su obra. Acababa de publicar en Visor su \u00faltimo libro, &#8216;Testigo de uno mismo&#8217;. A \u00e9l pertenece este poema que indica que fue &#8216;genio y figura&#8217;<\/BIG><\/p>\n<p><BIG><\/p>\n<p>SONETO DE LA ESCOBA<\/p>\n<p>Una escoba ser\u00eda necesaria<br \/>\npara barrer del hoy tanta inmundicia<br \/>\ntanto culto del mal tanta injusticia<br \/>\ntanta crueldaz voraz estrafalaria<\/p>\n<p>como es obvio no sirve la plegaria<br \/>\nni cierta desconfianza vitalicia<br \/>\nhay que acabar tambi\u00e9n con la codicia<br \/>\ny la arrogancia valetudinaria<\/p>\n<p>barrer a aqu\u00e9l in\u00fatil potentado<br \/>\nque untaba a los ingenuos con ofrendas<br \/>\ny se cre\u00eda due\u00f1o del mercado<\/p>\n<p>acabar de una vez con el que roba<br \/>\ncon el que miente a todos y a sabiendas<br \/>\npor favor que nos traigan una escoba.<\/p>\n<p><\/BIG><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este &#8216;post&#8217; responde a la invitaci\u00f3n de un comunicante an\u00f3nimo que lo pidi\u00f3 en un comentario de la entrada anterior. Y va para todos los que dsfrut\u00e1bais de la poes\u00eda de Benedetti, un autor que tuvo el m\u00e9rito de saber llegar a mucha gente, incluida la que no suele frecuentar la poes\u00eda. De ah\u00ed que [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,19],"tags":[82,434],"class_list":["post-171","post","type-post","status-publish","format-standard","hentry","category-libros","category-poesia","tag-benedetti","tag-testigo-de-uno-mismo"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/posts\/171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/comments?post=171"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/posts\/171\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/media?parent=171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/categories?post=171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/tags?post=171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}