{"id":178,"date":"2009-06-18T18:17:00","date_gmt":"2009-06-18T18:17:00","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/?p=178"},"modified":"2009-06-18T18:17:00","modified_gmt":"2009-06-18T18:17:00","slug":"inocente-como-kiwi","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/2009\/06\/18\/inocente-como-kiwi\/","title":{"rendered":"Inocente como un kiwi"},"content":{"rendered":"<p><big>(Publicado en la edici\u00f3n impresa de El Norte de Castilla el 18 de junio del 2009)<\/p>\n<p>Result\u00f3 lo esperado. La selecci\u00f3n de Nueva Zelanda fue muy poca cosa ante la roja en el comienzo de la Copa Federaci\u00f3n.  Y se comi\u00f3 un cinco a cero. Pero hubo un aspecto del partido que al parecer no fue tan previsible. Al d\u00eda siguiente los titulares de los peri\u00f3dicos calificaban <\/big><big>al equipo neozeland\u00e9s con adjetivos como \u2018noble\u2019, \u2018ingenuo\u2019, \u2018inocente\u2019. Ya saben con ese toque entre peyorativo o condescendiente. No me sorprendi\u00f3 demasiado. Eran los mismos que hab\u00eda escuchado a los comentaristas de radio durante el partido. Como solo ocurr\u00edan goles y solo de una parte, y no ocurr\u00edan patadas, ni entradas salvajes, ni juego sucio&#8230; Hab\u00eda poco que comentar. Me atrever\u00eda a decir que lo sent\u00edan.  Resulta que los neozelandeses perd\u00edan como caballeros cuando a este otro lado del mundo lo normal es que si un equipo est\u00e1 en inferioridad de condiciones, trate de parar la contrario a base de juego duro. Y si en la refriega alguna estrella sale estrellada, pues misi\u00f3n cumplida. Es lo normal. Cosas del deporte de \u2018\u00e9lite\u2019. De machos.  Que se lo digan si no a Cristiano Ronaldo. (\u00a1Vaya\u00a1 Ya sali\u00f3 y eso que no quer\u00eda hablar de este personaje en mi columna&#8230;)  Ver\u00e1n es que a m\u00ed lo de los 94 millones que ha pagado el Madrid por \u00e9l me escandaliza a medias. Quiero decir, que en estas cosas conviene no ser demasiado hip\u00f3critas, porque el sistema que santificamos como el mejor de los posibles permite estas aberraciones y otras peores.<\/big><br \/>\n<big>A m\u00ed lo que me fastidia es que se pague ese dineral por un presunto deportista que se va a convertir en un modelo para muchos ni\u00f1os y j\u00f3venes y que, como demostr\u00f3 en la final de la Champions frente al Bar\u00e7a, cuando se ve impotente se da al juego sucio. Un prepotente, vamos, que, por si no estaba claro, afirma que disfruta viendo el odio en las caras de la gente. Sobre esto los comentaristas tambi\u00e9n son blandos. (o muy machos). Son cosas de la edad, dicen. De eso nada. Conozco muchos chicos de su edad que no son as\u00ed ni de lejos, pero como no tienen pasta, ni salen en la tele, no sirven de ejemplo. \u00bfY \u00e9ste va a encarnar alg\u00fan valor relacionado con el esfuerzo, la superaci\u00f3n, el trabajo de equipo, la deportividad?  Perdonen si no me lo creo. (Y no voy a hacer chistes sobre con qui\u00e9n se divierte&#8230; All\u00e1 cada cual con su vida privada) <\/big><br \/>\n<big>Soy madridista qu\u00e9 se le va a hacer. Al final, el pueblo tira. Pero este Real Madrid de Florentino tirando de chequera como un tratante de ganado y fichando estos sujetos para hacer dinero con el \u2018merchandising\u2019, adem\u00e1s de parecerme hortera, me da grima<\/big>.<br \/>\n<big> Claro que mientras hablamos de estas cosas no miramos a los juzgados donde los representantes pol\u00edticos elegidos para defender los intereses del com\u00fan andan en entredicho por cosillas de nada como cohechos o delitos contra la hacienda p\u00fablica. Asuntillos que al parecer mucha gente ve tan normales en los pol\u00edticos como las megapatadas en los futbolistas. Me preocupa. Aunque bien pensado el problema debe de ser m\u00edo. Debo de parecer ingenua&#8230; o m\u00e1s inocente que un kiwi.<\/big><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Publicado en la edici\u00f3n impresa de El Norte de Castilla el 18 de junio del 2009) Result\u00f3 lo esperado. La selecci\u00f3n de Nueva Zelanda fue muy poca cosa ante la roja en el comienzo de la Copa Federaci\u00f3n. Y se comi\u00f3 un cinco a cero. Pero hubo un aspecto del partido que al parecer no [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-178","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/posts\/178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/comments?post=178"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/posts\/178\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/media?parent=178"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/categories?post=178"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/tags?post=178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}