{"id":186,"date":"2009-07-30T13:10:00","date_gmt":"2009-07-30T13:10:00","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/?p=186"},"modified":"2009-07-30T13:10:00","modified_gmt":"2009-07-30T13:10:00","slug":"las-vacas-flacas-de-cine","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/2009\/07\/30\/las-vacas-flacas-de-cine\/","title":{"rendered":"Las vacas flacas (de cine)"},"content":{"rendered":"<p><big>Si hay datos que empiezan a parecerse a los del paro, por lo que tienen de preocupantes, son los que peri\u00f3dicamente facilita el Instituto de las Ciencias y las Artes Audiovisuales (ICAA) sobre la afluencia de espectadores a las salas de cine. Con la diferencia de que \u00e9stos no parecen reversibles por muchos planes que se pongan en marcha (que no se van a poner).<\/big><br \/>\n<big>Que la forma de ver el cine est\u00e1 cambiando es algo que parece inevitable, pero que algunos aceptamos a rega\u00f1adientes. Las cifras son contundentes y los hechos tambi\u00e9n.<\/big><br \/>\n<big>Las cifras. En los seis primeros meses del a\u00f1o, la asistencia de espectadores a las salas baj\u00f3 el 15,2% (pas\u00f3 de 55,9 millones a 47,4 millones de espectadores), con respecto al mismo periodo del a\u00f1o anterior. Si s\u00f3lo nos fijamos en el cine espa\u00f1ol, las datos son a\u00fan m\u00e1s negros: perdi\u00f3 2,3 millones de espectadores, lo que supone el 32% del total.<\/big><br \/>\n<big>Los hechos. Valladolid fue hasta no hace mucho una de las provincias de Espa\u00f1a mejor situadas en cuanto al n\u00famero de butacas de cine por habitante y ese lugar de privilegio se mantuvo hasta el a\u00f1o pasado en que segu\u00eda ocupando el tercer lugar. El reciente cierre de los cines Parquesol habr\u00e1 ara\u00f1ado alg\u00fan puesto al ranking aunque desgraciadamente el fen\u00f3meno est\u00e1 tan generalizado como la gripe A. <\/big><br \/>\n<big>Malas noticias para quienes seguimos viendo el cine como un gozoso acto colectivo. Y para quienes no nos resignamos a ver las pel\u00edculas en pantalla dom\u00e9stica y en condiciones t\u00e9cnicas mucho m\u00e1s deficientes que en las salas, aunque de vez en cuando haya que soportar g\u00e9lidas temperaturas, comedores de patatas fritas o a esa gente que tiene que comentar la pel\u00edcula en susurros a su acompa\u00f1ante como si \u00e9ste fuera ciego. Para algunos, sospecho que cada vez menos, la sala a oscuras de un cine sigue siendo un lugar donde la magia es posible, donde lo que ocurre en la pantalla te envuelve precisamente porque no est\u00e1s rodeado por tu ambiente cotidiano, porque no hay luces ni ruidos extra\u00f1os a la acci\u00f3n que puedan distraerte y porque ese momento no tiene comparaci\u00f3n con la visi\u00f3n de una pel\u00edcula pirateada en malas condiciones que para algunos parece equiparable a haberla visto.<\/big><br \/>\n<big>Como el fen\u00f3meno es muy anterior a la crisis, habr\u00e1 que buscar otros culpables. Y a m\u00ed se me ocurre que uno de ellos, de dif\u00edcil soluci\u00f3n, es la falta de educaci\u00f3n de la que, en materia cinematogr\u00e1fica y audiovisual en general, adolece el sistema educativo espa\u00f1ol, tan poco afecto a las artes en las materias comunes.<\/big><br \/>\n<big>Los aficionados de Valladolid (las malas lenguas dicen que \u00e9stos no existen salvo en la Seminci, un comentario que siempre me ha parecido exagerado pero que quiz\u00e1 tenga algo de raz\u00f3n) tenemos adem\u00e1s otro problema: ya no es que se cierren cines, es que cada vez son m\u00e1s las pel\u00edculas que no se estrenan. La cartelera se va llenando poco a poco de lo m\u00e1s comercial y faltan t\u00edtulos y no de los m\u00e1s rebuscados. Esto dice poco de una ciudad con festival con pedigree y curso de cine potente.<\/big><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si hay datos que empiezan a parecerse a los del paro, por lo que tienen de preocupantes, son los que peri\u00f3dicamente facilita el Instituto de las Ciencias y las Artes Audiovisuales (ICAA) sobre la afluencia de espectadores a las salas de cine. Con la diferencia de que \u00e9stos no parecen reversibles por muchos planes que [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,5,7,20],"tags":[186],"class_list":["post-186","post","type-post","status-publish","format-standard","hentry","category-actualidad","category-cine","category-espectaculos","category-seminci","tag-espectadores-de-cine"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/posts\/186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/comments?post=186"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/posts\/186\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/media?parent=186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/categories?post=186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/tags?post=186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}