{"id":203,"date":"2009-10-24T16:53:00","date_gmt":"2009-10-24T16:53:00","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/?p=203"},"modified":"2009-10-24T16:53:00","modified_gmt":"2009-10-24T16:53:00","slug":"al-borde-la-alfombra-1","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/2009\/10\/24\/al-borde-la-alfombra-1\/","title":{"rendered":"Al borde de la alfombra (1)"},"content":{"rendered":"<p><big>Todos los a\u00f1os me suelo perder la gala inaugural porque estoy en el cine. Y la verdad, no suele importarme mucho. Pero est<\/big><IMG src=\"\/angelicatanarro\/wp-content\/uploads\/sites\/2\" id=\"img_1\" class=\"imgdcha\" height=\"241\" width=\"295\"><big>a vez s\u00ed lo he sentido. &#8220;La m\u00e1s divertida de los \u00faltimos a\u00f1os&#8221;, era el comentario un\u00e1nime en el cocktail inaugural. Siempre hay alguien que va m\u00e1s lejos: &#8220;la \u00fanica divertida en toda la historia de la Seminci&#8221;. El mago de tanta unanimidad. (Y mira que si hay un sitio donde la unanimidad es una rareza, casi un milagro, es este Festival). Tiene nombre irland\u00e9s. O as\u00ed. \u00c9l es Alex O&#8217;Dogherty, el actor que se meti\u00f3 al p\u00fablico en el bolsillo a fuerza de no querer parecer gracioso sino de tener gracia. El rap de los patrocinadores quedar\u00e1 como un hito en la <\/big><big>historia del Festival. Mientras el personal se lo pasaba en grande yo estaba sufriendo con los personajes de Angelopoulos. As\u00ed se escribe la historia, aunque sea la historia peque\u00f1ita. Bueno, tuve un premio de consolaci\u00f3n. La entrada del susodicho (que por cierto hace de poli municipal ingenuo en la serie de televisi\u00f3n Dr. Mateo y parece imposible que sean el mismo, o sea que es un buen actor) en plan l\u00edder de grupo musical a medio camino entre charanga y jazz band confirm\u00f2 que este chico sabe hacer de todo. Un gran showman. En alguna emisora o\u00ed que ped\u00edan que presentara la pr\u00f3xima gala de los Goya. Ser\u00eda mi oportunidad, porque no suelo perd\u00e9rmela. Lo dicho, Alex O&#8217;Dogherty, oiremos m\u00e1s cosas de \u00e9l.<\/big><\/p>\n<p>(En la foto de Gabriel Villamil, Alex&#8217;Dogherty, durante la gala)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Todos los a\u00f1os me suelo perder la gala inaugural porque estoy en el cine. Y la verdad, no suele importarme mucho. Pero esta vez s\u00ed lo he sentido. &#8220;La m\u00e1s divertida de los \u00faltimos a\u00f1os&#8221;, era el comentario un\u00e1nime en el cocktail inaugural. Siempre hay alguien que va m\u00e1s lejos: &#8220;la \u00fanica divertida en toda [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,20],"tags":[53],"class_list":["post-203","post","type-post","status-publish","format-standard","hentry","category-cine","category-seminci","tag-alex-o-dogherty"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/posts\/203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/comments?post=203"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/posts\/203\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/media?parent=203"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/categories?post=203"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/tags?post=203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}