{"id":211,"date":"2009-10-30T21:40:00","date_gmt":"2009-10-30T21:40:00","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/?p=211"},"modified":"2009-10-30T21:40:00","modified_gmt":"2009-10-30T21:40:00","slug":"apuntes-paralelos-4","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/2009\/10\/30\/apuntes-paralelos-4\/","title":{"rendered":"Apuntes paralelos (4)"},"content":{"rendered":"<h3>LOS QUE SE SALIERON DE SUS CASILLAS<\/h3>\n<p><big> El buen tono general de la Secci\u00f3n Oficial ha hecho de la 54 edici\u00f3n del Festival, como ya he dicho, una edici\u00f3n de navegaci\u00f3n tranquila. Pero no es precisamente malo decir de un Festival que ha mentenido una media de notable en las producciones programadas. Quiz\u00e1 se ha echado de menos una de esas pel\u00edculas que sorprenden, de las que se habla una y otra vez en las tertulias, de las que marcan una edici\u00f3n. Pero se ha visto buen cine y de eso se trata. Quiz\u00e1 el denominador com\u00fan haya sido ese salirse de la norma que han exhibido algunos de los directores de marcada personalidad que estaban convocados. Ayaso y Sabroso, Gu\u00e8diguian, Sam Mendes, o el mismo Schrader se han salido de sus casillas para demostrar que saben hacer otras cosas. Qu\u00e9 bien que lo hayan hecho aqu\u00ed.<\/big><\/p>\n","protected":false},"excerpt":{"rendered":"<p>LOS QUE SE SALIERON DE SUS CASILLAS El buen tono general de la Secci\u00f3n Oficial ha hecho de la 54 edici\u00f3n del Festival, como ya he dicho, una edici\u00f3n de navegaci\u00f3n tranquila. Pero no es precisamente malo decir de un Festival que ha mentenido una media de notable en las producciones programadas. Quiz\u00e1 se ha [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,20],"tags":[],"class_list":["post-211","post","type-post","status-publish","format-standard","hentry","category-cine","category-seminci"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/posts\/211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/comments?post=211"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/posts\/211\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/media?parent=211"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/categories?post=211"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/tags?post=211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}