{"id":215,"date":"2009-11-01T17:23:00","date_gmt":"2009-11-01T17:23:00","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/?p=215"},"modified":"2009-11-01T17:23:00","modified_gmt":"2009-11-01T17:23:00","slug":"creo-tengo-mono-el-dia-despues","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/2009\/11\/01\/creo-tengo-mono-el-dia-despues\/","title":{"rendered":"Creo que tengo mono (El d\u00eda despu\u00e9s)"},"content":{"rendered":"<p><big>Esta ma\u00f1ana me he levantado tarde y no ten\u00eda que ir al cine. As\u00ed que me sent\u00eda rara. Creo que tengo mono. As\u00ed que me puse a pensar cu\u00e1les hab\u00edan sido los mejores momentos del Festival, dejando aparte, claro, el cine en s\u00ed mismo y el reencuentro con colegas a los que s\u00f3lo se ve en esta cita y que siempre es estimulante o con los que mantenemos m\u00e1s trato pero estos d\u00edas se hace m\u00e1s intenso<\/big>.<br \/>\n<IMG src=\"\/angelicatanarro\/wp-content\/uploads\/sites\/2\" id=\"img_1\" class=\"imgdcha\" height=\"158\" width=\"323\"><br \/>\n<big>Y creo que han sido fundamentalmente dos, y est\u00e1n ligados a dos personas del cine a los que admiro profundamente. Uno de ellos tiene que ver con Geraldine Chaplin. Durante la fiesta de &#8216;La isla interior&#8217;, en la que hace el papel de madre dura y controladora, tuvimos ocasi\u00f3n de hablar de una pel\u00edcula que a las dos nos hab\u00eda gustado especialmente, &#8216;Adam Resurrected&#8217;, de Schrader. Disfrut\u00e9 por la forma en que defend\u00eda un filme &#8220;que toca con valent\u00eda el da\u00f1o que un ser humano puede hacer a otro&#8221;. Mientras me hablaba yo estaba fascinada por la fuerza y el magnetismo que desprende esta mujer, que a los 65 a\u00f1os no ha perdido ni la conciencia del necesario compromiso ni la pasi\u00f3n. Ni la fuerza en la mirada, que sigue siendo espl\u00e9ndida. Una mujer que demuestra que se puede tener un enorme atractivo sin renunciar a las arrugas, que el tiempo va dejando en el rostro de una vida vivida. Un placer, a pesar de que el volumen de la m\u00fasica en estos encuentros impide cualquier tipo de conversaci\u00f3n.<\/big><br \/>\n<IMG src=\"\/angelicatanarro\/wp-content\/uploads\/sites\/2\" id=\"img_0\" class=\"imgdcha\" height=\"221\" width=\"324\"><br \/>\n<big>El segundo tiene que ver con Ettore Scola. Fue un aut\u00e9ntico placer compartir un desayuno con alguien a quien siempre agradecer\u00e9 el papel de Gassman en &#8216;La familia&#8217; o las interpretaciones de Mastroiani y Loren en &#8216;Una jornada particular&#8217;. Al contrario que Gerarda, \u00e9l s\u00ed ha perdido la pasi\u00f3n.Y lo quiso dejar meridianamente claro, incluso con un tono algo gru\u00f1\u00f3n, para explicar por qu\u00e9 ya no hace cine. &#8220;Para hacer cine hay que amar a tu pa\u00eds y yo cada vez lo amo menos&#8221;. Fue una delicia escuchar c\u00f3mo consigui\u00f3 lo que consigui\u00f3 de sus actores. &#8220;Cuando eleg\u00eda a los protagonistas de mis pel\u00edculas ya les conoc\u00eda bien, \u00e9ramos amigos o conoc\u00eda sus carreras. Procuaraba buscar algo que no hubieran hecho antes. Gassman era un monumento tanto en lo f\u00edsico como en lo psicol\u00f3gico, pero tamti\u00e9n era un hombre sensible. As\u00ed que le di un papel (&#8216;En la familia&#8217;) de un hombre incapaz de tomar una sola decisi\u00f3n ni contra el fascismo, y que viv\u00eda con una mujer porque amaba a su hermana. Sab\u00eda que Gassman que es un hombre inteligente y lo contrario de ese personaje lo har\u00eda muy bien&#8221;. Y lo mismo con Mastroiani, el latin lover que \u00e9l convirti\u00f3 en un homosexual o Sof\u00eda Loren, el s\u00edmbolo &#8220;de la prosperidad napolitana&#8221;, convertida en una mujer sin ning\u00fan atractivo sexual, ni inteligencia.<\/big><br \/>\n<big>Ni siquiera el director del Festival, Javier Angulo, admirador de su cine y de su espl\u00e9ndida manera de escribir guiones, consigui\u00f3 arrancarle una sonrisa. \u00c9l s\u00ed lo hizo en el auditorio con sus iron\u00edas sobre la Italia actual, Berlusconi o los directores j\u00f3venes. Y fue un aut\u00e9ntico placer.<\/p>\n<p><\/big><em>(En las fotos de Gabriel Villamil, Geraldine Chaplin y Ettore Scola, durante la Seminci<\/em><big>)<\/big><\/p>\n<p> <del><\/p>\n<p><\/del><del> <\/del><del><\/del> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta ma\u00f1ana me he levantado tarde y no ten\u00eda que ir al cine. As\u00ed que me sent\u00eda rara. Creo que tengo mono. As\u00ed que me puse a pensar cu\u00e1les hab\u00edan sido los mejores momentos del Festival, dejando aparte, claro, el cine en s\u00ed mismo y el reencuentro con colegas a los que s\u00f3lo se ve [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,20],"tags":[190,221],"class_list":["post-215","post","type-post","status-publish","format-standard","hentry","category-cine","category-seminci","tag-ettore-scola","tag-geraldine-chaplin"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/posts\/215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/comments?post=215"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/posts\/215\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/media?parent=215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/categories?post=215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/tags?post=215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}