{"id":229,"date":"2010-02-01T19:08:00","date_gmt":"2010-02-01T19:08:00","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/?p=229"},"modified":"2010-02-01T19:08:00","modified_gmt":"2010-02-01T19:08:00","slug":"cuando-pasado-parece-tan-moderno","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/2010\/02\/01\/cuando-pasado-parece-tan-moderno\/","title":{"rendered":"Cuando el pasado parece tan moderno"},"content":{"rendered":"\n<p style=\"margin-bottom: 0cm;\"><IMG src=\"\/angelicatanarro\/wp-content\/uploads\/sites\/2\" id=\"img_0\" class=\"imgcen\" height=\"732\" width=\"502\"><span style=\"color: rgb(0, 0, 0);\"><font face=\"Brioni Std Bold, monospace\"><font size=\"3\">\u00abHablar cada vez m\u00e1s despacio, hasta que pronunciar una palabra dure a\u00f1os\u00bb. (Felipe Boso dixit). \u00a1Ah, las palabras! Inesperadamente alejadas, divorciadas casi, de su significado, jugando a significar otra cosa, a no significar nada. Soltando amarras en un poema, abriendo las c\u00e1rceles de las estrofas, dejando libertad a las letras para que se burlen del papel pautado. Los herederos de Tzara, de Breton, se pusieron manos a la obra y parieron palabras objeto, poemas que rimaban apariencias y distancias, ocurrencias o ideas luminosas. Fueron otros tiempos pero parecen el puro presente. Est\u00e1n ah\u00ed para bajarnos los humos de la modernidad, para sonrojarnos por nuestra acomodaticia manera de usar las palabras en la poes\u00eda, en la vida&#8230; Esas perras negras, que dec\u00eda Cort\u00e1zar&#8230;<\/span><\/span><\/span><font face=\"Brioni Std Bold, monospace\"><font size=\"3\"><\/p>\n<p><em><\/em><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;\"><em>(A prop\u00f3stito de la exposici\u00f3n &#8216;Escrito est\u00e1&#8217; sobre poes\u00eda de vanguardia en el Patio Herreriano de Valladolid. Publicado en el suplemento cultural de El Norte, &#8216;La sombra del cipr\u00e9s&#8217;. En la imagen, un poema de Felipe Boso)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abHablar cada vez m\u00e1s despacio, hasta que pronunciar una palabra dure a\u00f1os\u00bb. (Felipe Boso dixit). \u00a1Ah, las palabras! Inesperadamente alejadas, divorciadas casi, de su significado, jugando a significar otra cosa, a no significar nada. Soltando amarras en un poema, abriendo las c\u00e1rceles de las estrofas, dejando libertad a las letras para que se burlen del [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,13,19],"tags":[377,378],"class_list":["post-229","post","type-post","status-publish","format-standard","hentry","category-arte","category-literatura","category-poesia","tag-poesia-experimental","tag-poesia-visual"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/posts\/229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/comments?post=229"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/posts\/229\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/media?parent=229"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/categories?post=229"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/tags?post=229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}