{"id":263,"date":"2010-10-01T21:08:00","date_gmt":"2010-10-01T21:08:00","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/?p=263"},"modified":"2010-10-01T21:08:00","modified_gmt":"2010-10-01T21:08:00","slug":"futuro-imperfecto","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/2010\/10\/01\/futuro-imperfecto\/","title":{"rendered":"Futuro imperfecto"},"content":{"rendered":"<p><big>El otro d\u00eda estaba mirando la calle y se empa\u00f1aron los cristales de la ventana con mi respiraci\u00f3n. Entonces supe que se hab\u00eda acabado el verano. Fue una sensaci\u00f3n f\u00edsica extra\u00f1a porque me vino la infancia de golpe. \u00bfA qui\u00e9n no le ha rega\u00f1ado su madre por manchar el cristal reci\u00e9n limpio dibujando corazones? <\/big><br \/>\n<big>Encima de la mesa tengo un libro de cuentos de Medardo Fraile que ha publicado P\u00e1ginas de Espuma. Lo tengo ah\u00ed, a\u00fan sin abrir, formando parte de la pila de libros pendientes. Me gusta tenerlos cerca porque, aunque me recuerdan que el d\u00eda solo tiene 24 horas y no hay manera de leer todo lo que me gustar\u00eda, me acompa\u00f1an. Este est\u00e1 encima de todos porque me gusta su t\u00edtulo: \u2018Antes del futuro imperfecto\u2019 y no es verdad que no lo haya abierto. Lo oje\u00e9. Dentro hay historias del colegio, del instituto&#8230;, de ese tiempo anterior al  futuro imperfecto. En la portada, una ni\u00f1a con trenzas y un babi de cuadros sonr\u00ede en su pupitre. Yo no tuve trenzas y mi pupitre era m\u00e1s moderno que el de la foto pero tuve babi y me identifico con ella. Creo que nos hacemos mayores el d\u00eda que nos damos cuenta de que el futuro adem\u00e1s de un asunto que se acorta irremediablemente no es eso glorioso que imagin\u00e1bamos al hilo de los cuentos propios y ajenos.<\/big><br \/>\n<big>Futuro imperfecto&#8230; Escribo esta columna el mi\u00e9rcoles, el d\u00eda de la huelga general, mientras hago un seguimiento de los resultados. Y pienso que al final del d\u00eda me gustar\u00eda saber si de verdad la huelga ha tenido \u00e9xito. No digo los trabajadores, que esos ya s\u00e9 que no. Digo la huelga. Lo podr\u00edamos saber si todos los que no la han hecho por miedo a perder el trabajo o porque su situaci\u00f3n es tan apurada que una merma en su ya justo salario les supone un drama, y los que la han hecho por miedo a las represalias de esos piquetes que se llaman informativos pero entienden el verbo informar de un modo extra\u00f1o  \u2013aunque fueran temores exagerados\u2013 hubieran estado en la casilla que de verdad les correspond\u00eda. Por no hablar de la gente perpleja que no entiende por qu\u00e9 ahora y no encuentra ya ni en qu\u00e9 casilla acomodarse. Pero no lo lograremos.<\/big><br \/>\n<big>Aqu\u00ed s\u00ed: futuro imperfecto. Lo malo que ese futuro se lleva gestando desde hace mucho tiempo y  el mundo parec\u00eda mirar para otro lado. Mientras sal\u00edan las cuentas se segu\u00eda estirando la goma. Todos contentos, porque Espa\u00f1a iba bien. Y Europa no digamos. De repente nos despertamos un d\u00eda y nos dimos por enterados de que el sistema financiero hab\u00eda estado alimentando no s\u00e9 qu\u00e9 hipotecas basura, aparte de la basura que en forma de corrupci\u00f3n y ladrillo afloraba por doquier sum\u00e1ndose al agujero negro de los que evaden impuestos. Da risa ahora recordar lo que se dec\u00eda acerca de la crisis del capitalismo. <\/big><br \/>\n<big>Creo que lo \u00fanico sensato que he o\u00eddo hoy (que he o\u00eddo, no que haya escuchado, que son dos verbos distintos aunque la gente los confunde) es que Felipe Gonz\u00e1lez ha dicho que habr\u00e1 nuevas crisis si no se reforma el sistema financiero mundial. Pero nadie lo escuchar\u00e1 porque estas cosas tan brutalmente obvias se suelen <\/big><big>tildar de demagogia y a otra cosa mariposa&#8230;<br \/>\nComo ven, el oto\u00f1o me ha atacado: implacable.<\/big><\/p>\n<p>(Art\u00edculo publicado en la columna de opini\u00f3n &#8216;D\u00edas nublados&#8217; en la edici\u00f3n impresa de El Norte de Castilla del 30 de septiembre de 2010)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El otro d\u00eda estaba mirando la calle y se empa\u00f1aron los cristales de la ventana con mi respiraci\u00f3n. Entonces supe que se hab\u00eda acabado el verano. Fue una sensaci\u00f3n f\u00edsica extra\u00f1a porque me vino la infancia de golpe. \u00bfA qui\u00e9n no le ha rega\u00f1ado su madre por manchar el cristal reci\u00e9n limpio dibujando corazones? Encima [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,6],"tags":[],"class_list":["post-263","post","type-post","status-publish","format-standard","hentry","category-actualidad","category-dias-nublados"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/posts\/263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/comments?post=263"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/posts\/263\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/media?parent=263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/categories?post=263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/angelicatanarro\/wp-json\/wp\/v2\/tags?post=263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}