{"id":28,"date":"2009-12-21T17:17:00","date_gmt":"2009-12-21T17:17:00","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/cari\/?p=28"},"modified":"2009-12-21T17:17:00","modified_gmt":"2009-12-21T17:17:00","slug":"no-me-llames-navidad","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/cari\/2009\/12\/21\/no-me-llames-navidad\/","title":{"rendered":"NO ME LLAMES POR NAVIDAD"},"content":{"rendered":"<p><P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><FONT face=Calibri size=3>Hay una persona, amiga muy amiga, que nunca desea le llame por Navidad.<\/FONT><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><FONT face=Calibri size=3>Pero yo ilusa de m\u00ed cada a\u00f1o le <SPAN style=\"mso-spacerun: yes\"><\/SPAN>digo lo mismo: te llamo.<\/FONT><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><FONT size=3><FONT face=Calibri><SPAN style=\"mso-spacerun: yes\"><\/SPAN>No lo har\u00e9, es su deseo, y es mi deber no hacerlo para respet\u00e1rselo.<\/FONT><\/FONT><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><FONT face=Calibri size=3>Estamos a veces muy equivocados cuando creemos que en algunas fechas hay que estar con gente, que no acompa\u00f1ados, que por supuesto no es lo mismo.<\/FONT><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><FONT face=Calibri size=3>Ella lo tiene claro.<\/FONT><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><FONT face=Calibri size=3>La soledad que es deseada, o impuesta pero sin problemas para la persona que la vive, creo que no es tanta soledad.<\/FONT><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><FONT face=Calibri size=3>Supongo que mejor eso, que la sonrisa que no desea tener, ni la frase construida solo por el d\u00eda determinado.<\/FONT><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><FONT face=Calibri size=3>Pero yo, que s\u00ed estar\u00e9 acompa\u00f1ada porque me viene ya dado, pensar\u00e9 en ella, la recordar\u00e9, <SPAN style=\"mso-spacerun: yes\"><\/SPAN>pero sabr\u00e9 que no haciendo esa llamada, justo no haci\u00e9ndola, ella mi amiga del alma me lo agradecer\u00e1.<\/FONT><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><FONT face=Calibri size=3>Y para no hacerla infeliz no sonar\u00e1 su tel\u00e9fono.<\/FONT><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><FONT face=Calibri size=3>\u00bfCu\u00e1ntas personas pueden ser y sentir c\u00f3mo mi amiga?<\/FONT><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><FONT face=Calibri size=3>Muchas, creo que muchas, y esto es comprensible en un mundo en que no todo es apariencia afortunadamente y hay soledades que no quieren ser compartidas, y hay amistades que justo por eso las deseas lejos, en la certeza de que te entender\u00e1n sin dar explicaciones.<\/FONT><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><?xml:namespace prefix = o ns = \"urn:schemas-microsoft-com:office:office\" \/><o:p><FONT face=Calibri size=3><\/FONT><\/o:p><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><FONT face=Calibri size=3>Saludos blogueros, que teng\u00e1is un feliz a\u00f1o venidero.<\/FONT><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hay una persona, amiga muy amiga, que nunca desea le llame por Navidad. Pero yo ilusa de m\u00ed cada a\u00f1o le digo lo mismo: te llamo. No lo har\u00e9, es su deseo, y es mi deber no hacerlo para respet\u00e1rselo. Estamos a veces muy equivocados cuando creemos que en algunas fechas hay que estar con [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[308,1569,1681],"class_list":["post-28","post","type-post","status-publish","format-standard","hentry","tag-amiga","tag-respeto","tag-soledades"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/posts\/28","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/comments?post=28"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/posts\/28\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/media?parent=28"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/categories?post=28"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/tags?post=28"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}