{"id":31,"date":"2010-01-04T19:54:00","date_gmt":"2010-01-04T19:54:00","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/cari\/?p=31"},"modified":"2010-01-04T19:54:00","modified_gmt":"2010-01-04T19:54:00","slug":"sera-pedir","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/cari\/2010\/01\/04\/sera-pedir\/","title":{"rendered":"SER\u00c1 POR PEDIR&#8230;"},"content":{"rendered":"<p><P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><FONT face=Calibri size=3>A los Reyes m\u00e1gicos, a esos que cumplen los sue\u00f1os y caprichos de los m\u00e1s peque\u00f1ajos de la casa.<\/FONT><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><FONT face=Calibri size=3>Padres, abuel@s volvi\u00e9ndose locos para cumplir un deseo del que se olvidar\u00e1n a las dos d\u00edas las criaturitas. Yo a\u00fan no he llegado a esa fase.<\/FONT><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><FONT face=Calibri size=3>Juguetes que quedar\u00e1n tirados, pero eso s\u00ed, han costado un potos\u00ed.<\/FONT><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><FONT face=Calibri size=3>Pero\u2026 \u00bfy nosotros? <\/FONT><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><FONT face=Calibri size=3>Los que ya no escribimos cartas a nadie porque nadie nos hace ni pu\u00f1etero caso.<\/FONT><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><FONT face=Calibri size=3>Los que nos quedamos tan agustito sabiendo que nada tenemos nada damos porque pasamos de esa parafernalia.<\/FONT><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><FONT face=Calibri size=3>Pero a pesar de \u201cpasar\u201d lo mismo hasta nos hac\u00eda ilusi\u00f3n que alguien durante unos minutos se acordara de comprarnos <SPAN style=\"mso-spacerun: yes\"> <\/SPAN>ese detallito que para nada sirve seguramente pero que debemos agradecer porque se han acordado de nosotros. \u00bfA que me contradigo?, pues SIIIII.<\/FONT><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><FONT face=Calibri size=3>Menos claro est\u00e1, si van y nos compran la plancha, o la aspiradora, o la olla a presi\u00f3n que podemos pon\u00e9rsela al autor del delito por sombrero.<\/FONT><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><FONT face=Calibri size=3>Ni Pap\u00e1 Noel, ni Reyes, mejor lo dejamos como est\u00e1, no vaya a ser que alguien se vuelva loc@ y haga un regalo que arruine la econom\u00eda familiar y no es cuesti\u00f3n.<\/FONT><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><FONT face=Calibri size=3>As\u00ed que blogueros m\u00edos yo s\u00f3lo pedir\u00e9 seguir dando el callo cada d\u00eda, que nadie me toque las narices sacando lo peor que a veces todos llevamos dentro, mirar a los que me miran, querer a los que me quieren, y sobre todo que \u00e9ste pu\u00f1etero mundo se vaya poniendo las pilas y dejen los pol\u00edticos de tomarnos el pelo, y los soberbios dejen de subirse a las barbas de los humildes.<\/FONT><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><FONT face=Calibri size=3>Felices Reyes a todos, un abrazo.<\/FONT><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><?xml:namespace prefix = o ns = \"urn:schemas-microsoft-com:office:office\" \/><o:p><FONT face=Calibri size=3> <\/FONT><\/o:p><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><o:p><FONT face=Calibri size=3> <\/FONT><\/o:p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A los Reyes m\u00e1gicos, a esos que cumplen los sue\u00f1os y caprichos de los m\u00e1s peque\u00f1ajos de la casa. Padres, abuel@s volvi\u00e9ndose locos para cumplir un deseo del que se olvidar\u00e1n a las dos d\u00edas las criaturitas. Yo a\u00fan no he llegado a esa fase. Juguetes que quedar\u00e1n tirados, pero eso s\u00ed, han costado un [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[358,717,1459],"class_list":["post-31","post","type-post","status-publish","format-standard","hentry","tag-aspiradora","tag-detallito","tag-politicos"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/posts\/31","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/comments?post=31"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/posts\/31\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/media?parent=31"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/categories?post=31"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/tags?post=31"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}