{"id":34,"date":"2010-01-20T19:03:00","date_gmt":"2010-01-20T19:03:00","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/cari\/?p=34"},"modified":"2010-01-20T19:03:00","modified_gmt":"2010-01-20T19:03:00","slug":"fumas-bebes","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/cari\/2010\/01\/20\/fumas-bebes\/","title":{"rendered":"\u00bfFUMAS, BEBES?"},"content":{"rendered":"<p><P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><FONT face=Calibri size=3>Bueno como ya hagas las dos cosas ya puedes prepararte para ser una especie de proscrit@.<\/FONT><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><FONT face=Calibri size=3>Quiz\u00e1 tengamos que plantearnos dejar esas peque\u00f1as cosas como tomar un vinito con las amigas, fumar un cigarrillo, o incluso lo mismo salir de casa s\u00f3lo a pasear.<\/FONT><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><FONT face=Calibri size=3>Tendremos que plantearnos ese san\u00edsimo gimnasio que nos sale a ***** de pato y luego a casita, o lo mismo caminar seis o siete kil\u00f3metros diarios que adem\u00e1s es gratis, si acaso se gastan los deportivos que utilizamos.<\/FONT><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><FONT face=Calibri size=3>Esto viene a cuento de que hoy en una consulta m\u00e9dica en una discusi\u00f3n con el facultativo me ha preguntado que si bebo, claro que le he dicho que si, que bebo y fumo.<\/FONT><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><FONT face=Calibri size=3>Y ya est\u00e1 organizado el lio, la culpa de esa demanda, (ajena al fumeteo y al levantamiento de vidrio) de esa indignaci\u00f3n que ha salido de mi hartazgo, era consecuencia de eso\u2026por lo visto.<\/FONT><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><FONT face=Calibri size=3>No pondr\u00e9 en duda jam\u00e1s una vida sana, que el tabaco es perjudicial para la salud, que el alcohol se debe beber con moderaci\u00f3n, hasta ah\u00ed llego.<\/FONT><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><FONT face=Calibri size=3>Pero a lo que no llego es a pensar que todos nuestros problemas, ajenos al fumar y beber, se achaquen a esto.<\/FONT><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><FONT face=Calibri size=3>Supongo es lo m\u00e1s f\u00e1cil cuando alguien te est\u00e1 poniendo un problema sobre la mesa es preguntar si fumas o bebes, hay que fastidiarse&#8230;<\/FONT><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><FONT face=Calibri size=3>Escrib\u00ed hace un tiempo en el blog \u201cque nos deshumanizan\u201d, sobre la estancia en el hospital, esta charla digamos un poco en clave de mala uva, es como una continuaci\u00f3n de aquello que a\u00fan colea.<\/FONT><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><?xml:namespace prefix = o ns = \"urn:schemas-microsoft-com:office:office\" \/><o:p><FONT face=Calibri size=3> <\/FONT><\/o:p><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><FONT face=Calibri size=3>Saludos blogueros.<\/FONT><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><o:p><FONT face=Calibri size=3> <\/FONT><\/o:p><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><o:p><FONT face=Calibri size=3> <\/FONT><\/o:p><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><o:p><FONT face=Calibri size=3> <\/FONT><\/o:p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bueno como ya hagas las dos cosas ya puedes prepararte para ser una especie de proscrit@. Quiz\u00e1 tengamos que plantearnos dejar esas peque\u00f1as cosas como tomar un vinito con las amigas, fumar un cigarrillo, o incluso lo mismo salir de casa s\u00f3lo a pasear. Tendremos que plantearnos ese san\u00edsimo gimnasio que nos sale a ***** [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[930,962,1490,1500],"class_list":["post-34","post","type-post","status-publish","format-standard","hentry","tag-gimnasio","tag-hartazgo","tag-problemas","tag-proscrit"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/posts\/34","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/comments?post=34"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/posts\/34\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/media?parent=34"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/categories?post=34"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/tags?post=34"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}