{"id":41,"date":"2010-02-24T16:36:00","date_gmt":"2010-02-24T16:36:00","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/cari\/?p=41"},"modified":"2010-02-24T16:36:00","modified_gmt":"2010-02-24T16:36:00","slug":"la-mano-izquierda","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/cari\/2010\/02\/24\/la-mano-izquierda\/","title":{"rendered":"LA MANO IZQUIERDA."},"content":{"rendered":"\n<p class=\"MsoNormal\"><span style=\"font-family: \"Arial\",\"sans-serif\"; color: black;\">\u201cno <em>sepa tu izquierda<\/em> lo que <em>hace tu derecha\u201d<\/em>&#8230;<strong><o:p><\/o:p><\/strong><\/span><\/p>\n<p class=\"MsoNormal\"><strong><span style=\"font-family: \"Arial\",\"sans-serif\"; color: black;\"><o:p> <\/o:p><\/span><\/strong><\/p>\n<p class=\"MsoNormal\"><strong><span style=\"font-family: \"Arial\",\"sans-serif\"; color: black;\">No, no lo digo yo, eso lo dijo supuestamente Jes\u00fas hace siglos como ya sab\u00e9is.<o:p><\/o:p><\/span><\/strong><\/p>\n<p class=\"MsoNormal\"><strong><span style=\"font-family: \"Arial\",\"sans-serif\"; color: black;\">Pero hoy no voy de esto, que por cierto amenazo con hablar un d\u00eda de ello, voy de la poca mano izquierda que tenemos con seres humanos que se sienten dolidos cuando no medimos nuestras palabras y da\u00f1amos al que en ese momento est\u00e1 muy pero que muy vulnerable.<o:p><\/o:p><\/span><\/strong><\/p>\n<p class=\"MsoNormal\"><strong><span style=\"font-family: \"Arial\",\"sans-serif\"; color: black;\">A veces es dif\u00edcil, tener que reciclar en el momento lo que vamos a decir para no hacer da\u00f1o es casi imposible, pero puede hacerse si pensamos un poquito en que esa persona necesita justo lo contrario, \u00e1nimo esa palabra m\u00e1gica en algunos momentos.<o:p><\/o:p><\/span><\/strong><\/p>\n<p class=\"MsoNormal\"><strong><span style=\"font-family: \"Arial\",\"sans-serif\"; color: black;\">O sea, alguien te cuenta que se encuentra fatal, que tiene tal o cual problema y vas t\u00fa tan oreada y le dices: \u00a1oye! que conozco a alguien que se muri\u00f3 por esto, es un ejemplo un poco expl\u00edcito, pero que ocurre, ya lo creo que ocurre, aunque no sea tan a lo bestia.<o:p><\/o:p><\/span><\/strong><\/p>\n<p class=\"MsoNormal\"><strong><span style=\"font-family: \"Arial\",\"sans-serif\"; color: black;\">Esto viene<span style=\"\">  <\/span>a cuento de una situaci\u00f3n algo an\u00f3mala que estoy pasando, y ayer alguien por tel\u00e9fono me dice, me cuenta, que ella conoce a alguien que lleva as\u00ed cinco a\u00f1os. POS QUE BIEN, cielo, amor m\u00edo, me has alegrado el d\u00eda.<o:p><\/o:p><\/span><\/strong><\/p>\n<p class=\"MsoNormal\"><strong><span style=\"font-family: \"Arial\",\"sans-serif\"; color: black;\">\u00bfQu\u00e9 me est\u00e1s contando? Pues eso, hundir en la miseria a una persona desanimada es lo m\u00e1s f\u00e1cil del mundo si no somos un poco zurd@s.<o:p><\/o:p><\/span><\/strong><\/p>\n<p class=\"MsoNormal\"><strong><span style=\"font-family: \"Arial\",\"sans-serif\"; color: black;\">Menos mal que aqu\u00ed una servidora tiene m\u00e1s valor que Diego y procur\u00e9 levantarme de mis cenizas, pero claro, aqu\u00ed estoy para cont\u00e1roslo cual cotilla bloguera.<o:p><\/o:p><\/span><\/strong><\/p>\n<p class=\"MsoNormal\"><strong><span style=\"font-family: \"Arial\",\"sans-serif\"; color: black;\">Saludos blogueros m\u00edos.<\/span><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cno sepa tu izquierda lo que hace tu derecha\u201d&#8230; No, no lo digo yo, eso lo dijo supuestamente Jes\u00fas hace siglos como ya sab\u00e9is. Pero hoy no voy de esto, que por cierto amenazo con hablar un d\u00eda de ello, voy de la poca mano izquierda que tenemos con seres humanos que se sienten dolidos [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[328,1544,1820,1893],"class_list":["post-41","post","type-post","status-publish","format-standard","hentry","tag-animo","tag-reciclar","tag-valor","tag-zurdos"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/posts\/41","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/comments?post=41"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/posts\/41\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/media?parent=41"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/categories?post=41"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/tags?post=41"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}