{"id":46,"date":"2010-03-17T16:31:00","date_gmt":"2010-03-17T16:31:00","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/cari\/?p=46"},"modified":"2010-03-17T16:31:00","modified_gmt":"2010-03-17T16:31:00","slug":"la-lucha-contra-elementos","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/cari\/2010\/03\/17\/la-lucha-contra-elementos\/","title":{"rendered":"LA LUCHA CONTRA LOS &#8220;ELEMENTOS&#8221;"},"content":{"rendered":"<p><P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><FONT face=Calibri size=3>Y no, blogueros m\u00edos, no hablo de esos elementos de la naturaleza tan alterada \u00faltimamente, contra esos no hay lucha que valga.<\/FONT><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><FONT face=Calibri size=3>Hablo de lo que a veces nos tiene comprometidos, de esas luchas que poca gente entiende o apoya, de esa lucha que a veces sirve de hazmerreir cuando hablas de lo que te preocupa, del asunto por el que luchamos, s\u00f3lo mayormente con nuestra palabra, hablada o escrita.<\/FONT><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><FONT face=Calibri size=3>Recuerdo un detalle por decir alguno, de un d\u00eda cercano a Setiembre que estaba tomando un vino con unos amigos, sali\u00f3 el tema del Toro de la Vega, alguien en <SPAN style=\"mso-spacerun: yes\"><\/SPAN>el bar dijo que era una maravilla ver aquello, la tradici\u00f3n y bla, bla, bla\u2026 esta persona me conoc\u00eda s\u00f3lo de vista, y le dije que yo no estaba de acuerdo, casi me come, claro que comerme es muy dif\u00edcil cuando tengo un convencimiento\u2026pod\u00eda haber acabado con indigesti\u00f3n, <SPAN style=\"mso-spacerun: yes\"><\/SPAN>esto ha sido s\u00f3lo un ejemplo, que por cierto este caballero ahora me saluda y hasta me dice algo agradable cuando me ve.<\/FONT><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><FONT face=Calibri size=3>A lo que voy, llevar adelante eso en lo que crees, es muy pero que muy dif\u00edcil, \u00bfpor qu\u00e9? porque el otro tambi\u00e9n tiene su raz\u00f3n y hay que respetarla aunque fastidie, lo de fastidie, lo he puesto en plan fino porque la palabra era otra, pero debo un respeto a los que me leen y a la correcci\u00f3n.<\/FONT><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><FONT face=Calibri size=3>A veces hay luchas que sabemos est\u00e1n casi perdidas, pero que no nos cansamos de denunciar a\u00fan a costa de resultar \u201ccansina\u201d como es mi caso cuando hablo de algunos temas, que encima no saco yo, pero que, digamos entro al trapo.<\/FONT><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><FONT face=Calibri size=3>A pesar de todas estas inconveniencias creo que merece la pena luchar con la palabra y delante de \u00e9ste frio ordenador pero c\u00f3mplice de nuestras inquietudes, por lo que creemos, por lo que nos parece injusto, por lo que nos duele, cercano, personal o lejano.<\/FONT><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><FONT face=Calibri size=3>\u00bfLo que m\u00e1s duele? La soledad que se ve o intuye hasta dentro de las personas que se supone tendr\u00edan que entenderte, decepci\u00f3n, pero no pasa nada\u2026 supongo la vida es una lucha, no quedarse parado en una vida c\u00f3moda, incomodarse a veces es una buena terapia que habla de solidaridad.<\/FONT><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><?xml:namespace prefix = o ns = \"urn:schemas-microsoft-com:office:office\" \/><o:p><FONT face=Calibri size=3><\/FONT><\/o:p><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><FONT face=Calibri size=3>Saludos bogueros.<\/FONT><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><o:p><FONT face=Calibri size=3><\/FONT><\/o:p><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 10pt\"><o:p><FONT face=Calibri size=3><\/FONT><\/o:p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Y no, blogueros m\u00edos, no hablo de esos elementos de la naturaleza tan alterada \u00faltimamente, contra esos no hay lucha que valga. Hablo de lo que a veces nos tiene comprometidos, de esas luchas que poca gente entiende o apoya, de esa lucha que a veces sirve de hazmerreir cuando hablas de lo que te [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[582,964,1147,1683,1739],"class_list":["post-46","post","type-post","status-publish","format-standard","hentry","tag-comprometidos","tag-hazmerreir","tag-luchas","tag-solidaridad","tag-terapia"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/posts\/46","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/comments?post=46"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/posts\/46\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/media?parent=46"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/categories?post=46"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/tags?post=46"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}