{"id":49,"date":"2010-03-27T16:48:00","date_gmt":"2010-03-27T16:48:00","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/cari\/?p=49"},"modified":"2010-03-27T16:48:00","modified_gmt":"2010-03-27T16:48:00","slug":"observando-blogs","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/cari\/2010\/03\/27\/observando-blogs\/","title":{"rendered":"OBSERVANDO LOS BLOGS"},"content":{"rendered":"\n<p class=\"MsoNormal\">Me gusta observar lo escrito en opini\u00f3n, en el foro, en los blogs, y a veces saco conclusiones para m\u00ed al menos interesantes.<\/p>\n<p class=\"MsoNormal\">Entro en el Norte cada ma\u00f1ana, luego en los blog, en el foro, en las noticias, las leo, las analizo, veo las respuestas, leo el peri\u00f3dico, no todo de una vez, durante el tiempo que tengo libre quiero decir, voy haci\u00e9ndolo y leo otras opiniones de otros medios de comunicaci\u00f3n.<\/p>\n<p class=\"MsoNormal\">Al final me doy cuenta de lo que se cuece, de lo que hablamos, de lo que opinamos, de lo que nos decepcionamos.<\/p>\n<p class=\"MsoNormal\">Hay blogs que a veces son intocables, hay blogs sencillos, estupendos, otros intelectuales a tope, otros con ese respaldo que da el escribir para el peri\u00f3dico, en fin\u2026<\/p>\n<p class=\"MsoNormal\">Y entonces te encuentras con que lo mismo en alguno mejor lo dejas, a veces esos blogs no son para opinar t\u00fa, s\u00f3lo son para que opinen ellos.<\/p>\n<p class=\"MsoNormal\">Yo tengo un blog gracias al NORTE, cosa que agradezco, <\/p>\n<p class=\"MsoNormal\">Supongo \u00e9ste peri\u00f3dico, lo podr\u00eda cortar en cuantito yo dijera algo que no fuera correcto, as\u00ed que siendo sincera procuro andar con pies de plomo, a\u00fan as\u00ed alguna opini\u00f3n me la han borrado.<\/p>\n<p class=\"MsoNormal\">No pasa nada, pero a veces lo ves injusto, porque cualquier peri\u00f3dico sobrevive a base de sus lectores, y esos lectores tratamos de opinar desde nuestro razonamiento, mejor o peor, pero el nuestro, sin atacar ni insultar a nadie.<\/p>\n<p class=\"MsoNormal\">Tengo claro al d\u00eda de hoy que hay categor\u00edas en los blogs, y que en algunas de ellas, ya jam\u00e1s entrar\u00e9 cosa que pasar\u00e1 desapercibida, a no ser que yo fuera \u201cfulanita de tal\u201d y no lo soy.<\/p>\n<p class=\"MsoNormal\">No me importa no ser esa fulanita de tal que SI importa, s\u00f3lo soy una lectora muy de andar por casa, participativa pero entiendo que a veces \u201cmosca cojonera\u201d donde las haya.<\/p>\n<p class=\"MsoNormal\">\u00c9sta charla de hoy va de un peque\u00f1o cabreo que he tenido el otro d\u00eda, no hace falta contarlo ni decir detalles, pero al menos creo que llegar\u00e1 a alguien.<\/p>\n<p class=\"MsoNormal\">Y ahora que lo pienso en cuanto de la palabra m\u00e1gica PUBLICAR&#8221; lo mismo es lo \u00faltimo que escribo.  :-)<\/p>\n<p class=\"MsoNormal\"><o:p> <\/o:p><\/p>\n<p class=\"MsoNormal\">Saludos bloguer@s.<\/p>\n<p class=\"MsoNormal\"><o:p> <\/o:p><\/p>\n<p class=\"MsoNormal\"><o:p> <\/o:p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Me gusta observar lo escrito en opini\u00f3n, en el foro, en los blogs, y a veces saco conclusiones para m\u00ed al menos interesantes. Entro en el Norte cada ma\u00f1ana, luego en los blog, en el foro, en las noticias, las leo, las analizo, veo las respuestas, leo el peri\u00f3dico, no todo de una vez, durante [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[507,669,1056,1111,1507],"class_list":["post-49","post","type-post","status-publish","format-standard","hentry","tag-categorias","tag-decepcion","tag-intocables","tag-lectores","tag-publicar"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/posts\/49","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/comments?post=49"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/posts\/49\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/media?parent=49"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/categories?post=49"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/tags?post=49"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}