{"id":56,"date":"2010-05-01T16:23:00","date_gmt":"2010-05-01T16:23:00","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/cari\/?p=56"},"modified":"2010-05-01T16:23:00","modified_gmt":"2010-05-01T16:23:00","slug":"llegue-la-lluvia","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/cari\/2010\/05\/01\/llegue-la-lluvia\/","title":{"rendered":"LLEGU\u00c9 DE LA LLUVIA."},"content":{"rendered":"\n<p class=\"MsoNormal\">Hace tiempo escrib\u00ed un relato de mis muchos <span style=\"\"> <\/span>a\u00f1os vividos en el Norte, titulado as\u00ed, \u201cllegu\u00e9 de la lluvia\u201d.<\/p>\n<p class=\"MsoNormal\">Mi norte adorado y adoptivo, mi Castilla de nacimiento.<\/p>\n<p class=\"MsoNormal\">Hoy debo estar nost\u00e1lgica, me he acordado de \u00e9ste relato que tengo guardado en un caj\u00f3n.<\/p>\n<p class=\"MsoNormal\">En ese escrito hablo de esos d\u00edas grises, de esos malos tiempos, de las mordazas pol\u00edticas y humanas, <span style=\"\"> <\/span>de la hija del alma que all\u00ed naci\u00f3.<\/p>\n<p class=\"MsoNormal\"><span style=\"\"> <\/span>Aunque fui nacida en un pueblecito de Castilla, fui ni\u00f1a, adolescente y mujer en un lugar del Pa\u00eds Vasco, ahora por avatares de la vida estoy en mis raices de nuevo y amo tambi\u00e9n \u00e9sta Castilla plana y \u00e1rida pero hermosa.<\/p>\n<p class=\"MsoNormal\">Y es que hace unos a\u00f1os sal\u00ed de la lluvia, de aquel color verde que me enamoraba, de esos d\u00edas grises a los que ya estaba acostumbrada.<\/p>\n<p class=\"MsoNormal\">Y en \u00e9ste escrito de hoy hay retazos del relato de esa historia, pocos, pero los hay.<\/p>\n<p class=\"MsoNormal\">Recuerdo esas monta\u00f1as siempre verdes, la bruma, la lluvia, los astilleros donde ve\u00eda levantarse lo esqueletos de esos barcos que se har\u00edan a la mar con su carga marinera.<\/p>\n<p class=\"MsoNormal\">Las playas bravas, como bravo es el Cant\u00e1brico, donde yo tem\u00eda entrar, estaban fr\u00edas, muy fr\u00edas sus aguas, pero el sol t\u00edmido casi siempre y su inmensidad hac\u00eda de ellas algo realmente hermoso.<\/p>\n<p class=\"MsoNormal\">Pero de vez en cuando vuelvo y recuerdo, a\u00fan hay personas que me hacen regresar, hasta que se me acaben las personas, se me acaben los recuerdos o la a\u00f1oranza que a veces niego.<\/p>\n<p class=\"MsoNormal\">Contemplo ahora en paz el paisaje plano, inmenso y bello de Castilla, y cuando su sol da\u00f1a mis ojos creo que sus rayos quieren recordarme que llegu\u00e9 de la lluvia.<\/p>\n<p class=\"MsoNormal\">Saludos blogueros.<\/p>\n<p class=\"MsoNormal\"><o:p> <\/o:p><\/p>\n<p class=\"MsoNormal\"><o:p> <\/o:p><\/p>\n<p class=\"MsoNormal\"><o:p> <\/o:p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hace tiempo escrib\u00ed un relato de mis muchos a\u00f1os vividos en el Norte, titulado as\u00ed, \u201cllegu\u00e9 de la lluvia\u201d. Mi norte adorado y adoptivo, mi Castilla de nacimiento. Hoy debo estar nost\u00e1lgica, me he acordado de \u00e9ste relato que tengo guardado en un caj\u00f3n. En ese escrito hablo de esos d\u00edas grises, de esos malos [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[505,1137,1251,1560,1572,1679],"class_list":["post-56","post","type-post","status-publish","format-standard","hentry","tag-castilla","tag-lluvia","tag-montanas","tag-relato","tag-retazos","tag-sol"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/posts\/56","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/comments?post=56"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/posts\/56\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/media?parent=56"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/categories?post=56"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/tags?post=56"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}