{"id":74,"date":"2010-09-07T18:08:00","date_gmt":"2010-09-07T18:08:00","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/cari\/?p=74"},"modified":"2010-09-07T18:08:00","modified_gmt":"2010-09-07T18:08:00","slug":"el-canivalismo-virtual","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/cari\/2010\/09\/07\/el-canivalismo-virtual\/","title":{"rendered":"EL CANIBALISMO VIRTUAL"},"content":{"rendered":"<p><meta http-equiv=\"Content-Type\" content=\"text\/html; charset=utf-8\"><meta name=\"ProgId\" content=\"Word.Document\"><meta name=\"Generator\" content=\"Microsoft Word 12\"><meta name=\"Originator\" content=\"Microsoft Word 12\"><link rel=\"File-List\" href=\"file:\/\/\/C:%5CUsers%5CCari%5CAppData%5CLocal%5CTemp%5Cmsohtmlclip1%5C01%5Cclip_filelist.xml\"><link rel=\"themeData\" href=\"file:\/\/\/C:%5CUsers%5CCari%5CAppData%5CLocal%5CTemp%5Cmsohtmlclip1%5C01%5Cclip_themedata.thmx\"><link rel=\"colorSchemeMapping\" href=\"file:\/\/\/C:%5CUsers%5CCari%5CAppData%5CLocal%5CTemp%5Cmsohtmlclip1%5C01%5Cclip_colorschememapping.xml\">\n<p class=\"MsoNormal\">Somos capaces de comernos vivos, ya lo creo que s\u00ed.<\/p>\n<p class=\"MsoNormal\">Virtualmente o quiz\u00e1 si llegara el caso en vivo y en directo, por lo que leo, por lo que oigo.<\/p>\n<p class=\"MsoNormal\">En temas digamos, comprometidos, donde nos lanzamos a opinar a favor o en contra exigimos respeto para nosotros y el contrario hace lo mismo.<\/p>\n<p class=\"MsoNormal\">Pero ese respeto en l\u00edneas generales no existe, todos queremos llevar la opini\u00f3n a nuestro terreno, todos queremos que nuestra raz\u00f3n se lea o escuche m\u00e1s que la del otro.<\/p>\n<p class=\"MsoNormal\">Por eso he titulado as\u00ed mi charla de hoy seguro suena fuerte, seguro suena torpe o quiz\u00e1 exagerada, pero es lo que pienso y as\u00ed lo expreso.<\/p>\n<p class=\"MsoNormal\">Siempre pens\u00e9 y pienso que la verdad absoluta no existe venga de quien venga.<\/p>\n<p class=\"MsoNormal\">Siempre pens\u00e9 que esa frase filos\u00f3fica de que mi libertad se termina donde empiezan los derechos de los dem\u00e1s, esa frase digo, iba a misa, ahora ya no lo s\u00e9, porque cuando los derechos de los dem\u00e1s a decir su verdad aplasta \u201cmi verdad\u201d ya casi pienso que lo mismo quien la dijo por primera vez no conoc\u00eda con quien se jugaba los cuartos.<\/p>\n<p class=\"MsoNormal\">Y cuando hay un debate en la calle, sobre el tema que sea, que levanta pasiones y emotividad dejamos en muchos comentarios lo peor de nosotros mismos.<\/p>\n<p class=\"MsoNormal\">\nTal parece que todos estamos en posesi\u00f3n de una verdad que no es de nadie, y nos quedamos m\u00e1s anchos que altos<span style=\"\">  <\/span>con eso de \u201cy t\u00fa m\u00e1s\u201d, y no razonamos, no vemos m\u00e1s all\u00e1 o no queremos ver, no vaya a ser que se nos abran los ojos demasiado.<\/p>\n<p class=\"MsoNormal\">Esas luchas dial\u00e9cticas al final ni siquiera quedan en tablas, quedan en la sensaci\u00f3n de que a\u00fan no hemos dicho todo, de que a\u00fan falta la \u00faltima palabra que queremos sea nuestra aunque se las lleve el aire del peri\u00f3dico de hoy y ma\u00f1ana no existan como escritas, porque habr\u00e1n dado paso a otras con m\u00e1s de lo mismo.<\/p>\n<p class=\"MsoNormal\">Hoy que se ha nombrado a Valladolid \u201cCiudad Taurina\u201d y me he propuesto no pelearme con nadie ni decir esa \u00faltima palabra que a nadie importar\u00e1 y que nadie leer\u00e1, porque al final s\u00f3lo conseguir\u00e9 un cabreo may\u00fasculo y la tristeza de saber que esta ciudad que actualmente me acoge, me ha fallado y decepcionado, ya lo creo que s\u00ed, pero supongo es lo que tocaba, malos tiempos para pensar y reflexionar, demostrado est\u00e1.<\/p>\n<p class=\"MsoNormal\">Saludos blogueros.<\/p>\n<p class=\"MsoNormal\"><o:p> <\/o:p><\/p>\n<p class=\"MsoNormal\">\n<p class=\"MsoNormal\"><o:p> <\/o:p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Somos capaces de comernos vivos, ya lo creo que s\u00ed. Virtualmente o quiz\u00e1 si llegara el caso en vivo y en directo, por lo que leo, por lo que oigo. En temas digamos, comprometidos, donde nos lanzamos a opinar a favor o en contra exigimos respeto para nosotros y el contrario hace lo mismo. Pero [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[665,765,1118,1386,1836],"class_list":["post-74","post","type-post","status-publish","format-standard","hentry","tag-debate","tag-emotividad","tag-libertad","tag-pasiones","tag-verdad"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/posts\/74","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/comments?post=74"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/posts\/74\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/media?parent=74"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/categories?post=74"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/tags?post=74"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}