{"id":78,"date":"2010-09-26T15:53:00","date_gmt":"2010-09-26T15:53:00","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/cari\/?p=78"},"modified":"2010-09-26T15:53:00","modified_gmt":"2010-09-26T15:53:00","slug":"ese-plato-se-sirve-frio","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/cari\/2010\/09\/26\/ese-plato-se-sirve-frio\/","title":{"rendered":"ESE PLATO QUE SE SIRVE FRIO"},"content":{"rendered":"\n<p class=\"MsoNormal\">Si, hablo de la VENGANZA,<span style=\"\">  <\/span>y hablo de esto porque hoy en la sobremesa de mi casa hemos hablado de ello, arrancando de la noticia de la mujer ejecutada en Virginia por inyecci\u00f3n letal.<\/p>\n<p class=\"MsoNormal\">El alcaide de la prisi\u00f3n dijo que hab\u00eda sido una muerte \u201csin complicaciones\u201d claro es de ley, la muerte llega en este caso atada a una camilla sin ninguna posibilidad.<\/p>\n<p class=\"MsoNormal\">De vez en cuando es noticia, han ejecutado a\u2026s\u00f3lo es eso una noticia escueta en la TV.<\/p>\n<p class=\"MsoNormal\">Me pod\u00e9is decir, que tampoco tuvieron posibilidad lo que murieron porque ella se encarg\u00f3 de que no la tuvieran, hay dudas en este caso, pero bueno en eso no entrar\u00e9, son cosas que adem\u00e1s ahora ya no importan mucho.<\/p>\n<p class=\"MsoNormal\">Dicho esto, siempre pens\u00e9 que la venganza es una gran p\u00e9rdida de tiempo, s\u00f3lo hace que vivas para que llegue ese momento, que cuando llega no te devuelve al ser querido que esa persona destruy\u00f3, viol\u00f3, asesino\u2026nunca vuelve.<\/p>\n<p class=\"MsoNormal\">He visto y le\u00eddo \u201cEl Conde de Montecristo\u201d varias veces, la venganza de las venganzas.<\/p>\n<p class=\"MsoNormal\">Pero siempre me dej\u00f3 una sensaci\u00f3n agridulce.<\/p>\n<p class=\"MsoNormal\">Siempre desde que lo recuerdo, supongo<span style=\"\">  <\/span>que desde que tengo uso de raz\u00f3n, estuve en contra de la PENA DE MUERTE y sigo est\u00e1ndolo.<\/p>\n<p class=\"MsoNormal\">Estoy en contra de muchas cosas como una gran parte de la humanidad pero no puedo\/podemos evitarlo, somos un grano de arena en una inmensa playa mundial.<\/p>\n<p class=\"MsoNormal\">A veces en nuestra vida cotidiana, normal, de andar por casa, se presentan ocasiones de aplicar esa venganza que tal parece es la motivaci\u00f3n que gu\u00eda cada paso que damos.<\/p>\n<p class=\"MsoNormal\">Si extrapolamos<span style=\"\">  <\/span>cada situaci\u00f3n, cada, \u201cya me lo pagar\u00e1s\u201d a lo que significa que la vida de una persona pague la muerte de otra\u2026o sin llegar a la muerte, a esperar ah\u00ed agazapados a que llegue la ocasi\u00f3n para devolver el golpe , aunque estemos cargados de razones,<span style=\"\">  <\/span>la felicidad se ir\u00e1 a morar a otro lugar donde no exista ese deseo quiz\u00e1 justo, pero doloroso<span style=\"\">  <\/span>e in\u00fatil. <\/p>\n<p class=\"MsoNormal\">Tengo una frase en mi otro yo, \u201cojo por ojo y el mundo se quedar\u00e1 ciego\u201d de <em><span style=\"font-family: \"Calibri\",\"sans-serif\";\">Gandhi<\/span><\/em> creo que as\u00ed ser\u00eda y de alguna manera as\u00ed es, nos queda mucha amargura, odio, y revancha por descargar de nuestras vidas, ojal\u00e1 fuera tan f\u00e1cil como descargarse algo en Internet.<\/p>\n<p class=\"MsoNormal\">Lo dicho una gran p\u00e9rdida de tiempo, una gran amargura, algo que seguro no nos hace m\u00e1s felices para nada.<\/p>\n<p class=\"MsoNormal\">Est\u00e1n han sido mis divagaciones de hoy, <span style=\"\"> <\/span>que he querido como siempre compartir con vosotros.<\/p>\n<p class=\"MsoNormal\">Saludos blogueros y gracias, si est\u00e1is en este punto y <span style=\"\"><\/span>le\u00eddo mis saludos es que os hab\u00e9is  pasado por aqu\u00ed.<\/p>\n<p class=\"MsoNormal\">\n<p class=\"MsoNormal\">\n<p class=\"MsoNormal\">\n","protected":false},"excerpt":{"rendered":"<p>Si, hablo de la VENGANZA, y hablo de esto porque hoy en la sobremesa de mi casa hemos hablado de ello, arrancando de la noticia de la mujer ejecutada en Virginia por inyecci\u00f3n letal. El alcaide de la prisi\u00f3n dijo que hab\u00eda sido una muerte \u201csin complicaciones\u201d claro es de ley, la muerte llega en [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[272,735,907,1831],"class_list":["post-78","post","type-post","status-publish","format-standard","hentry","tag-agazapados","tag-divagaciones","tag-gandhi","tag-venganza"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/posts\/78","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/comments?post=78"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/posts\/78\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/media?parent=78"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/categories?post=78"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/cari\/wp-json\/wp\/v2\/tags?post=78"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}