{"id":1038,"date":"2015-06-05T19:56:32","date_gmt":"2015-06-05T17:56:32","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/enfaserem\/?p=1038"},"modified":"2015-06-05T19:56:32","modified_gmt":"2015-06-05T17:56:32","slug":"el-himno","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/2015\/06\/05\/el-himno\/","title":{"rendered":"El himno"},"content":{"rendered":"<p>Como piezas de arte los himnos suelen ser lamentables: la m\u00fasica militarmente melodram\u00e1tica y los versos, cuando los hay, planos y facilones. Como s\u00edmbolo son otra cosa: han llevado en ocasiones al acero y a la sangre. Quien diga pues que darle vueltas a lo del s\u00e1bado en el Camp Nou es una memez, o es un ignorante total o \u2014m\u00e1s probable\u2014 est\u00e1 del lado de los silbidos. As\u00ed <strong>Artur Mas<\/strong>, cuya ladina, cariada y satisfecha sonrisilla al lado del Rey es la perfecta s\u00edntesis de la victoria miserable. <<A m\u00ed tambi\u00e9n me han silbado>>, hab\u00eda dicho antes del partido, a modo de clic incendiario. Se le olvid\u00f3 a\u00f1adir que a \u00e9l con raz\u00f3n. El Rey no tiene culpa de haber nacido rey. El Rey, en su funci\u00f3n de rey, lo ha hecho mucho mejor que Mas en la suya. Estos silbantes confunden la mala educaci\u00f3n con el ideario pol\u00edtico, y la distancia que hay entre la sonrisilla de Mas y el silencio de <strong>Felipe VI <\/strong>es la que media entre <strong>Pilatos<\/strong> y <strong>Marco Aurelio<\/strong>.<\/p>\n<p>Pero lo de Mas a nadie ha de sorprender. A uno a quien le gustar\u00eda o\u00edr es a los jugadores, mayormente a los del Bar\u00e7a que vistieron la camiseta de la selecci\u00f3n en el Mundial de Sud\u00e1frica y se metieron en la buchaca 600.000 euros en primas \u2014cada uno\u2014. Su silencio no es el silencio estoico del Rey, sino un silencio\u2026 bueno, uno cuya calidad justamente deber\u00edan aclarar hablando. La posici\u00f3n de los cracks es muy c\u00f3moda; a ellos les pagan por jugar, el resto no les compete. Solo que juegan en una liga cuyo reglamento dice, y es algo que quiz\u00e1 por ser lo m\u00e1s b\u00e1sico se ha omitido\/marginado en el alud de reacciones pro\/contra, que el club que intervenga en el Campeonato Nacional \u2014de primera y segunda divisi\u00f3n\u2014 est\u00e1 obligado a jugar la Copa de S.M. el Rey. As\u00ed que lo tienen muy f\u00e1cil: abandonen el paraguas que la marca LFP les proporciona y formen una competici\u00f3n paralela con sus televisiones, sus patrocinadores y, si les place, tambi\u00e9n sus himnos propios. No s\u00e9 a qu\u00e9 esperan.<\/p>\n<p style=\"text-align: right;\">(<em>El Norte de Castilla<\/em>, 5\/6\/2015)<\/p>\n<p style=\"text-align: left;\"><a title=\"@enfaserem\" href=\"https:\/\/twitter.com\/enfaserem\" target=\"_blank\" rel=\"external nofollow\">@enfaserem<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como piezas de arte los himnos suelen ser lamentables: la m\u00fasica militarmente melodram\u00e1tica y los versos, cuando los hay, planos y facilones. Como s\u00edmbolo son otra cosa: han llevado en ocasiones al acero y a la sangre. Quien diga pues que darle vueltas a lo del s\u00e1bado en el Camp Nou es una memez, o [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,7],"tags":[234,366,411,529,832],"class_list":["post-1038","post","type-post","status-publish","format-standard","hentry","category-ha-ocurrido-esta-ocurriendo-ocurrira","category-columnas","tag-democracia","tag-futbol","tag-himno","tag-libertad","tag-silbidos"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/1038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/comments?post=1038"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/1038\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/media?parent=1038"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/categories?post=1038"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/tags?post=1038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}