{"id":1050,"date":"2015-06-27T12:52:44","date_gmt":"2015-06-27T10:52:44","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/enfaserem\/?p=1050"},"modified":"2015-06-27T12:52:44","modified_gmt":"2015-06-27T10:52:44","slug":"apunte-cine-el-principe-y-la-corista","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/2015\/06\/27\/apunte-cine-el-principe-y-la-corista\/","title":{"rendered":"Apunte cine &#8211; El pr\u00edncipe y la corista"},"content":{"rendered":"<p><a href=\"\/enfaserem\/wp-content\/uploads\/sites\/14\/2015\/06\/el-pri\u0301ncipe-y-la-corista-e1435402235341.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-1051\" title=\"el pri\u0301ncipe y la corista\" src=\"\/enfaserem\/wp-content\/uploads\/sites\/14\/2015\/06\/el-pri\u0301ncipe-y-la-corista-e1435402235341.jpg\" alt=\"\" width=\"240\" height=\"135\" \/><\/a>En <em>El pr\u00edncipe y la corista<\/em> se nota la presencia ven\u00e9rica de un escritor, lo cual siempre es de agradecer; no tanto la visible de un director. Resulta teatral en el sentido menos cinematogr\u00e1fico del t\u00e9rmino \u2014cuando <strong>Olivier<\/strong> se empe\u00f1a en borrar los rasgos teatrales es justamente cuando estos m\u00e1s brillan y denuncian su origen\u2014, y tiene un problema esencial: que la qu\u00edmica de opuestos solo funciona a r\u00e1fagas; todo el proyecto \u2014lo que se ve en pantalla y lo que queda fuera de esta\u2014 se articula en torno a la idea de un dualismo de signo contrario, que se desglosa en distintos dualismos menores: actor shakespeareano\/actriz de m\u00e9todo; personalidad severa\/personalidad mundana; pr\u00edncipe\/corista; reflexi\u00f3n\/intuici\u00f3n; prestigio acad\u00e9mico\/favor popular; seguridad patol\u00f3gica en el arte propio\/inseguridad patol\u00f3gica en el arte propio, etc. El que la idea que el p\u00fablico tiene de algunos de estos conceptos no se ajuste a su contenido real \u2014fuera de la pantalla\u2014 o al contenido que en esta se muestra, no solo no impide sino que parece avivar el juego. En pantalla, la corista encarna el polo positivo y el pr\u00edncipe el negativo, y como polos contrarios que son surge la atracci\u00f3n desde el principio, si bien es una atracci\u00f3n en la que cada polo baila con frecuencia por su lado: los dos siguen el mismo comp\u00e1s, los dos atienden a la misma melod\u00eda, pero la pareja en conjunto no aporta nada extra a lo que cada uno por separado. <strong>Marilyn<\/strong> es capaz de no incurrir en el clich\u00e9 asignado, y proporciona una de las interpretaciones m\u00e1s matizadas de su carrera, no solo aguantando sino superando en muchos intercambios al casi siempre sobrevalorado actor ingl\u00e9s. Muy sabiamente, <strong>Rattigan<\/strong> deja en suspenso el final \u2014<<No sabes la de cosas que pueden pasar en dieciocho meses>>\u2014, que adquiere as\u00ed una doble cualidad, de nuevo contraria, de resignaci\u00f3n\/esperanza, y que retrospectivamente confiere a la obra una capa de melancol\u00eda que enriquece el aspecto c\u00f3mico, predominante y m\u00e1s inmediatamente perceptible, mostrado hasta entonces.<\/p>\n<p><a title=\"@enfaserem\" href=\"https:\/\/twitter.com\/enfaserem\" target=\"_blank\" rel=\"external nofollow\">@enfaserem<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En El pr\u00edncipe y la corista se nota la presencia ven\u00e9rica de un escritor, lo cual siempre es de agradecer; no tanto la visible de un director. Resulta teatral en el sentido menos cinematogr\u00e1fico del t\u00e9rmino \u2014cuando Olivier se empe\u00f1a en borrar los rasgos teatrales es justamente cuando estos m\u00e1s brillan y denuncian su origen\u2014, [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,10],"tags":[68,176,282,515,564,866,875],"class_list":["post-1050","post","type-post","status-publish","format-standard","hentry","category-apuntes","category-desde-la-pantalla","tag-apuntecine","tag-cine","tag-el-principe-y-la-corista","tag-laurence-olivier","tag-marilyn","tag-teatro","tag-terence-rattigan"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/1050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/comments?post=1050"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/1050\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/media?parent=1050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/categories?post=1050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/tags?post=1050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}