{"id":1084,"date":"2015-11-11T15:55:43","date_gmt":"2015-11-11T14:55:43","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/enfaserem\/?p=1084"},"modified":"2015-11-11T15:55:43","modified_gmt":"2015-11-11T14:55:43","slug":"conexion-gospel","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/2015\/11\/11\/conexion-gospel\/","title":{"rendered":"Conexi\u00f3n g\u00f3spel"},"content":{"rendered":"<p><a href=\"\/enfaserem\/wp-content\/uploads\/sites\/14\/2015\/11\/good-news-e1447253663520.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-1085\" title=\"good news\" src=\"\/enfaserem\/wp-content\/uploads\/sites\/14\/2015\/11\/good-news-e1447253663520.jpg\" alt=\"\" width=\"240\" height=\"173\" \/><\/a>La formaci\u00f3n simanque\u00f1a <strong>Good News<\/strong> (treinta y una mujeres entre sopranos, mezzos y contraltos, y veintitr\u00e9s hombres entre tenores y bajos, dirigidos por <strong>Mario del Campo<\/strong>), con m\u00e1s de una d\u00e9cada de traves\u00eda nacional e internacional, ser\u00e1 la encargada de hacer arrancar la segunda edici\u00f3n del Festival de Jazz de Palencia con una propuesta que, si bien se espera caliente a los aficionados hasta la llegada del fin de semana, se halla lejana del estilo que da nombre al festival. En jazz es el aliento del solista, su idiosincrasia e incluso sus caprichos, el que determina el rumbo de la interpretaci\u00f3n, pues el resto de los miembros han de estar alerta y responder sin pausa \u2014tambi\u00e9n seg\u00fan su propia idiosincrasia\u2014; incluso en las improvisaciones colectivas \u2014digamos del <em>Ascension<\/em> de <strong>Coltrane<\/strong>, o las de la orquesta de <strong>Sun Ra <\/strong>o del <strong>Art Ensemble of Chicago<\/strong>\u2014 se deja un espacio pivotal, irrenunciable, para la expresi\u00f3n individual; en g\u00f3spel el aliento es esencialmente comunal, el p\u00e1lpito plural, y cada voz es antes parte de una voz superior, que es la que al final importa: en ambos estilos el precipitado es \u2014o idealmente deber\u00eda ser\u2014 mayor que la suma de las partes, pero en jazz ese precipitado es casi involuntario, mientras que en el g\u00f3spel resulta inherente. Y no solo inherente sino previsible, y es esta, m\u00e1s all\u00e1 de la elecci\u00f3n de los temas, la vestimenta, el n\u00famero de m\u00fasicos o el sustrato religioso, la diferencia fundamental entre ambos estilos. El jazz se basa en la sorpresa del momento, el g\u00f3spel en las estructuras aprendidas; los pasos, las palmas, los arreglos: cada cantante sabe en qu\u00e9 comp\u00e1s entra el vecino, no hay se\u00f1as como disparos en la sien que indiquen se pasa la bola del solo.<\/p>\n<p>El riesgo que asume el g\u00f3spel es otro, el de establecer una corriente bidireccional entre los cantantes y el respetable, ofrecer un abrazo sonoro que sea correspondido (cu\u00e1ntas veces hemos asistido a conciertos de jazz en que los m\u00fasicos, ensimismados en su \u00f3rbita privada, parecen no estar interesados en comunicaci\u00f3n musical alguna); se trata de una conexi\u00f3n delicada, un misterio que se produce o no se produce y que es mejor no tratar de comprender, algo que en \u00faltima instancia no depende siquiera de la entrega del coro (esta es imprescindible pero no asegura la conexi\u00f3n).<\/p>\n<p>Pese a esta incertidumbre y misterio, Good News, con un repertorio vario que va desde los espirituales tradicionales hasta los villancios e incluso el soul \u2014suerte de g\u00f3spel laico\u2014, unas armon\u00edas vocales muy cuidadas y una direcci\u00f3n \u00e1gil, es hoy una de las apuestas m\u00e1s seguras en el panorama nacional para que la conexi\u00f3n, y as\u00ed el disfrute, se establezca.<\/p>\n<p style=\"text-align: right;\">(<em>El Norte de Castilla,<\/em> 10\/11\/2015)<\/p>\n<p style=\"text-align: left;\"><a title=\"@enfaserem\" href=\"https:\/\/twitter.com\/enfaserem\" target=\"_blank\" rel=\"external nofollow\">@enfaserem<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La formaci\u00f3n simanque\u00f1a Good News (treinta y una mujeres entre sopranos, mezzos y contraltos, y veintitr\u00e9s hombres entre tenores y bajos, dirigidos por Mario del Campo), con m\u00e1s de una d\u00e9cada de traves\u00eda nacional e internacional, ser\u00e1 la encargada de hacer arrancar la segunda edici\u00f3n del Festival de Jazz de Palencia con una propuesta que, [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,6],"tags":[338,387,388,465,610],"class_list":["post-1084","post","type-post","status-publish","format-standard","hentry","category-ha-ocurrido-esta-ocurriendo-ocurrira","category-claves-sonoras","tag-festival-jazz-palencia","tag-good-news","tag-gospel","tag-jazz","tag-musica"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/1084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/comments?post=1084"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/1084\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/media?parent=1084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/categories?post=1084"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/tags?post=1084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}