{"id":109,"date":"2008-09-24T21:55:00","date_gmt":"2008-09-24T19:55:00","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/enfaserem\/?p=109"},"modified":"2008-09-24T21:55:00","modified_gmt":"2008-09-24T19:55:00","slug":"dimitir-de-la-vida","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/2008\/09\/24\/dimitir-de-la-vida\/","title":{"rendered":"Dimitir de la vida"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"\/\/3.bp.blogspot.com\/_VpyEEFR-Hsc\/TD8Boh8b7oI\/AAAAAAAAARQ\/B0Uhr22WsCI\/s200\/4339.jpg\" alt=\"\" width=\"200\" height=\"133\" \/>En una sociedad cuyo tratamiento de la muerte resulta esquizoide adem\u00e1s de hip\u00f3crita (no se puede hablar de ella pero s\u00ed lucrarse a su costa, estiliz\u00e1ndola en videojuegos manga y cine de k\u00e9tchup), el suicidio se ha convertido no en el problema filos\u00f3fico por excelencia, como quer\u00eda <strong>Camus<\/strong>, sino en el tab\u00fa m\u00e1s herm\u00e9tico. As\u00ed, tras el suicidio por soga al cuello del escritor <strong>David Foster Wallace<\/strong> han asomado las peri\u00f3dicas, habituales muestras de impotencia que brotan cuando un fen\u00f3meno se niega a encasillarse en esos par\u00e1metros asumidos que consideramos inamovibles. C\u00f3mo alguien a quien han sonre\u00eddo el \u00e9xito en su profesi\u00f3n y la espuma de la fama, alguien con una mujer a su lado que le quer\u00eda, alguien con s\u00f3lo 46 a\u00f1os ha podido&#8230; Porque lo \u00fanico innegable es que ha podido. Quienes escupen estas preguntas sin destinatario (el \u00fanico que hubiera podido responderlas es el muerto) parece a veces que se toman una decisi\u00f3n sobre la propia vida de alguien a quien no han conocido como una afrenta personal y deliberada por causarles dolor. Y el fatigar sus escritos en busca de \u201cpistas reveladoras\u201d, conscientes o no, de su futura decisi\u00f3n constituye un ejercicio tan est\u00e9ril como insincero, es s\u00f3lo el disfraz con el que se pretende entretener la impotencia ante un hecho que desborda la comprensi\u00f3n, en el sentido de facultad para entender y casi siempre tambi\u00e9n en el de tolerancia. Dicen buscar una raz\u00f3n, pero s\u00f3lo hacen como que la buscan: la tienen delante y no quieren verla. Ni <strong>Virginia Woolf<\/strong> ni <strong>Primo Levi<\/strong> ni Foster Wallace comparten otra cosa que la de haber dicho basta. La depresi\u00f3n, la angustia, la fatiga, esos caudales irregulares y caprichosos, sencillamente a veces llegan con un volumen que no se puede achicar acudiendo a los habituales cubos de socorro: el amor, el trabajo, el futuro &#8211; el Futuro -, los piolines culturales; y entonces es mejor dejarlo, acudir a la armer\u00eda o a la farmacia m\u00e1s cercanas y fin.<\/p>\n<p>Esta ceguera voluntaria nada tiene que ver con la humana incomprensi\u00f3n que nace de nuestra incapacidad para meternos en la piel \u2013 en la cabeza \u2013 del suicida. El suicidio nos sit\u00faa pues de la manera m\u00e1s radical ante lo que con respecto a la eutanasia <strong>Salvador P\u00e1niker<\/strong> ha llamado \u201cderecho a dimitir de la vida\u201d. \u00bfPor qu\u00e9 no va a tener derecho a dimitir alguien cuyos \u2013 acudiendo a la expresi\u00f3n de que se vale nuestro c\u00f3digo penal &#8211; \u201cgraves padecimientos permanentes\u201d se nos han pasado por alto? \u00bfO ha de ser la evidencia terminal perceptible por cualquiera para que admitamos el ejercicio de atributos como libre albedr\u00edo, autonom\u00eda, etc., supuestamente indisociables de la persona? Por supuesto que tal decisi\u00f3n siempre va a resultar en mayor o menor grado incomprensible para quienes quedamos de este lado, y admitirla se vuelve m\u00e1s y m\u00e1s dif\u00edcil cuanto m\u00e1s estimemos-queramos-amemos al suicida. Pero no debe olvidarse el Perogrullo \u2013 y con frecuencia se olvida &#8211; de que, por mucho sufrimiento que pueda causar en quienes por ahora hemos decidido seguir en la rueda de las horas y los d\u00edas, quien m\u00e1s sufre en un suicidio es el suicida, por la sencilla raz\u00f3n de que es irreversible, y que su sufrimiento hasta llegar al suicidio ha sido tal que le ha hecho optar por un naipe sin vuelta atr\u00e1s.<\/p>\n<p style=\"text-align: right;\">(<em>El Norte de Castilla<\/em>, septiembre de 2008)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En una sociedad cuyo tratamiento de la muerte resulta esquizoide adem\u00e1s de hip\u00f3crita (no se puede hablar de ella pero s\u00ed lucrarse a su costa, estiliz\u00e1ndola en videojuegos manga y cine de k\u00e9tchup), el suicidio se ha convertido no en el problema filos\u00f3fico por excelencia, como quer\u00eda Camus, sino en el tab\u00fa m\u00e1s herm\u00e9tico. As\u00ed, [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,9],"tags":[348,529,604,853],"class_list":["post-109","post","type-post","status-publish","format-standard","hentry","category-columnas","category-antes-de-la-arrancada","tag-foster-wallace","tag-libertad","tag-muerte","tag-suicidio"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/comments?post=109"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/109\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/media?parent=109"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/categories?post=109"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/tags?post=109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}