{"id":111,"date":"2008-10-15T13:00:18","date_gmt":"2008-10-15T11:00:18","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/enfaserem\/?p=111"},"modified":"2008-10-15T13:00:18","modified_gmt":"2008-10-15T11:00:18","slug":"los-tertuleros","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/2008\/10\/15\/los-tertuleros\/","title":{"rendered":"Los tertuleros"},"content":{"rendered":"<p>El reciente desenlace de la demanda por injurias graves que el din\u00e1mico alcalde de Madrid interpuso contra uno de los m\u00e1s sintonizados nombres del panorama radiof\u00f3nico nacional ha vuelto a traer al primer plano de la palestra informativa toda la madeja verbal y los bastidores ocultos de la radio, ese gigante ciego de lengua incansable y memoria de pez. La radio hoy puede clasificarse\/reducirse en\/a tres esferas fundamentales: la musical \u2013 por as\u00ed llamarla en las cadenas corporativas, pues en puridad s\u00f3lo la atiende Radio Nacional -; la publicitaria \u2013 complemento indispensable de la anterior, que la sustenta y a la vez reduce, al punto de ocupar m\u00e1s tiempo que las canciones en ciertos programas supuestamente dedicados a la m\u00fasica \u2013, y la esfera opinatriz, o sea los tertuleros, que son quienes meten ca\u00f1a diaria al asunto, arrastran audiencias y en definitiva m\u00e1s servicio hacen en el atasco o el currele, asordando con su verborrea cruzada la bocina del pasmado de delante o las quejas del compa\u00f1ero que no termina de cuadrar el balance y a quien el ni\u00f1o no le ha dejado pegar ojo, hombre.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"\/\/a1.idata.over-blog.com\/136x110\/1\/63\/75\/03\/2255140608_53f77581b8.jpg\" alt=\"\" width=\"136\" height=\"110\" \/>Dejando al margen al director del cotarro, supuesto moderador que sin embargo no puede evitar se le escape alg\u00fan uppercut de cuando en cuando, en primer lugar tenemos al tertulero oficial, un se\u00f1or sin otra dedicaci\u00f3n conocida que la de acudir a cuanta tertulia se le ofrezca \u2013 eligiendo seg\u00fan pago \u2013 y con una capacidad camale\u00f3nicamente asombrosa para defender una opini\u00f3n en un programa y la contraria en el siguiente. Este tertulero oficial es el tipo m\u00e1s genuino, m\u00e1s vers\u00e1til y sagaz de tertulero, pero a d\u00eda de hoy se encuentra en v\u00edas de extinci\u00f3n, pues las cadenas prefieren asegurarse tertuleros ideol\u00f3gicamente afines, corporativos, predecibles como puntos cardinales, con lo que de entrada le quitan toda la gracia que el asunto pudiera tener. Un segundo tipo es el tertulero ocasional. El ocasional viene avalado por la aureola de sus logros profesionales, y su incorporaci\u00f3n suele deberse a una coyuntura de la actualidad que exige para pronunciarse de ciertos pilares t\u00e9cnicos; por ello, una vez que los ha expuesto al grupo se convierte en gui\u00f1ol sin ventr\u00edlocuo, nadie le hace caso y \u00e9l mismo se da cuenta de que lo suyo poco tiene que ver con la morcilla verbal, \u00e9l es hombre de flexo y persiana bajada y por tanto deja de intervenir. Como es l\u00f3gico renuncia o le echan. El \u00faltimo tipo b\u00e1sico es el del tertulero-columnista. Dir\u00edase \u00e9ste un animal fuera de h\u00e1bitat, como el ocasional, pero por la fogosidad con que algunos se emplean m\u00e1s se asemejan al tipo corporativo; de hecho muchos doblan en tertulero por obligaciones de contrato con quienes les editan en papel, que tambi\u00e9n poseen la cadena de radio y as\u00ed se aseguran la obediencia ideol\u00f3gico-corporativa y del tir\u00f3n se autopromocionan, ahorr\u00e1ndose adem\u00e1s un sueldo.<\/p>\n<p>Entre todos ahorman un espect\u00e1culo ac\u00fastico rara vez sugestivo y siempre ruidoso. La mayor\u00eda no son sino la expresi\u00f3n amplificada de la general pr\u00e1ctica espa\u00f1ola de no escuchar al de enfrente y exponer la r\u00e9plica siempre en un tono m\u00e1s alto: lo opuesto a una tertulia merecedora de tal nombre. S\u00f3lo se diferencian de las verduleras chismosas en que ellos cobran por darle a la h\u00fameda.<\/p>\n<p style=\"text-align: right;\">(<em>El Norte de Castilla<\/em>, octubre de 2008)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El reciente desenlace de la demanda por injurias graves que el din\u00e1mico alcalde de Madrid interpuso contra uno de los m\u00e1s sintonizados nombres del panorama radiof\u00f3nico nacional ha vuelto a traer al primer plano de la palestra informativa toda la madeja verbal y los bastidores ocultos de la radio, ese gigante ciego de lengua incansable [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,9],"tags":[839,877],"class_list":["post-111","post","type-post","status-publish","format-standard","hentry","category-columnas","category-antes-de-la-arrancada","tag-sociedad","tag-tertuleros"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/comments?post=111"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/111\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/media?parent=111"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/categories?post=111"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/tags?post=111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}