{"id":1131,"date":"2016-03-03T19:00:19","date_gmt":"2016-03-03T18:00:19","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/enfaserem\/?p=1131"},"modified":"2016-03-03T19:00:19","modified_gmt":"2016-03-03T18:00:19","slug":"petaloso","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/2016\/03\/03\/petaloso\/","title":{"rendered":"Petaloso"},"content":{"rendered":"<p><a href=\"\/enfaserem\/wp-content\/uploads\/sites\/14\/2016\/03\/petaloso-e1457027957630.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-1132\" title=\"petaloso\" src=\"\/enfaserem\/wp-content\/uploads\/sites\/14\/2016\/03\/petaloso-e1457027957630.jpg\" alt=\"\" width=\"240\" height=\"135\" \/><\/a>O sea con muchos p\u00e9talos. Con este adjetivo derivado, que \u00e9l invent\u00f3 para describir una flor (de g\u00e9nero masculino en italiano), el ni\u00f1o <strong>Matteo<\/strong>, de ocho a\u00f1os, ha conseguido en siete d\u00edas demostrar la fuerza vital, creadora del lenguaje con mayor nitidez y fulgor que cualquier voluntarioso manual de divulgaci\u00f3n. Un encargo escolar, un error feliz, la conjunci\u00f3n de una profesora sensible y una Academia de o\u00eddos abiertos: la historia tiene algo de cuento de hadas y de f\u00e1bula tambi\u00e9n, y el que al final se incorpore o no el t\u00e9rmino al diccionario no empa\u00f1a en nada el valor po\u00e9tico y did\u00e1ctico de esta genialidad infantil (todo genio tiene algo de ni\u00f1o). Como ha demostrado Matteo con solo ocho letras, la palabra justa, incluso en un tiempo tan ic\u00f3nico e impaciente como el nuestro, que prefiere comunicarse con min\u00fasculas sand\u00edas faciales, sigue siendo la v\u00eda de comunicaci\u00f3n m\u00e1s potente. El que adem\u00e1s la palabra haya sido inventada no hace sino subrayar la cualidad org\u00e1nica, maleable de la lengua, y su infinita capacidad para sorprender.<\/p>\n<p>El neologismo no es solo un derecho sino casi una obligaci\u00f3n del escritor, y solo por esto todos los juntaletras deber\u00edamos estar agradecidos al ni\u00f1o. La literatura es ante todo juego seg\u00fan <strong>Cort\u00e1zar<\/strong>, quien sin duda hubiera celebrado este relato fant\u00e1stico, y uno mismo, tan reacio a dar consejos, aconsejar\u00eda no obstante a Matteo que no deje de estirar, contraer y retorcer las palabras, de zambullirse en ellas y confundirlas alegremente, en definitiva de jugar con el lenguaje, ese organismo multiforme que se ofrece como un sol sin prisa y que es el factor que m\u00e1s conforma al hombre, al ni\u00f1o. Ver c\u00f3mo el lenguaje florece en un ni\u00f1o es uno de los mayores deleites y asombros que la vida ha tenido a bien regalarnos, y que haya sido un ni\u00f1o el que haya conseguido con un adjetivo florido un milagro de comunicaci\u00f3n tal no puede dejar de celebrarse y sonre\u00edrse.<\/p>\n<p style=\"text-align: right;\">(<em>El Norte de Castilla<\/em>, 3\/3\/2016)<\/p>\n<p style=\"text-align: left;\"><a title=\"@enfaserem\" href=\"https:\/\/twitter.com\/enfaserem\" target=\"_blank\" rel=\"external nofollow\">@enfaserem<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O sea con muchos p\u00e9talos. Con este adjetivo derivado, que \u00e9l invent\u00f3 para describir una flor (de g\u00e9nero masculino en italiano), el ni\u00f1o Matteo, de ocho a\u00f1os, ha conseguido en siete d\u00edas demostrar la fuerza vital, creadora del lenguaje con mayor nitidez y fulgor que cualquier voluntarioso manual de divulgaci\u00f3n. Un encargo escolar, un error [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,7],"tags":[192,442,495,522,619,688],"class_list":["post-1131","post","type-post","status-publish","format-standard","hentry","category-ha-ocurrido-esta-ocurriendo-ocurrira","category-columnas","tag-comunicacion","tag-infancia","tag-juego","tag-lenguaje","tag-neologismo","tag-petaloso"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/1131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/comments?post=1131"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/1131\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/media?parent=1131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/categories?post=1131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/tags?post=1131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}