{"id":1207,"date":"2016-12-30T15:56:09","date_gmt":"2016-12-30T14:56:09","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/enfaserem\/?p=1207"},"modified":"2016-12-30T15:56:09","modified_gmt":"2016-12-30T14:56:09","slug":"propositos","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/2016\/12\/30\/propositos\/","title":{"rendered":"Prop\u00f3sitos"},"content":{"rendered":"<p>Con el cambio de calendario llegan inevitables, como llega la calma despu\u00e9s de la tormenta, los prop\u00f3sitos para el a\u00f1o naciente. Que tienden casi siempre, al anotarlos en la cabeza o el papel, a desbocarse en un maximalismo imperial: aprender a tocar la guitarra, terminar la marat\u00f3n de Boston, leer todo <strong>Faulkner<\/strong>, todo <strong>Valle<\/strong>, todo <strong>Shakespeare<\/strong>. M\u00e1s que prop\u00f3sitos son delirios de grandeza, y sin embargo al anotarlos nos parecen incluso modestos; no solo creemos que los llevaremos a cabo sino que estamos seguros de que vamos a. Luego mayo dobla en junio y Valle sin abrir y de la guitarra apenas media docena de acordes, y septiembre en octubre y poco m\u00e1s, y cuando nos queremos dar cuenta otro calendario, y prop\u00f3sitos renovados. Sin embargo no nos reprochamos no haberlos realizado. Mil y un motivos invencibles \u2014por ello irreprochables\u2014 con los que no cont\u00e1bamos se han interpuesto. \u00bfCon los que no cont\u00e1bamos? Esos motivos no suelen ser sino el pu\u00f1ado de vulgaridades que forman la argamasa de los d\u00edas: horarios, celebraciones, espl\u00edn vital. \u00bfPor qu\u00e9 entonces la ceguera de una nueva lista de prop\u00f3sitos? Desde luego, en teor\u00eda, podr\u00edamos cumplirlos. Tenemos la capacidad para ello. Pero como apunt\u00f3 Einstein, en teor\u00eda, la teor\u00eda y la pr\u00e1ctica son lo mismo; en la pr\u00e1ctica no lo son. \u00bfNo es m\u00e1s probable, si nunca los hemos llevado a cabo, que tampoco ahora?<\/p>\n<p>Tal vez la manera de no reincidir en el fracaso sea fijarse metas m\u00e1s cercanas, aun cuando en el momento de fijarlas nos resulten logros \u00ednfimos. \u00bfTodo Shakespeare? De momento <em>Hamlet<\/em>, y solo si <em>Hamlet<\/em>, <em>Macbeth<\/em>. O mejor aun, no fijarse ninguna meta en absoluto. Lo \u00fanico cierto es la incertidumbre, y puesto que los prop\u00f3sitos nacen del deseo, voluble como el coraz\u00f3n, resultar\u00eda m\u00e1s sano, y con el aliciente de toparse de tanto en tanto con una sorpresa grata, simplemente dejarse llevar. Claro que pocas cosas m\u00e1s dif\u00edciles, si es que alguna, que ese <<simplemente>>.<\/p>\n<p style=\"text-align: right;\">(<em>El Norte de Castilla<\/em>, 29\/12\/2016)<\/p>\n<p style=\"text-align: left;\"><a title=\"@enfaserem\" href=\"https:\/\/twitter.com\/enfaserem\" target=\"_blank\" rel=\"external nofollow\">@enfaserem<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con el cambio de calendario llegan inevitables, como llega la calma despu\u00e9s de la tormenta, los prop\u00f3sitos para el a\u00f1o naciente. Que tienden casi siempre, al anotarlos en la cabeza o el papel, a desbocarse en un maximalismo imperial: aprender a tocar la guitarra, terminar la marat\u00f3n de Boston, leer todo Faulkner, todo Valle, todo [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,7],"tags":[342,529,602,731,754],"class_list":["post-1207","post","type-post","status-publish","format-standard","hentry","category-ha-ocurrido-esta-ocurriendo-ocurrira","category-columnas","tag-fin-de-ano","tag-libertad","tag-motivacion","tag-psicologia","tag-realidad"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/1207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/comments?post=1207"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/1207\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/media?parent=1207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/categories?post=1207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/tags?post=1207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}