{"id":1215,"date":"2017-02-02T15:57:22","date_gmt":"2017-02-02T14:57:22","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/enfaserem\/?p=1215"},"modified":"2017-02-02T15:57:22","modified_gmt":"2017-02-02T14:57:22","slug":"salvador-paniker","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/2017\/02\/02\/salvador-paniker\/","title":{"rendered":"Salvador P\u00e1niker"},"content":{"rendered":"<p>Cuenta <strong>Salvador P\u00e1niker<\/strong> en uno de sus diarios, creo que a prop\u00f3sito de <strong>Francisco Ayala<\/strong>, que cuando nos enteramos de que alguien cumple cien a\u00f1os nos gana una especie de sacudida, como si dij\u00e9semos, \u00a1qu\u00e9 tenacidad! Ahora \u00e9l cumple noventa menos un mes, y los cumple como quien cumple veinticinco, o noventa y un d\u00eda. Es que la tenacidad hay que dejarla estar, hay que ser tenaz sin intentarlo. Esta es una de las cosas que P\u00e1niker, contradictorio \u00e9l mismo, no ha dejado de predicar: que hay que conciliar los extremos, Oriente y Occidente, lo retro y lo progre, la tradici\u00f3n y la tecnolog\u00eda, el flirt y la gravedad, la piel y lo trascendente, <strong>Johann Sebastian Bach<\/strong> y la trompeta de <strong>Chet Baker<\/strong>. Lo cual quiere decir que solo son contrarios en la superficie, y que cada cual ha de configurarse su propio men\u00fa, su dietario vital que le ayude a seguir tirando, acaso hasta los noventa. Si quiere, porque tampoco la vida es un valor absoluto, y el derecho a dimitir de ella es consustancial al derecho a ejercerla, pues tal posibilidad, tal elecci\u00f3n dignifica \u2014humaniza\u2014 al individuo: es el n\u00facleo irreductible de su autonom\u00eda.<\/p>\n<p>Aparte de unos \u00a0vol\u00famenes de entrevistas impagables \u2014no entrevistas sino conversaciones: no imponer los l\u00edmites mentales del entrevistador al entrevistado sino estarse en el instante, en la escucha\u2014, SP nos ha ido dejando una serie de libros de memorias \u2014en el sentido m\u00e1s amplio o caprichoso de memoria: anecd\u00f3tica y evocativa y reflexiva\u2014 que son los m\u00e1s \u00fatiles manuales de autoayuda que uno haya encontrado jam\u00e1s, con algunas m\u00e1ximas inagotables que se repiten como p\u00e1jaros migratorios y recurrentes. Jugar los naipes (tomada de Hemingway pero que SP ha hecho suya), hacerse una religi\u00f3n a la carta (y quien dice religi\u00f3n dice men\u00fa intelectual), el relativismo como salud mental, la necesidad de cogerle el gusto a lo dif\u00edcil. Filosof\u00eda, pues, en el genuino sentido del arte de aprender a vivir. Que se trata de ir pasando la maroma.<\/p>\n<p style=\"text-align: right;\">(<em>El Norte de Castilla<\/em>, 2\/2\/2017)<\/p>\n<p style=\"text-align: left;\"><a title=\"@enfaserem\" href=\"https:\/\/twitter.com\/enfaserem\" target=\"_blank\" rel=\"external nofollow\">@enfaserem<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuenta Salvador P\u00e1niker en uno de sus diarios, creo que a prop\u00f3sito de Francisco Ayala, que cuando nos enteramos de que alguien cumple cien a\u00f1os nos gana una especie de sacudida, como si dij\u00e9semos, \u00a1qu\u00e9 tenacidad! Ahora \u00e9l cumple noventa menos un mes, y los cumple como quien cumple veinticinco, o noventa y un d\u00eda. [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,7],"tags":[61,341,679,802,935],"class_list":["post-1215","post","type-post","status-publish","format-standard","hentry","category-ha-ocurrido-esta-ocurriendo-ocurrira","category-columnas","tag-aniversario","tag-filosofia","tag-perfiles","tag-salvador-paniker","tag-vida"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/1215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/comments?post=1215"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/1215\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/media?parent=1215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/categories?post=1215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/tags?post=1215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}