{"id":1254,"date":"2017-06-07T11:16:38","date_gmt":"2017-06-07T09:16:38","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/enfaserem\/?p=1254"},"modified":"2017-06-07T11:16:38","modified_gmt":"2017-06-07T09:16:38","slug":"amsterdam-roja","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/2017\/06\/07\/amsterdam-roja\/","title":{"rendered":"\u00c1msterdam roja"},"content":{"rendered":"<p>Se tiene la imagen de Holanda como la del para\u00edso de la tolerancia. O del infierno de la depravaci\u00f3n. Eutanasia avanzada. Aborto controlado. Asesor\u00eda en hach\u00eds y drogas blandas. Parecen los nombres de materias optativas para una licenciatura on-line, pero no hacen sino sintetizar la situaci\u00f3n real, o al menos la legal \u2014la legalidad es la realidad sancionada\u2014, de la convivencia en los Pa\u00edses Bajos. Donde una bicicleta puede, literalmente, detener a un tranv\u00eda con el que llega a la vez a un cruce, aunque no ahorrarse la reprimenda gestual del conductor del tranv\u00eda \u2014aparte el sobresalto\u2014. Donde la red de trenes funciona puntual y casi silenciosa, aunque si por despiste o ignorancia pagas un billete que no te corresponde te caer\u00e1 una multa digna de un desfalco suizo. Y as\u00ed ha de ser, aun cuando puntualmente escueza.<\/p>\n<p>El ideal de la aplicaci\u00f3n de la ley deber\u00eda ser el automatismo: temporal y general; sin entrar en el contenido, que el contenido viene despu\u00e9s y ser\u00e1, siempre, discutible, graduable, reversible incluso. Esa inmediatez ciega en la aplicaci\u00f3n de las normas \u2014lo contrario a lo habitual en Espa\u00f1a, tierra de la excepci\u00f3n arbitraria, aunque no siempre malintencionada, y la demora end\u00e9mica\u2014, esa certeza en la fiabilidad de la ley proporciona seguridad jur\u00eddica pero sobre todo tranquilidad de esp\u00edritu. Con unas normas claras y funcionales el ciudadano adquiere m\u00e1s autonom\u00eda, porque sabe a qu\u00e9 atenerse, al punto de olvidarse de la norma al asumirla en su conducta por el mero vivir al d\u00eda; el ciudadano es, en suma, m\u00e1s libre.<\/p>\n<p>Holanda es a la autonom\u00eda ciudadana lo que <strong>Kant<\/strong> al pensamiento independiente. Ahora han (re)abierto un burdel en \u00c1msterdam que ser\u00e1 autogestionado por las prostitutas, en situaci\u00f3n legal (tributaci\u00f3n y cotizaci\u00f3n a la SS) desde el 2000: podr\u00e1n determinar sus horarios, saber de antemano la tarifa por el alquiler de la habitaci\u00f3n, ser parte del consejo asesor. \u00bfInfierno? Sospecho <strong>Francisco <\/strong>no lo calificar\u00eda de tal.<\/p>\n<p style=\"text-align: right;\">(<em>El Norte de Castilla<\/em>, 1\/7\/2017)<\/p>\n<p style=\"text-align: left;\">@enfaserem<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se tiene la imagen de Holanda como la del para\u00edso de la tolerancia. O del infierno de la depravaci\u00f3n. Eutanasia avanzada. Aborto controlado. Asesor\u00eda en hach\u00eds y drogas blandas. Parecen los nombres de materias optativas para una licenciatura on-line, pero no hacen sino sintetizar la situaci\u00f3n real, o al menos la legal \u2014la legalidad es [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,7],"tags":[237,419,529,984],"class_list":["post-1254","post","type-post","status-publish","format-standard","hentry","category-ha-ocurrido-esta-ocurriendo-ocurrira","category-columnas","tag-derecho","tag-holanda","tag-libertad","tag-prostitucion"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/1254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/comments?post=1254"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/1254\/revisions"}],"predecessor-version":[{"id":1255,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/1254\/revisions\/1255"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/media?parent=1254"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/categories?post=1254"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/tags?post=1254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}