{"id":1284,"date":"2017-09-28T13:37:33","date_gmt":"2017-09-28T11:37:33","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/enfaserem\/?p=1284"},"modified":"2017-09-28T13:37:33","modified_gmt":"2017-09-28T11:37:33","slug":"el-elegido","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/2017\/09\/28\/el-elegido\/","title":{"rendered":"El elegido"},"content":{"rendered":"<p>\u00bfQu\u00e9 es la realidad? \u00bfC\u00f3mo conocer la esencia, el no\u00fameno de la cosa? Kantianamente no habita el hombre el mundo, el hombre habita el mundo entre sospechas, entre tinieblas. Solo unos pocos elegidos son capaces de ver, con el desgarro que acarrea \u2014incomprensi\u00f3n ajena\u2014 el que se les haya concedido ese don. Pero tambi\u00e9n la voluntad del elegido es muy superior a la de la media, como lo es su capacidad de sacrificio. El elegido ha de cumplir la misi\u00f3n que se le ha encomendado pese a quien pese \u2014empezando por \u00e9l mismo y las posibles, ocasionales dudas que le puedan surgir\u2014, ya que de la misi\u00f3n depende su vida \u2014<em>es<\/em> su vida\u2014 y con el cumplimiento se redime. Y nos redime a los dem\u00e1s, pobres ciegos incapaces de percibir la realidad.<\/p>\n<p>Y algunos no solo ciegos sino beligerantes activos: se oponen, persiguen al elegido con la sa\u00f1a del inquisidor y tratan por todos los medios de que no lleve a cabo su misi\u00f3n \u2014se\u00f1al irrefutable de la verdad y necesidad de la misma\u2014. Por si no fueran bastantes obst\u00e1culos, existe un tercer sector que comprende y apoya la misi\u00f3n, pero que no se quiere implicar <em>de facto<\/em> en ella. Bueno, tambi\u00e9n hay que abrir los ojos a quien uno m\u00e1s quiere, por quien uno se sacrifica, aunque duela; tal es el escal\u00f3n \u00faltimo del hero\u00edsmo, y la prueba que disipa la cuesti\u00f3n de si uno ha sido en verdad elegido o se trata de un facs\u00edmil.<\/p>\n<p>As\u00ed pues, el elegido completar\u00e1 su misi\u00f3n, y si los frutos no son aceptados de inmediato \u2014la ceguera puede ser tan tenaz como la ley de la gravedad\u2014, tampoco se rendir\u00e1 entonces; magn\u00e1nimo, se ofrecer\u00e1 para encontrarse con cuantos ciegos sean necesarios, y se rebajar\u00e1 a su altura, y dialogar\u00e1 con ellos; es decir: les har\u00e1 darse cuenta de cu\u00e1l es la verdad y qui\u00e9n la posee; tras un ejercicio de paciencia infinito, caer\u00e1 sobre los ciegos una epifan\u00eda que los arrasar\u00e1 y conseguir\u00e1n ver. \u00a1S\u00ed, por fin conseguir\u00e1n ver! Y el elegido, realizado, obtener su merecido descanso.<\/p>\n<p style=\"text-align: right;\">(<em>El Norte de Castilla<\/em>, 28\/9\/2017)<\/p>\n<p style=\"text-align: left;\">@enfaserem<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfQu\u00e9 es la realidad? \u00bfC\u00f3mo conocer la esencia, el no\u00fameno de la cosa? Kantianamente no habita el hombre el mundo, el hombre habita el mundo entre sospechas, entre tinieblas. Solo unos pocos elegidos son capaces de ver, con el desgarro que acarrea \u2014incomprensi\u00f3n ajena\u2014 el que se les haya concedido ese don. Pero tambi\u00e9n la [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,7],"tags":[151,305,437,703],"class_list":["post-1284","post","type-post","status-publish","format-standard","hentry","category-ha-ocurrido-esta-ocurriendo-ocurrira","category-columnas","tag-cataluna","tag-espana","tag-independencia","tag-politica"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/1284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/comments?post=1284"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/1284\/revisions"}],"predecessor-version":[{"id":1285,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/1284\/revisions\/1285"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/media?parent=1284"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/categories?post=1284"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/tags?post=1284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}