{"id":132,"date":"2011-10-20T11:54:48","date_gmt":"2011-10-20T09:54:48","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/enfaserem\/?p=132"},"modified":"2011-10-20T11:54:48","modified_gmt":"2011-10-20T09:54:48","slug":"pintadas","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/2011\/10\/20\/pintadas\/","title":{"rendered":"Pintadas"},"content":{"rendered":"<p>Una campa\u00f1a de pintadas est\u00e1 tachonando las fachadas de Valladolid, desde la Circular a Covaresa, desde Constituci\u00f3n a <strong>Manuel de Falla<\/strong>, como una epidemia oto\u00f1al del ladrillo, un mar de caries sin otro prop\u00f3sito que el de atraer la mirada perdida del paseante o del vecino del portal y detenerlas, encendiendo su ira, en las cuatro letras del eslogan de la campa\u00f1a: <<FUMA>>. Que en realidad ni es eslogan ni grito airado, ni denuncia capitalista o ecol\u00f3gica ni invitaci\u00f3n al cambio; hemos hablado de pintadas pero m\u00e1s bien son garabatos que circunstancialmente adoptan la forma de una orden legible, mero af\u00e1n destructivo: <<Hey, \u00bfveis que he plantado mi cagadita y lo orgulloso que estoy?>>. Filos\u00f3ficamente no difiere de una violaci\u00f3n: ambas acciones se limitan a da\u00f1ar el \u00e1mbito de autonom\u00eda de otra persona no solo sin su consentimiento sino sabiendo a priori que les va a producir un da\u00f1o y a sentar mal; o de esa quema de bosques que est\u00e1 convirtiendo el verde gallego en ceniza triste, como en el poema de <strong>Valente<\/strong>. Pero incluso esta otra campa\u00f1a de fuego estar\u00eda m\u00e1s justificada desde un punto de vista est\u00e9tico &#8211; est\u00e9ticamente pervertido y neroniano -, pues la imagen del bosque ardiendo, como la de Roma, se aproxima a lo sublime; un muro de ladrillo violado con un garabato monocolor, aparte las ganas de joder, solo demuestra la zafiedad del gusto de sus autores, aunque este t\u00e9rmino les quede grande. Nada tiene que ver con el aullido urbano, mural y colorista del grafiti, no hay en estos garabatos asomo de arte o voluntad creativa; la guerra de aerosoles entre los grafiteros <strong>Bansky<\/strong> y <strong>Robbo<\/strong> les importa tanto como el Plan Bolonia o la conferencia\/ETA en San Sebasti\u00e1n. Uno les sugerir\u00eda que dirigiesen sus esprays hacia las paredes del sal\u00f3n de su pap\u00e1 o hacia su pelo, y as\u00ed al menos su gesto tendr\u00eda cierto sustrato de rebeld\u00eda, cierta base justificativa que mereciera alguna atenci\u00f3n. Estos no est\u00e1n indignados, solo desorientados y aburridos.<\/p>\n<p style=\"text-align: right;\">(<em>El Norte de Castilla<\/em>, 20\/10\/2011)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una campa\u00f1a de pintadas est\u00e1 tachonando las fachadas de Valladolid, desde la Circular a Covaresa, desde Constituci\u00f3n a Manuel de Falla, como una epidemia oto\u00f1al del ladrillo, un mar de caries sin otro prop\u00f3sito que el de atraer la mirada perdida del paseante o del vecino del portal y detenerlas, encendiendo su ira, en las [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,7],"tags":[703,839],"class_list":["post-132","post","type-post","status-publish","format-standard","hentry","category-ha-ocurrido-esta-ocurriendo-ocurrira","category-columnas","tag-politica","tag-sociedad"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/comments?post=132"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/132\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/media?parent=132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/categories?post=132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/tags?post=132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}