{"id":1360,"date":"2017-12-21T12:22:29","date_gmt":"2017-12-21T11:22:29","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/enfaserem\/?p=1360"},"modified":"2017-12-21T12:22:29","modified_gmt":"2017-12-21T11:22:29","slug":"exito-rotundo","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/2017\/12\/21\/exito-rotundo\/","title":{"rendered":"\u00bf\u00c9xito rotundo?"},"content":{"rendered":"<p>El d\u00eda m\u00e1s corto del a\u00f1o a algunos se les va a hacer muy largo. Estamos hechos de tiempo, e igual que para el ni\u00f1o la tarde de la noche de Reyes no acaba nunca, muchos votantes separatistas no ver\u00e1n el momento en que se cierren las urnas. No deber\u00edan angustiarse; como el <strong>Tancredo<\/strong> de <strong>Lampedusa<\/strong>, los dirigentes han removido las instituciones, agitado el c\u00f3ctel legislativo, en definitiva hecho una hoja de ruta con apariencia de gincana llena de obst\u00e1culos \u2014y solo en apariencia, pues que previstos de inicio\u2014 solo para dejar las cosas como estaban. Y no es que como Tancredo quieran dejarlas igual, pero sab\u00edan que el objetivo declarado, y por el cual han movilizado a sus fieles, era una quimera cuya extrema materializaci\u00f3n ser\u00eda esto que hemos tenido, que estamos o est\u00e1n teniendo hoy, las elecciones. Que salvo se\u00edsmo sorprendente no alumbrar\u00e1n otro resultado que el de dejar, como decimos, el reparto de la tarta parlamentaria m\u00e1s o menos como est\u00e1.<\/p>\n<p>As\u00ed, no cabe sino hablar de \u00e9xito separatista, y quiz\u00e1 de \u00e9xito rotundo. &lt;&lt;Catalu\u00f1a&gt;&gt; ha sido la palabra en 2017 que mayor incremento en las b\u00fasquedas ha experimentado en Google. \u00bfCabe prueba m\u00e1s definitiva? Que para alcanzar este \u00e9xito hayan tenido que jugar con la credulidad de sus fieles es un tributo colateral que el fin justifica de sobra, y ni siquiera un procedimiento novedoso: los sentimientos son maleables y el nacionalismo la corriente pol\u00edtica que con mayor precisi\u00f3n y peso les da forma. Hasta han conseguido convertir a sus dos l\u00edderes medi\u00e1ticos en m\u00e1rtires por la causa, uno en el exilio y el otro en la c\u00e1rcel. \u00bfQu\u00e9 votante independentista no ve en esto un ejemplo m\u00e1ximo de abnegaci\u00f3n del dirigente por el pueblo, algo que ning\u00fan otro estar\u00eda dispuesto a asumir?<\/p>\n<p>Si al final el bloque unionista obtiene un trozo m\u00e1s jugoso, que nadie se lleve a enga\u00f1o sobre qui\u00e9n ha salido vencedor. Estas elecciones solo pueden a\u00f1adir m\u00e1s barriles de \u00e9xito al \u00e9xito que ya ha obtenido el separatismo.<\/p>\n<p style=\"text-align: right;\">(<em>El Norte de Castilla<\/em>, 21\/12\/2017)<\/p>\n<p style=\"text-align: left;\">@enfaserem<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El d\u00eda m\u00e1s corto del a\u00f1o a algunos se les va a hacer muy largo. Estamos hechos de tiempo, e igual que para el ni\u00f1o la tarde de la noche de Reyes no acaba nunca, muchos votantes separatistas no ver\u00e1n el momento en que se cierren las urnas. No deber\u00edan angustiarse; como el Tancredo de [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,7],"tags":[285,703,1006],"class_list":["post-1360","post","type-post","status-publish","format-standard","hentry","category-ha-ocurrido-esta-ocurriendo-ocurrira","category-columnas","tag-elecciones-catalanas","tag-politica","tag-proces"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/1360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/comments?post=1360"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/1360\/revisions"}],"predecessor-version":[{"id":1361,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/1360\/revisions\/1361"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/media?parent=1360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/categories?post=1360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/tags?post=1360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}