{"id":1766,"date":"2019-04-04T15:51:12","date_gmt":"2019-04-04T13:51:12","guid":{"rendered":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/?p=1766"},"modified":"2019-04-04T15:51:12","modified_gmt":"2019-04-04T13:51:12","slug":"historia-falseada","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/2019\/04\/04\/historia-falseada\/","title":{"rendered":"Historia falseada"},"content":{"rendered":"<p>&lt;&lt;En el d\u00eda de hoy, cautivo y desarmado el ej\u00e9rcito rojo\u2026&gt;&gt;. 80 a\u00f1os desde la formalizaci\u00f3n lapidaria de <strong>Franco<\/strong>, pero parece no han bastado para apagar los rescoldos del rencor. La Santa Transici\u00f3n, tan alabada como modelo de flexibilidad, posibilismo y sentido com\u00fan por tantos y tantos, vemos ahora que parece no fue tan ejemplar, m\u00e1s bien un par\u00e9ntesis necesario pero que m\u00e1s pronto o m\u00e1s tarde todos sab\u00edan terminar\u00eda por quebrar. De momento solo en el discurso, pero cu\u00e1ntas veces las palabras llevan a las acciones. El valle no se toca, el valle s\u00ed se toca. Ustedes tienen que pedir perd\u00f3n; no, son ustedes quienes tienen que pedirlo. Aburren con las batallitas del abuelo; \u00bfaburrimos? C\u00f3mo se nota que no se trata de los suyos. Y as\u00ed podr\u00edamos seguir hasta\u2026 Hemos criticado mucho a <strong>L\u00f3pez Obrador<\/strong> por su cruzada por el perd\u00f3n hist\u00f3rico, pero este juego preelectoral del &lt;&lt;y t\u00fa m\u00e1s&gt;&gt; no resulta menos penoso.<\/p>\n<p>Por supuesto, no se trata de olvidar. &lt;&lt;\u00bfOlvida? \u00bfQui\u00e9n olvida?&gt;&gt;, salt\u00f3 <strong>Julio Cort\u00e1zar<\/strong> tras escuchar en la radio de los atentados en la olimpiada de M\u00fanich, periodo de (te\u00f3rica) tregua universal durante el cual los pueblos, seg\u00fan el locutor, olvidaban sus diferencias. Y acota <strong>Pere Gimferrer<\/strong>: &lt;&lt;Es la pregunta de un moralista&gt;&gt;. A los cabezas de cartel no les mueve en absoluto la moral, pues todos sus alegatos pro\/contra est\u00e1n mediatizados hacia el fin de reba\u00f1ar tantos votos como puedan. Nada les importa que se conozca la historia, que nunca es binaria, nunca blanquinegra. Un pueblo con conciencia cr\u00edtica de lo que ocurri\u00f3 \u2014partiendo de la base de que no es posible saber nunca al mil\u00edmetro qu\u00e9 ocurri\u00f3, y que todo o casi todo hecho hist\u00f3rico exige una interpretaci\u00f3n\u2014 es lo \u00faltimo que quieren los cabezas de cartel, pues eso les arruinar\u00eda el discurso simplista y los esl\u00f3ganes voceados. El seguidismo es mucho m\u00e1s manejable, y si hay que falsear los hechos, adelante. Que es otra forma de inducir al olvido, uno mucho m\u00e1s nocivo y peligroso.<\/p>\n<p style=\"text-align: right;\">(<em>El Norte de Castilla<\/em>, 4\/4\/2019)<\/p>\n<p style=\"text-align: left;\">@enfaserem<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&lt;&lt;En el d\u00eda de hoy, cautivo y desarmado el ej\u00e9rcito rojo\u2026&gt;&gt;. 80 a\u00f1os desde la formalizaci\u00f3n lapidaria de Franco, pero parece no han bastado para apagar los rescoldos del rencor. La Santa Transici\u00f3n, tan alabada como modelo de flexibilidad, posibilismo y sentido com\u00fan por tantos y tantos, vemos ahora que parece no fue tan ejemplar, [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,7],"tags":[1145,1154,415,600,703],"class_list":["post-1766","post","type-post","status-publish","format-standard","hentry","category-ha-ocurrido-esta-ocurriendo-ocurrira","category-columnas","tag-elecciones-2019","tag-guerra-civil-espanola","tag-historia","tag-moral","tag-politica"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/1766","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/comments?post=1766"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/1766\/revisions"}],"predecessor-version":[{"id":1767,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/1766\/revisions\/1767"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/media?parent=1766"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/categories?post=1766"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/tags?post=1766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}