{"id":1771,"date":"2019-04-18T18:22:44","date_gmt":"2019-04-18T16:22:44","guid":{"rendered":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/?p=1771"},"modified":"2019-04-18T18:37:01","modified_gmt":"2019-04-18T16:37:01","slug":"cuentos-toxicos","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/2019\/04\/18\/cuentos-toxicos\/","title":{"rendered":"Cuentos t\u00f3xicos"},"content":{"rendered":"<p>Despu\u00e9s de la paridad por decreto, despu\u00e9s del <a href=\"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/2013\/12\/28\/cine-sexista\/\" target=\"_blank\">test de <strong>Bechdel<\/strong><\/a>, despu\u00e9s de las acusaciones an\u00f3nimas y grav\u00edsimas de un sector no menor del #MeToo, ahora le ha tocado a <strong>Caperucita<\/strong>: por reproducir patrones sexistas y oxidados; a <em>Cenicienta<\/em>, por tolerar la esclavitud laboral; a <em>Blancanieves<\/em>, por fomentar el narcisismo y la envidia. A\u00f1\u00e1danse <em>ad libitum<\/em> los motivos que se quieran. Porque toda precauci\u00f3n es poca si de proteger a la infancia se trata. \u00bfQu\u00e9 es m\u00e1s importante, la tradici\u00f3n literaria o el desarrollo sin traumas del ni\u00f1o? \u00bfO es que va usted a decirme qu\u00e9 o qu\u00e9 no le leo a mi hijo? No, por supuesto, pero tampoco quisiera uno que le dijesen qu\u00e9 puede leer al suyo. Y &lt;&lt;suyo&gt;&gt; significa &lt;&lt;cualquiera&gt;&gt;, incluso el del padre airado; igual este un d\u00eda cambia de opini\u00f3n, o se le ocurre leer <em>Los tres cerditos <\/em>a su hijo y \u2014\u00a1anda!\u2014 descubre que tambi\u00e9n est\u00e1 en la lista, o sea no en la estanter\u00eda de la escuela.<\/p>\n<p>Hemos llegado a un punto de delirio \u2014acaso bienintencionado, pero no por ello menos grave ni peligroso\u2014 que se antoja insuperable. Habr\u00eda que explicar a estos convencidos progenitores del poder enriquecedor, y terap\u00e9utico, del s\u00edmbolo en los cuentos de hadas (<strong>Jung<\/strong>); que el mundo no es blanquinegro, y mucho menos blanquiblanco; que una de las experiencias infantiles \u2014y adultas\u2014 m\u00e1s vibrantes es ponerse en los zapatos del protagonista de una aventura llena de peligros sabi\u00e9ndose a salvo entre las s\u00e1banas; que esa asepsia absoluta que pretenden les puede estallar en la cara: &lt;&lt;Aquello que no ve la luz como s\u00edmbolo aparece despu\u00e9s como real&gt;&gt; (<strong>Lacan<\/strong>), y a lo mejor por no leer <em>Hansel y Gretel <\/em>luego el ni\u00f1o es incapaz de resistirse a una chuche. \u00bfExageraci\u00f3n? Ya hay publicado una <em>Santa Jordina <\/em>en lugar de <em>Sant Jordi<\/em>, que adem\u00e1s no mata al drag\u00f3n porque es una hero\u00edna sin crueldad. Podemos recurrir al humor o a la indignaci\u00f3n, pero al final queda solo resignaci\u00f3n y abatimiento. Porque por desgracia no es insuperable, el delirio.<\/p>\n<p style=\"text-align: right;\">(<em>El Norte de Castilla<\/em>, 18\/4\/2019)<\/p>\n<p style=\"text-align: left;\">@enfaserem<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Despu\u00e9s de la paridad por decreto, despu\u00e9s del test de Bechdel, despu\u00e9s de las acusaciones an\u00f3nimas y grav\u00edsimas de un sector no menor del #MeToo, ahora le ha tocado a Caperucita: por reproducir patrones sexistas y oxidados; a Cenicienta, por tolerar la esclavitud laboral; a Blancanieves, por fomentar el narcisismo y la envidia. A\u00f1\u00e1danse ad [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,7],"tags":[274,433,442,517,529],"class_list":["post-1771","post","type-post","status-publish","format-standard","hentry","category-ha-ocurrido-esta-ocurriendo-ocurrira","category-columnas","tag-educacion","tag-igualdad","tag-infancia","tag-lectura","tag-libertad"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/1771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/comments?post=1771"}],"version-history":[{"count":2,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/1771\/revisions"}],"predecessor-version":[{"id":1773,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/1771\/revisions\/1773"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/media?parent=1771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/categories?post=1771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/tags?post=1771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}