{"id":1775,"date":"2019-04-25T15:55:11","date_gmt":"2019-04-25T13:55:11","guid":{"rendered":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/?p=1775"},"modified":"2019-04-25T15:58:52","modified_gmt":"2019-04-25T13:58:52","slug":"la-pinata","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/2019\/04\/25\/la-pinata\/","title":{"rendered":"La pi\u00f1ata"},"content":{"rendered":"<p>Por lo general el suicida no renuncia a la vida porque la odie: renuncia por desencanto. Ha explorado la vida a fondo, invertido en ella una carga notable de ilusi\u00f3n, sin por ello cegarse voluntariamente a los sinsabores (el suicida no es un ingenuo). As\u00ed, el balance hipot\u00e9tico le resulta, si no desproporcionado hacia el platillo del haber, s\u00ed favorable a este. Pero luego la realidad se impone como la incansable roca de <strong>S\u00edsifo<\/strong>, y \u00e9l es incapaz, al contrario que el condenado por los dioses, de hacer de la roca &lt;&lt;su cosa&gt;&gt;, de seguir y seguir y seguir siguiendo. De forma similar, no es infrecuente que quien renuncia a votar entienda la pol\u00edtica como la aplicaci\u00f3n social de principios \u00e9ticos. Como es l\u00f3gico, partiendo de esta concepci\u00f3n dif\u00edcilmente va a tolerar el continuo atentado que d\u00eda a d\u00eda le infligen los pol\u00edticos de carn\u00e9. Quienes, con un truco no por empleado menos eficaz, consiguen campa\u00f1a s\u00ed y campa\u00f1a tambi\u00e9n darle la vuelta a la responsabilidad y hacer recaer la culpa del estado de la realidad en el elector no votante.<\/p>\n<p>Y esta atribuci\u00f3n de culpa no distingue de siglas de marca. Si hubo algo en que los cuatro jinetes televisivos se pusieron de acuerdo antes del inicio de las hostilidades verbales fue en que el ciudadano deb\u00eda verlos, para despu\u00e9s acudir a votar mejor pertrechado. No tanto por el verlos, sino por el votar despu\u00e9s. Cualquiera de los jinetes prefiere mil veces que se vote a una marca contraria a que no se vote. El objetivo primero es alcanzar el p\u00f3dium del poder, pero si no se logra, al menos quedarse en posici\u00f3n de alcanzarlo en pr\u00f3ximo intento, y mientras seguir aspirando sus aromas, que a quienes est\u00e1n en la pomada tambi\u00e9n llegan. Lo que en modo alguno se puede tolerar es que la rueda se detenga, que haya una abstenci\u00f3n tal que obligue a replantearse el invento, y si para ello hay que culpar a quien no vota, pues se culpa: el no votante no tiene rostro, y por tanto no existe. Es la pi\u00f1ata perfecta.<\/p>\n<p style=\"text-align: right;\">(<em>El Norte de Castilla<\/em>, 25\/4\/2019)<\/p>\n<p style=\"text-align: left;\">@enfaserem<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por lo general el suicida no renuncia a la vida porque la odie: renuncia por desencanto. Ha explorado la vida a fondo, invertido en ella una carga notable de ilusi\u00f3n, sin por ello cegarse voluntariamente a los sinsabores (el suicida no es un ingenuo). As\u00ed, el balance hipot\u00e9tico le resulta, si no desproporcionado hacia el [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,7],"tags":[234,1156,1145,701,703,837],"class_list":["post-1775","post","type-post","status-publish","format-standard","hentry","category-ha-ocurrido-esta-ocurriendo-ocurrira","category-columnas","tag-democracia","tag-derecho-al-voto","tag-elecciones-2019","tag-poder","tag-politica","tag-sistema"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/1775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/comments?post=1775"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/1775\/revisions"}],"predecessor-version":[{"id":1776,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/1775\/revisions\/1776"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/media?parent=1775"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/categories?post=1775"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/tags?post=1775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}