{"id":178,"date":"2011-11-10T12:08:40","date_gmt":"2011-11-10T11:08:40","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/enfaserem\/?p=178"},"modified":"2011-11-10T12:08:40","modified_gmt":"2011-11-10T11:08:40","slug":"el-perdedor","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/2011\/11\/10\/el-perdedor\/","title":{"rendered":"El perdedor"},"content":{"rendered":"<p>Cuando el mayor aliciente del \u00fanico debate de campa\u00f1a electoral de unas generales entre los dos l\u00edderes de los partidos mayoritarios es determinar cu\u00e1ntas veces pronunci\u00f3 cada uno la palabra <<empleo>> o interrumpi\u00f3 la intervenci\u00f3n del otro, cu\u00e1ntas se llev\u00f3 la mano al nudo de la corbata o el vaso de agua a la boca, queda claro que el \u00fanico inter\u00e9s del intercambio no fue el contraste pol\u00edtico entre las distintas propuestas presentadas &#8211; caso de que presentaran alguna &#8211; sino la promesa de sangre en vivo. Si lo vimos fue por la lucha, por el brillo, por la gota de sudor en la sien; lo vimos m\u00e1s con los ojos achinados del tirador que con los ojos abiertos de un p\u00fablico dispuesto a ilustrarse, a recibir sin orejeras las palabras de uno y otro lado. \u00bfRealmente hay alguien a quien el debate le haya cambiado su intenci\u00f3n de voto, o que al menos se sentase ante la tele con la mente abierta a un posible cambio? Quiz\u00e1, pero desde luego son una inmensa minor\u00eda de esos 12 millones de espectadores que nos dicen lo siguieron. Claro que tampoco se nos dio la oportunidad de abrir la mente y los o\u00eddos.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"\/\/globedia.com\/imagenes\/usuarios\/noticias\/43075\/1320747686.jpg\" alt=\"\" width=\"242\" height=\"107\" \/>El d\u00eda despu\u00e9s asegur\u00f3 que la barba gan\u00f3 a la calva, con lo que por tanto cabr\u00eda deducir f\u00e1cilmente qui\u00e9n fue el perdedor. Pero el \u00fanico perdedor fue el propio votante, a quien se le brind\u00f3 un parip\u00e9 de debate, un encuentro ama\u00f1ado en el que faltaban tantos participantes con derecho a estar que no importa qui\u00e9n se lleve al final mayor tajada, porque el bote ya se lo han repartido entre <strong>Rajoy<\/strong> y <strong>Rubalcaba<\/strong> antes de que se celebre el concurso. A quienes hubieran denunciado la ominosa Ley <strong>D\u2019Hondt<\/strong> o la no menos ominosa cerraz\u00f3n de listas, lo car\u00edsimo que resulta meter la papela en la urna, etc., todos esos temillas que el ciudadano no se explica y que culpablemente omiten los dos l\u00edderes omnipresentes, no se les dio tribuna, en una forma de censura disfrazada de buena educaci\u00f3n que resulta, si cabe, m\u00e1s hip\u00f3crita. Fue un debate para el pueblo sin el pueblo.<\/p>\n<p style=\"text-align: right;\">(<em>El Norte de Castilla<\/em>, 10\/11\/2011)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuando el mayor aliciente del \u00fanico debate de campa\u00f1a electoral de unas generales entre los dos l\u00edderes de los partidos mayoritarios es determinar cu\u00e1ntas veces pronunci\u00f3 cada uno la palabra o interrumpi\u00f3 la intervenci\u00f3n del otro, cu\u00e1ntas se llev\u00f3 la mano al nudo de la corbata o el vaso de agua a la boca, queda [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,7],"tags":[231,284,703],"class_list":["post-178","post","type-post","status-publish","format-standard","hentry","category-ha-ocurrido-esta-ocurriendo-ocurrira","category-columnas","tag-debate","tag-elecciones","tag-politica"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/comments?post=178"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/178\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/media?parent=178"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/categories?post=178"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/tags?post=178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}