{"id":1840,"date":"2019-09-26T18:16:30","date_gmt":"2019-09-26T16:16:30","guid":{"rendered":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/?p=1840"},"modified":"2019-09-26T18:16:30","modified_gmt":"2019-09-26T16:16:30","slug":"escanos-calientes","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/2019\/09\/26\/escanos-calientes\/","title":{"rendered":"Esca\u00f1os calientes"},"content":{"rendered":"<p>Era un presupuesto de manual, quiz\u00e1 el ep\u00edtome de lo que significa la democracia parlamentaria. Y una oportunidad para acallar las gargantas que los acusaban de ombliguistas, rapaces del poder, preocupados solo por mantener o expandir su feudo con la bandera del ciudadano como excusa. Exponer sus puntos y escuchar a los de quien se sienta en el otro lado de la mesa, tirar y aflojar y llegar a un compromiso inevitablemente intermedio: tesis, ant\u00edtesis y s\u00edntesis, y sin necesidad de haber le\u00eddo a <strong>Hegel<\/strong>. Pero han sido incapaces, y ahora las gargantas est\u00e1n tan hartas que muchas ya ni siquiera tienen ganas de manifestar su desencanto, de repetir otra vez las denuncias consabidas. Se comprende: el tener raz\u00f3n a veces descorazona m\u00e1s que el no tenerla. Sin embargo el fracaso no ha hecho cambiar la actitud de los participantes, que se siguen pasando la pelota de la culpa. O casi todos. <strong>Gabriel Rufi\u00e1n<\/strong> se levant\u00f3 para entonar el yo nos acuso, &lt;&lt;la gente est\u00e1 hasta las narices de nosotros, de todos nosotros&gt;&gt;. No hace falta la ratificaci\u00f3n estad\u00edstica de las encuestas para admitir que el rey est\u00e1 desnudo.<\/p>\n<p>Pero los diputados insisten en la pelota, como insiste la hoja caduca en oto\u00f1o caer, y la voz discordante solo una manifestaci\u00f3n de impotencia in\u00fatil, a la que no hace falta siquiera tratar de ahogar, basta continuar con la farsa y pasarse la pelota hasta noviembre, despu\u00e9s ya se ver\u00e1, total los votos que cuentan son los contables, valga la tautolog\u00eda, y si el 40 % de los convocados a repetir deciden que vayan ellos, que se voten ellos, no importa, los esca\u00f1os se ocupar\u00e1n igual, menudo invento genial, y ante la hip\u00f3tesis m\u00e1s que probable de unos resultados semejantes y de nuevo la necesidad de tirar y aflojar y llegar a un acuerdo, bueno, \u00bfno es el hombre el animal que tropieza dos veces con la misma piedra? Tan genial es el invento que hasta admitir\u00eda un nuevo tropiezo, otro partido abandonado, y eso s\u00ed, mientras, el esca\u00f1o calentito.<\/p>\n<p style=\"text-align: right;\">(<em>El Norte de Castilla<\/em>, 26\/9\/2019)<\/p>\n<p style=\"text-align: left;\">@enfaserem<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Era un presupuesto de manual, quiz\u00e1 el ep\u00edtome de lo que significa la democracia parlamentaria. Y una oportunidad para acallar las gargantas que los acusaban de ombliguistas, rapaces del poder, preocupados solo por mantener o expandir su feudo con la bandera del ciudadano como excusa. Exponer sus puntos y escuchar a los de quien se [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,7],"tags":[231,234,1173,305,701],"class_list":["post-1840","post","type-post","status-publish","format-standard","hentry","category-ha-ocurrido-esta-ocurriendo-ocurrira","category-columnas","tag-debate","tag-democracia","tag-elecciones-10-n","tag-espana","tag-poder"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/1840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/comments?post=1840"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/1840\/revisions"}],"predecessor-version":[{"id":1841,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/1840\/revisions\/1841"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/media?parent=1840"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/categories?post=1840"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/tags?post=1840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}