{"id":1897,"date":"2019-11-28T18:19:51","date_gmt":"2019-11-28T17:19:51","guid":{"rendered":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/?p=1897"},"modified":"2019-11-28T18:19:51","modified_gmt":"2019-11-28T17:19:51","slug":"black-friday","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/2019\/11\/28\/black-friday\/","title":{"rendered":"&#8216;Black Friday&#8217;"},"content":{"rendered":"<p>Alg\u00fan rito hay que tener, sea el de votar el martes siguiente al primer lunes de noviembre, sea el de dejar la tarjeta en n\u00fameros rojos (y la cuenta del vendedor en muy negros) el d\u00eda siguiente a Acci\u00f3n de Gracias. &#8216;Black Friday&#8217;, yes. Y no decimos &#8216;Viernes negro&#8217; porque nadie lo dice, y el comerciante espa\u00f1ol menos que nadie. El anglicismo viene a condensar la creciente, imparable, rid\u00edcula y nociva corriente que como una peste negra \u2014justamente\u2014 afecta al comercio patrio desde hace un pu\u00f1ado de a\u00f1os, y que amenaza con colonizarlo por completo en otros tantos. Esta misma semana he pasado por delante del escaparate de una tienda que vend\u00eda &lt;&lt;ropa espa\u00f1ola&gt;&gt; (polos con el toro de <strong>Osborne<\/strong>, pulseritas rojigualdas\u2026) cuyos anuncios estaban todos en ingl\u00e9s; en un celeb\u00e9rrimo centro comercial, no solo los anuncios, sino el hilo sonoro recitaba en el idioma de <strong>Shakespeare<\/strong> \u2014y de <strong>Trump<\/strong>\u2014 la gavilla de oportunidades. \u00bfQu\u00e9 sentido tiene? \u00bfEst\u00e9tico, porque en ingl\u00e9s &lt;&lt;suena mejor&gt;&gt;, como dicen de las canciones rock? \u00bfPorque da un barniz cosmopolita? M\u00e1s que cosmopolitismo denota catetismo, pero en el fondo poco importa esto; sea cual sea el motivo, se supone se adopta para vender m\u00e1s. \u00bfEs entonces razonable sacudirse de entrada un importante sector que desconoce lo que se le est\u00e1 ofreciendo? Denunciamos que en Catalu\u00f1a multasen al comerciante que quer\u00eda rotular su negocio en castellano, pero aquello ten\u00eda alguna l\u00f3gica (pervertida e ilegal, pero l\u00f3gica al cabo).<\/p>\n<p>Aunque tal vez d\u00e9 igual. El dinero no es verde, no tiene color, y el idioma del dinero tampoco es el ingl\u00e9s o el espa\u00f1ol, sino el idioma universal del deseo \u2014real o ilusorio\u2014, de la manera m\u00e1s efectiva de fomentarlo y explotarlo. Como el ni\u00f1o que no puede esperar a terminarse el bocadillo para comerse la chuche, el comprador si quiere algo lo quiere ya, y si para obtenerlo tiene que reducir su expresi\u00f3n a un \u00edndice apuntador, sea. Y adem\u00e1s, \u00bfno tiene todo el mundo traductor en el m\u00f3vil?<\/p>\n<p style=\"text-align: right;\">(<em>El Norte de Castilla<\/em>, 28\/11\/2019)<\/p>\n<p>@enfaserem<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alg\u00fan rito hay que tener, sea el de votar el martes siguiente al primer lunes de noviembre, sea el de dejar la tarjeta en n\u00fameros rojos (y la cuenta del vendedor en muy negros) el d\u00eda siguiente a Acci\u00f3n de Gracias. &#8216;Black Friday&#8217;, yes. Y no decimos &#8216;Viernes negro&#8217; porque nadie lo dice, y el [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4,7],"tags":[1193,143,522,839],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/1897"}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/comments?post=1897"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/1897\/revisions"}],"predecessor-version":[{"id":1898,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/1897\/revisions\/1898"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/media?parent=1897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/categories?post=1897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/tags?post=1897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}