{"id":1945,"date":"2020-03-05T11:30:05","date_gmt":"2020-03-05T10:30:05","guid":{"rendered":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/?p=1945"},"modified":"2020-03-04T22:43:29","modified_gmt":"2020-03-04T21:43:29","slug":"las-flamigeras","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/2020\/03\/05\/las-flamigeras\/","title":{"rendered":"Las flam\u00edgeras"},"content":{"rendered":"<p>\u00bfEs que no hay mujeres viles? Concluir que no las hay parece ser el \u00faltimo estadio por hollar en esta incansable, hist\u00e9rica cruzada por desmontar las estructuras patriarcales, at\u00e1vicas e injustas que nos ha tocado heredar. Algunos lo han hollado ya. El hecho de tener pene se dir\u00eda un estigma de culpabilidad, algo cuya posesi\u00f3n, aun impuesta, ha de demostrarse se repudia. Solo as\u00ed podr\u00e1 el hombre obtener el beneficio de la duda a los ojos de las flam\u00edgeras.<\/p>\n<p>En la patria de la libert\u00e9, la \u00e9galit\u00e9 y la fraternit\u00e9 acaban de anticipar que esta tendencia es una realidad inmediata e imparable. La concesi\u00f3n a <strong>Polanski<\/strong> de Mejor Director por <em>El oficial y el esp\u00eda<\/em> hizo estallar las \u00faltimas costuras que todav\u00eda pod\u00edan hacer creer que la posici\u00f3n en que lo hab\u00edan puesto no era tan insoportable; actores abandonando el teatro al alim\u00f3n, las flam\u00edgeras en la calle coreando consignas como anatemas&#8230; La cinta ven\u00eda de ganar el Le\u00f3n de Plata en Venecia, y era la que m\u00e1s candidaturas hab\u00eda cosechado para los C\u00e9sar. Pero el hecho de individualizar en Polanski el reconocimiento ha resultado insoportable. Que el director, de 86 a\u00f1os, niegue la \u00faltima acusaci\u00f3n que se le imputa (no judicialmente: ha prescrito) no es el asunto; ni siquiera lo es el que, aun prescrita, sea cierta. El asunto es que ha sido condenado de entrada, equiparando pues denuncia y sentencia firme. Las flam\u00edgeras, con la aquiescencia impl\u00edcita de tantos que callan, se est\u00e1n cargado a <strong>Beccaria<\/strong>, y no solo: ya la Academia Francesa ha anunciado profundos cambios en su organizaci\u00f3n y funcionamiento. Hay que amoldarse al signo de los tiempos, aunque el signo de los tiempos apeste.<\/p>\n<p>Mueve a las flam\u00edgeras el rencor hist\u00f3rico y no un sentimiento de justicia, y vician as\u00ed unos objetivos admirables. No se trata solo de alcanzar un fin, sino del medio por el que se alcanza. Y los medios empleados no difieren, en esencia, de los m\u00e1s oscuros que ha conocido el hombre.<\/p>\n<p style=\"text-align: right;\">(<em>El Norte de Castilla<\/em>, 5\/3\/2020)<\/p>\n<p>@enfaserem<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfEs que no hay mujeres viles? Concluir que no las hay parece ser el \u00faltimo estadio por hollar en esta incansable, hist\u00e9rica cruzada por desmontar las estructuras patriarcales, at\u00e1vicas e injustas que nos ha tocado heredar. Algunos lo han hollado ya. El hecho de tener pene se dir\u00eda un estigma de culpabilidad, algo cuya posesi\u00f3n, [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4,7],"tags":[1123,970,1000,1215],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/1945"}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/comments?post=1945"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/1945\/revisions"}],"predecessor-version":[{"id":1946,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/1945\/revisions\/1946"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/media?parent=1945"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/categories?post=1945"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/tags?post=1945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}