{"id":1965,"date":"2020-04-01T12:24:39","date_gmt":"2020-04-01T10:24:39","guid":{"rendered":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/?p=1965"},"modified":"2020-04-01T12:24:39","modified_gmt":"2020-04-01T10:24:39","slug":"leer-a-nazis","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/2020\/04\/01\/leer-a-nazis\/","title":{"rendered":"Leer a nazis"},"content":{"rendered":"<p>Amazon ha reculado: hacerse con <em>Mein Kampf <\/em>supone apenas unos minutos en la red. Al rev\u00e9s que la ilustrada Gallimard, que hace dos a\u00f1os se retract\u00f3 de reeditar las <em>Bagatelas para una masacre <\/em>de <strong>C\u00e9line<\/strong>, de antisemitismo quiz\u00e1 no menos virulento que el panfleto hitleriano. Adquirir las <em>Bagatelas\u2026<\/em> resulta sin embargo mucho m\u00e1s arduo, y por ello, la retractaci\u00f3n de Gallimard m\u00e1s penosa. El argumento dado \u2014que &lt;&lt;la \u00e9poca&gt;&gt; no estaba preparada para juzgar el texto &lt;&lt;con serenidad&gt;&gt;\u2014 es inconcebible en un editor, salvo como disculpa por miedo a perder hipot\u00e9ticos clientes. Como sea, lo preocupante es la aceptaci\u00f3n del argumento como razonable, o incluso su celebraci\u00f3n.<\/p>\n<p>Si la historia se repite, el enterrar los textos que sembraron o abonaron la infamia no previene sino que fomenta la repetici\u00f3n; el texto hace visible el afecto reprimido, que encuentra as\u00ed una v\u00eda de liberaci\u00f3n y no favorece que estalle m\u00e1s tarde con consecuencias catastr\u00f3ficas.<\/p>\n<p>La censura de C\u00e9line a\u00f1ade otro componente no menos peligroso; no hay vez que no se lo mencione como el autor genial de <em>Muerte a cr\u00e9dito<\/em> y <em>Viaje al fin de la noche<\/em>, pero se le condenan sus textos racistas y se le aparta de las listas oficiales de aniversarios. Se quiere pues un C\u00e9line sin m\u00e1cula, blanquiblanco, lo cual no es solo hip\u00f3crita sino que pretende eliminar la inherente contradicci\u00f3n del hombre, \u00fanico ser capaz de infligir da\u00f1o gratuito pero tambi\u00e9n de entregar su vida gratuitamente. No somos robots, y de nuestra contradicci\u00f3n podemos, con todo, sacar alguna ense\u00f1anza.<\/p>\n<p style=\"text-align: right;\">(<em>El Norte de Castilla<\/em>, 1\/4\/2020)<\/p>\n<p>@enfaserem<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Amazon ha reculado: hacerse con Mein Kampf supone apenas unos minutos en la red. Al rev\u00e9s que la ilustrada Gallimard, que hace dos a\u00f1os se retract\u00f3 de reeditar las Bagatelas para una masacre de C\u00e9line, de antisemitismo quiz\u00e1 no menos virulento que el panfleto hitleriano. Adquirir las Bagatelas\u2026 resulta sin embargo mucho m\u00e1s arduo, y [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4,7],"tags":[1221,156,534,1220,683,839],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/1965"}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/comments?post=1965"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/1965\/revisions"}],"predecessor-version":[{"id":1966,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/1965\/revisions\/1966"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/media?parent=1965"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/categories?post=1965"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/tags?post=1965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}