{"id":2006,"date":"2020-08-07T10:49:17","date_gmt":"2020-08-07T08:49:17","guid":{"rendered":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/?p=2006"},"modified":"2020-08-07T10:56:27","modified_gmt":"2020-08-07T08:56:27","slug":"pieles-rojas","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/2020\/08\/07\/pieles-rojas\/","title":{"rendered":"Pieles rojas"},"content":{"rendered":"<p>El m\u00edtico equipo de f\u00fatbol americano Washington Redskins (pieles rojas) ha decidido rebautizarse porque han ca\u00eddo en la cuenta de que el nombre es racista. Han tardado m\u00e1s de ochenta a\u00f1os en caer. Hasta fin de temporada han decidido permanecer en una suerte de limbo nominal: Equipo de F\u00fatbol de Washington. Luego ya decidir\u00e1n entre comunidad, afici\u00f3n y equipo t\u00e9cnico (cabe entender que con derecho de veto de los patrocinadores, &#8220;promotores&#8221; del ejemplar y muy necesario cambio).<\/p>\n<p>No hay que tomar la noticia a la ligera, pues el resto del mundo desarrollado tenemos la fastidiosa tendencia de importar del planeta americano solo lo peor. \u00bfY si la movida del rey em\u00e9rito es solo el primer paso de un descalabro mon\u00e1rquico total y Espa\u00f1a, como quien dice ma\u00f1ana, se levanta republicana? \u00bfQu\u00e9 ser\u00eda del Pucela? \u00bfY del Madr\u00ed? \u00bfY de er Betis? En buena l\u00f3gica deber\u00edan dejar de ser &lt;&lt;reales&gt;&gt; (el nombre podr\u00eda ser incluso inconstitucional). Claro que a las hinchadas les sentar\u00eda a cuerno quemado; las del balompi\u00e9 son, pese a las apariencias, mucho m\u00e1s mercuriales que las del otro f\u00fatbol, y estando como est\u00e1 la temperatura social, tal cambio de nomenclatura podr\u00eda ser el detonante de un caos que r\u00edete t\u00fa de la covid-19. Y eso por no mencionar los intereses econ\u00f3micos allende nuestras fronteras. \u00bfQui\u00e9nes son estos timadores que me tratan de vender como oficial esta camiseta de <strong>Benzema<\/strong>?<\/p>\n<p>Llegados a este punto solo nos quedar\u00eda, como a <strong>Ner\u00f3n<\/strong> con Roma, sentarnos a ver c\u00f3mo arde el mundo. Y sin ni siquiera el consuelo de unos acordes de lira.<\/p>\n<p style=\"text-align: right;\">(<em>El Norte de Castilla<\/em>, 5\/8\/2020)<\/p>\n<p style=\"text-align: left;\">@enfaserem<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El m\u00edtico equipo de f\u00fatbol americano Washington Redskins (pieles rojas) ha decidido rebautizarse porque han ca\u00eddo en la cuenta de que el nombre es racista. Han tardado m\u00e1s de ochenta a\u00f1os en caer. Hasta fin de temporada han decidido permanecer en una suerte de limbo nominal: Equipo de F\u00fatbol de Washington. Luego ya decidir\u00e1n entre [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4,7],"tags":[366,414,744,1231],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/2006"}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/comments?post=2006"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/2006\/revisions"}],"predecessor-version":[{"id":2007,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/2006\/revisions\/2007"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/media?parent=2006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/categories?post=2006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/tags?post=2006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}