{"id":2009,"date":"2020-08-19T13:44:43","date_gmt":"2020-08-19T11:44:43","guid":{"rendered":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/?p=2009"},"modified":"2020-08-19T13:44:43","modified_gmt":"2020-08-19T11:44:43","slug":"la-decimonovena","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/2020\/08\/19\/la-decimonovena\/","title":{"rendered":"La Decimonovena"},"content":{"rendered":"<p>Tal que hace un siglo se ratific\u00f3 la Decimonovena Enmienda a la Constituci\u00f3n de los Estados Unidos, por la que el sexo (o el &lt;&lt;g\u00e9nero&gt;&gt;, dir\u00edamos ahora: igual hay que poner una enmienda a la enmienda) ya no pod\u00eda impedir el ejercicio del voto. Las mujeres tardaron pues cincuenta a\u00f1os m\u00e1s que los (hombres) negros en que se les reconociera el derecho. \u00bfSignifica esto que hasta el 2059 no habr\u00e1 una mujer en el Despacho Oval? Parece un poco demasi\u00e9, pero si repasamos la historia reciente, y el panorama de la carrera presidencial reci\u00e9n disparada, quiz\u00e1 no tan inveros\u00edmil. Hacia atr\u00e1s, tenemos a una que obtuvo mayor porcentaje de votos que el vencedor, y que se qued\u00f3 sin despacho (aqu\u00ed entran en juego otros factores, pero con todo); hacia delante, la que tiene m\u00e1s posibilidades de alcanzar alguna influencia real en el Oval corre como escudera del candidato dem\u00f3crata. Mujer que adem\u00e1s es negra (y guapa).<\/p>\n<p>\u00bfSer\u00eda una vicepresidenta apta? <strong>Condoleezza Rice<\/strong> demostr\u00f3 ser el halc\u00f3n m\u00e1s dotado del gabinete\/<strong>Bush<\/strong>, y no hay que rascar mucho para se\u00f1alar qu\u00e9 pol\u00edtico europeo es quien merece con mayor justicia la calificaci\u00f3n de estadista. Lo descorazonador es que la conjunci\u00f3n de sexo y raza hacen a la posible vice autom\u00e1ticamente sospechosa de cuota; las cuotas de las encuestas no son menos determinantes que las legales, y el equipo de <strong>Biden<\/strong> la ha elegido, antes que por su val\u00eda, por esos accidentes. Puede ser inteligente, honesta, laboriosa\u2026 pero incluso sus partidarios ven antes el color de la piel y la falda: justo lo que no quer\u00eda <strong>Luther King<\/strong>.<\/p>\n<p style=\"text-align: right;\">(<em>El Norte de Castilla<\/em>, 19\/8\/2020)<\/p>\n<p>@enfaserem<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tal que hace un siglo se ratific\u00f3 la Decimonovena Enmienda a la Constituci\u00f3n de los Estados Unidos, por la que el sexo (o el &lt;&lt;g\u00e9nero&gt;&gt;, dir\u00edamos ahora: igual hay que poner una enmienda a la enmienda) ya no pod\u00eda impedir el ejercicio del voto. Las mujeres tardaron pues cincuenta a\u00f1os m\u00e1s que los (hombres) negros [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4,7],"tags":[1233,1156,1234,606,703],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/2009"}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/comments?post=2009"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/2009\/revisions"}],"predecessor-version":[{"id":2010,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/2009\/revisions\/2010"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/media?parent=2009"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/categories?post=2009"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/tags?post=2009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}