{"id":2083,"date":"2021-02-15T12:11:24","date_gmt":"2021-02-15T11:11:24","guid":{"rendered":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/?p=2083"},"modified":"2021-06-07T12:41:20","modified_gmt":"2021-06-07T10:41:20","slug":"voluntad-de-propaganda","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/2021\/02\/15\/voluntad-de-propaganda\/","title":{"rendered":"\u00bfVoluntad de propaganda?"},"content":{"rendered":"<p>Hace un tiempo escribimos aqu\u00ed, en relaci\u00f3n a <a href=\"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/2018\/11\/18\/reescribir-la-historia\/\"><em>Octubre<\/em><\/a> (<strong>Sergu\u00e9i Einsenstein <\/strong>y <strong>Griori Aleks\u00e1ndrov<\/strong>, 1928), que arte y propaganda no tienen por qu\u00e9 excluirse; a\u00f1ad\u00edamos que en todo caso el film ruso solo era propagand\u00edstico relativamente, y lo compar\u00e1bamos con la frontalidad casi obvia de <em>El triunfo de la voluntad<\/em>. Ahora toca desdecirse, o matizarse; el film de <strong>Leni<\/strong> <strong>Riefenstahl<\/strong> plantea una serie de cuestiones fascinantes que en <em>Octubre<\/em> quedan fuera o solo inciden de manera marginal. La de la propaganda resulta cardinal, y a partir de ella derivan muchas de las otras.<\/p>\n<p>La propaganda es en no poca medida inherente a la naturaleza del cine. Hablar de &lt;&lt;cine de propaganda&gt;&gt; es casi una tautolog\u00eda; muy dif\u00edcil encontrar un film, aun no narrativo, que no afirme un mensaje. Pero es que sobre todo la imagen, debido a la honda fuerza inmediata que produce su recepci\u00f3n, se adecua especialmente al ejercicio de la propaganda como conformadora de voluntades (y mucho m\u00e1s si a la imagen la completa el sonido, como en la \u00bftotalidad? de films con vocaci\u00f3n propagand\u00edstica). Esta fuerza se incrementa \u2014y aqu\u00ed la determinante diferencia entre <em>El triunfo\u2026<\/em> y la mayor\u00eda de las obras de propaganda mejor consideradas (<em>Octubre<\/em>, <em>El nacimiento de una naci\u00f3n<\/em>\u2026)\u2014 si se trata de im\u00e1genes documentales. El aroma de la ficci\u00f3n difumina, disfraza inevitablemente el mensaje, aun un mensaje indudable, de modo paralelo a como lo hace el sue\u00f1o con el contenido manifiesto; el formato documental, por contra, confiere de entrada en la mente del espectador un peso de veracidad extra, un filtro que reduce o elimina la duda. Pero este poder de la imagen documental tiene tambi\u00e9n un reverso perverso: que el realizador haga pasar por veraz informaci\u00f3n o hechos que no lo son. Por supuesto, por mucha voluntad de distanciamiento o de transparencia que ponga el realizador, ning\u00fan documental es capaz de dar la realidad tal cual. Toda decisi\u00f3n formal \u2014punto de vista y duraci\u00f3n de las tomas; uso o no de m\u00fasica, y de qu\u00e9 m\u00fasica; filmaci\u00f3n en blanco y negro o color; selecci\u00f3n y ordenaci\u00f3n de los acontecimientos, etc.\u2014 repercute en el resultado. Como casi todo, se trata pues de una cuesti\u00f3n de l\u00edmite: si las decisiones formales adoptadas han quebrado o no la esencial veracidad de la realidad mostrada.<\/p>\n<p><a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/14\/2021\/02\/el-triunfo-de-la-voluntad.jpeg\"><img loading=\"lazy\" class=\"alignleft wp-image-2085\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/14\/2021\/02\/el-triunfo-de-la-voluntad.jpeg\" alt=\"\" width=\"304\" height=\"170\" \/><\/a>\u00bfY cu\u00e1l fue la realidad del congreso del Partido Nazi, en N\u00faremberg en 1934, que <em>El triunfo de la voluntad<\/em> retrata? El prop\u00f3sito expl\u00edcito de Riefenstahl era hacer un film que no se semejara &lt;&lt;a un noticiario&gt;&gt;; un film que, sin ser &lt;&lt;de argumento&gt;&gt;, mantuviera el inter\u00e9s del espectador como si lo fuera. Y es lo que hace: un film narrativo con im\u00e1genes documentales. As\u00ed, comienza con una serie de planos subjetivos de nubes algodonosas, para cortar a una vista exterior de un avi\u00f3n que desciende y aterriza\u2026 y del que desembarca <strong>Hitler<\/strong>. La secuencia, en sentido literal, es imparcial: un avi\u00f3n que aterriza y un hombre que desembarca; pero la manera de presentarla nos hace leerla, sin demasiada dificultad, como: he aqu\u00ed el Mes\u00edas que desciende de los cielos. Sin embargo, la realizadora dijo que no ten\u00eda ninguna pretensi\u00f3n de aureolar a Hitler como mes\u00edas de nada: simplemente lo consider\u00f3 la manera m\u00e1s efectiva de arrancar el film y presentar al protagonista. Y no puede negarse se trata de un acierto formal que cumple su funci\u00f3n, como tantos otros que pueblan el metraje. Las siguientes tomas muestran a Alemania que se levanta a un d\u00eda hist\u00f3rico (postigos de ventanas que se abren, rostros ba\u00f1ados por blanco sol\u2026); el traslado del canciller, enhiesto en su Mercedes, flanqueado a ambos lados de la carretera por saludos romanos y rostros transportados de cualquier edad y estrato social; finalmente la llegada. Nada de esto resulta, contado as\u00ed, en modo alguno excitante; tampoco el resto del contenido: desfiles que se suceden con mon\u00f3tona precisi\u00f3n y extractos de discursos donde las palabras &lt;&lt;Hitler&gt;&gt; y &lt;&lt;Alemania&gt;&gt; se indentifican machaconas. No obstante, la excitaci\u00f3n se mantiene en todo momento.<\/p>\n<p><a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/14\/2021\/02\/leni-riefenstahl.jpg\"><img loading=\"lazy\" class=\"alignleft wp-image-2087\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/14\/2021\/02\/leni-riefenstahl.jpg\" alt=\"\" width=\"300\" height=\"221\" srcset=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/14\/2021\/02\/leni-riefenstahl.jpg 1600w, https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/14\/2021\/02\/leni-riefenstahl-300x221.jpg 300w, https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/14\/2021\/02\/leni-riefenstahl-768x565.jpg 768w, https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/14\/2021\/02\/leni-riefenstahl-1024x753.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>T\u00e9cnica esencial para lograrlo es la del contrapunto, que LR maneja con pulso de director de orquesta. Ejemplo: muestra de los soldados desfilando (plano A); el rostro arrobado de alguien del p\u00fablico, o el de Hitler con las mand\u00edbulas apretadas (plano B); es el efecto <strong>Kuleshov<\/strong> llevado al extremo: en la primera s\u00edntesis, el espectador extrae la sensaci\u00f3n de entusiasmo y gratitud; en la segunda, de organizaci\u00f3n sin fisuras, de eficacia incomparable. Y de este modo, por acumulaci\u00f3n de distintos &lt;&lt;kuleshovs&gt;&gt;, al final se ha dejado el poso deseado. El contrapunto no se limita a la contraposici\u00f3n de dos planos fijos sin inflexi\u00f3n: se embellece con tr\u00e1velin, tomas a\u00e9reas, planos de situaci\u00f3n &lt;&lt;desde el punto de vista de Dios&gt;&gt;, un poco a la manera de <strong>Hitchcock<\/strong> (solo que antes de que los hiciera Hitchcock famosos)\u2026 Recursos todos que siguen las directrices del montaje de atracciones de <strong>Eisenstein<\/strong> y su prop\u00f3sito expl\u00edcito de manipular al espectador.<\/p>\n<p>\u00bfProduce este uso de los recursos est\u00e9tico-formales una manipulaci\u00f3n que quepa calificar de propagand\u00edstica? Hay un hecho que, en justicia, no puede obviarse: el de que nuestra mirada, retrospectiva, est\u00e1 contaminada por la historia. Por mucho que uno trate de blindarse al espanto del Holocausto y atenerse al texto f\u00edlmico, no puede evitar una vocecita que no deja de susurrarle: &lt;&lt;soluci\u00f3n final&gt;&gt;, &lt;&lt;seis millones&gt;&gt;, &lt;&lt;arte degenerado&gt;&gt;&#8230; De no haberse producido la II Guerra Mundial, o de haber muerto Hitler antes y Alemania no abrazado el NSDAP, \u00bfse asumir\u00eda la cinta con la misma reticencia preventiva, cuando no rechazo frontal? <em>El triunfo\u2026<\/em>, entre otros muchos, obtuvo el Gran Premio en la Exposici\u00f3n Internacional en Par\u00eds en 1937 (&lt;&lt;se lo dieron los enemigos&gt;&gt;, arguy\u00f3 LR para justificar la ausencia de odio o la presencia de propaganda).<\/p>\n<p>Se puede argumentar que justamente la celebraci\u00f3n extranjera prueba la eficacia de la realizaci\u00f3n. Que el montaje se ide\u00f3, desde el \u00e9xtasis de los uniformes a la selecci\u00f3n de los discursos, para dar una impresi\u00f3n de fortaleza pero no de amenaza, de esplendor pero no de imperialismo, y as\u00ed no despertar el recelo de las otras potencias. Pero esto es solo conjetura. Basta el material existente, sin forzar demasidado la lectura, para percibir la carga propagand\u00edstica. \u00bfLa introdujo Riefenstahl a voluntad? Parece improbable que no, pese a su obstinado alegato de asepsia ideol\u00f3gica (no era miembro del partido) y exclusivo empe\u00f1o &lt;&lt;art\u00edstico&gt;&gt;. De cualquier forma, lo indudable es que se trata de un film excepcional.<\/p>\n<p style=\"text-align: right;\">(<em>La sombra del cipr\u00e9s<\/em>, 12\/2\/2021)<\/p>\n<p>@enfaserem<\/p>\n<p>&nbsp;<\/p>\n<p><u>Ficha del film<\/u><\/p>\n<p>T\u00edt: <em>El triunfo de la voluntad<\/em> (<em>Triumph des Willens<\/em>)<\/p>\n<p>A\u00f1o: 1935<\/p>\n<p>Dir.: Leni Riefenstahl<\/p>\n<p>Ints.: no los hay en sentido estricto. Aparecen Adolf Hitler, Joseph Goebbels y otros jerarcas nazis; miembros de las distintas esferas del partido y otras organizaciones sociales; ciudadanos alemanes&#8230;<\/p>\n<p>Alemania, documental, blanco y negro, 114 mins.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hace un tiempo escribimos aqu\u00ed, en relaci\u00f3n a Octubre (Sergu\u00e9i Einsenstein y Griori Aleks\u00e1ndrov, 1928), que arte y propaganda no tienen por qu\u00e9 excluirse; a\u00f1ad\u00edamos que en todo caso el film ruso solo era propagand\u00edstico relativamente, y lo compar\u00e1bamos con la frontalidad casi obvia de El triunfo de la voluntad. Ahora toca desdecirse, o matizarse; [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4,10,983],"tags":[176,264,1250,1249],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/2083"}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/comments?post=2083"}],"version-history":[{"count":4,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/2083\/revisions"}],"predecessor-version":[{"id":2090,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/2083\/revisions\/2090"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/media?parent=2083"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/categories?post=2083"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/tags?post=2083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}