{"id":236,"date":"2011-12-25T19:56:55","date_gmt":"2011-12-25T18:56:55","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/enfaserem\/?p=236"},"modified":"2011-12-25T19:56:55","modified_gmt":"2011-12-25T18:56:55","slug":"poema-de-la-semana-15","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/2011\/12\/25\/poema-de-la-semana-15\/","title":{"rendered":"Poema de la semana"},"content":{"rendered":"<p><a href=\"\/enfaserem\/wp-content\/uploads\/sites\/14\/2011\/12\/pablo-neruda1.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-238\" title=\"pablo neruda\" src=\"\/enfaserem\/wp-content\/uploads\/sites\/14\/2011\/12\/pablo-neruda1.png\" alt=\"\" width=\"322\" height=\"473\" srcset=\"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-content\/uploads\/sites\/14\/2011\/12\/pablo-neruda1.png 322w, https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-content\/uploads\/sites\/14\/2011\/12\/pablo-neruda1-204x300.png 204w\" sizes=\"auto, (max-width: 322px) 100vw, 322px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>ODA AL GATO<\/p>\n<p>&nbsp;<\/p>\n<p>Los animales fueron<br \/>\nimperfectos,<br \/>\nlargos de cola, tristes<br \/>\nde cabeza.<br \/>\nPoco a poco se fueron<br \/>\ncomponiendo,<br \/>\nhaci\u00e9ndose paisaje,<br \/>\nadquiriendo lunares, gracia, vuelo.<br \/>\nEl gato,<br \/>\ns\u00f3lo el gato<br \/>\napareci\u00f3 completo<br \/>\ny orgulloso:<br \/>\nnaci\u00f3 completamente terminado,<br \/>\ncamina solo y sabe lo que quiere.<\/p>\n<p>El hombre quiere ser pescado y p\u00e1jaro,<br \/>\nla serpiente quisiera tener alas,<br \/>\nel perro es un le\u00f3n desorientado,<br \/>\nel ingeniero quiere ser poeta,<br \/>\nla mosca estudia para golondrina,<br \/>\nel poeta trata de imitar la mosca,<br \/>\npero el gato<br \/>\nquiere ser s\u00f3lo gato<br \/>\ny todo gato es gato<br \/>\ndesde bigote a cola,<br \/>\ndesde presentimiento a rata viva,<br \/>\ndesde la noche hasta sus ojos de oro.<\/p>\n<p>No hay unidad<br \/>\ncomo \u00e9l,<br \/>\nno tienen<br \/>\nla luna ni la flor<br \/>\ntal contextura:<br \/>\nes una sola cosa<br \/>\ncomo el sol o el topacio,<br \/>\ny la el\u00e1stica l\u00ednea en su contorno<br \/>\nfirme y sutil es como<br \/>\nla l\u00ednea de la proa de una nave.<br \/>\nSus ojos amarillos<br \/>\ndejaron una sola<br \/>\nranura<br \/>\npara echar las monedas de la noche.<\/p>\n<p>Oh peque\u00f1o<br \/>\nemperador sin orbe,<br \/>\nconquistador sin patria,<br \/>\nm\u00ednimo tigre de sal\u00f3n, nupcial<br \/>\nsult\u00e1n del cielo<br \/>\nde las tejas er\u00f3ticas,<br \/>\nel viento del amor<br \/>\nen la intemperie<br \/>\nreclamas<br \/>\ncuando pasas<br \/>\ny posas<br \/>\ncuatro pies delicados<br \/>\nen el suelo,<br \/>\noliendo,<br \/>\ndesconfiando<br \/>\nde todo lo terrestre,<br \/>\nporque todo<br \/>\nes inmundo<br \/>\npara el inmaculado pie del gato.<\/p>\n<p>Oh fiera independiente<br \/>\nde la casa, arrogante<br \/>\nvestigio de la noche,<br \/>\nperezoso, gimn\u00e1stico<br \/>\ny ajeno,<br \/>\nprofund\u00edsimo gato,<br \/>\npolic\u00eda secreta<br \/>\nde las habitaciones,<br \/>\ninsignia<br \/>\nde un<br \/>\ndesaparecido terciopelo,<br \/>\nseguramente no hay<br \/>\nenigma<br \/>\nen tu manera,<br \/>\ntal vez no eres misterio,<br \/>\ntodo el mundo te sabe y perteneces<br \/>\nal habitante menos misterioso,<br \/>\ntal vez todos lo creen,<br \/>\ntodos se creen due\u00f1os,<br \/>\npropietarios, t\u00edos<br \/>\nde gatos, compa\u00f1eros,<br \/>\ncolegas,<br \/>\ndisc\u00edpulos o amigos<br \/>\nde su gato.<\/p>\n<p>Yo no.<br \/>\nYo no suscribo.<br \/>\nYo no conozco al gato.<br \/>\nTodo lo s\u00e9, la vida y su archipi\u00e9lago,<br \/>\nel mar y la ciudad incalculable,<br \/>\nla bot\u00e1nica,<br \/>\nel gineceo con sus extrav\u00edos,<br \/>\nel por y el menos de la matem\u00e1tica,<br \/>\nlos embudos volc\u00e1nicos del mundo,<br \/>\nla c\u00e1scara irreal del cocodrilo,<br \/>\nla bondad ignorada del bombero,<br \/>\nel atavismo azul del sacerdote,<br \/>\npero no puedo descifrar un gato.<br \/>\nMi raz\u00f3n resbal\u00f3 en su indiferencia,<br \/>\nsus ojos tienen n\u00fameros de oro.<\/p>\n<p>&nbsp;<\/p>\n<p align=\"right\"><strong>Pablo Neruda<\/strong><\/p>\n<p align=\"right\"><em>Navegaciones y regresos<\/em><\/p>\n<p align=\"right\">LOSADA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; ODA AL GATO &nbsp; Los animales fueron imperfectos, largos de cola, tristes de cabeza. Poco a poco se fueron componiendo, haci\u00e9ndose paisaje, adquiriendo lunares, gracia, vuelo. El gato, s\u00f3lo el gato apareci\u00f3 completo y orgulloso: naci\u00f3 completamente terminado, camina solo y sabe lo que quiere. El hombre quiere ser pescado y p\u00e1jaro, la serpiente [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,12],"tags":[534,622,702],"class_list":["post-236","post","type-post","status-publish","format-standard","hentry","category-cubos-con-hojas","category-poema-de-la-semana","tag-libros","tag-neruda","tag-poesia"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/comments?post=236"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/236\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/media?parent=236"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/categories?post=236"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/tags?post=236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}