{"id":25,"date":"2007-09-22T17:15:20","date_gmt":"2007-09-22T15:15:20","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/enfaserem\/?p=25"},"modified":"2007-09-22T17:15:20","modified_gmt":"2007-09-22T15:15:20","slug":"el-ajedrez-o-la-vida","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/2007\/09\/22\/el-ajedrez-o-la-vida\/","title":{"rendered":"El ajedrez o la vida"},"content":{"rendered":"<p><strong>Oscar Wilde<\/strong> ya advirti\u00f3 en <em>La decadencia de la mentira<\/em> c\u00f3mo la vida imita al arte, y ahora, m\u00e1s de cien a\u00f1os despu\u00e9s, el ex campe\u00f3n mundial de ajedrez metido a pol\u00edtico nos viene a descubrir en forma de manual de autoayuda c\u00f3mo la vida imita al ajedrez, que tras varias decenas de siglos a\u00fan no se sabe si es arte, juego, ciencia, o las tres cosas juntas, en cualquier caso una disciplina que excede con mucho el cerebro humano, incluso un cerebro tan privilegiado como el de <strong>Kasparov<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"\/\/www.megustaleer.com\/img\/libros_244\/C847116.jpg\" alt=\"\" width=\"244\" height=\"376\" \/>El objetivo \u00faltimo del libro es que el lector aprenda a leerse a s\u00ed mismo, para, a partir de ah\u00ed, desarrollar un m\u00e9todo personal, y por tanto diferente en cada caso, que a la postre le permita alcanzar el \u00e9xito, lo que cada lector entienda por tal. Objetivo sin duda ambicioso, como por otro lado no pod\u00eda ser de otra manera viniendo el libro de quien viene. Paralelamente a una partida de ajedrez cl\u00e1sica, el volumen se estructura en tres partes. La primera (apertura) incide en la identificaci\u00f3n de las cualidades de cada uno, los puntos fuertes y d\u00e9biles en jerga ajedrec\u00edstica y que Kasparov denomina \u201cel mapa personal\u201d; la segunda (medio juego) resalta la fundamental importancia de un an\u00e1lisis honesto de esos puntos; y la tercera y \u00faltima (final) pretende se\u00f1alar las v\u00edas a tomar para mejorarlos y transmitir la importancia de fijarse nuevas metas para progresar.<\/p>\n<p>Esta tercera parte es la de m\u00e1s inter\u00e9s, por cuanto que abunda en la noci\u00f3n de reto, central de la filosof\u00eda vital de Kasparov junto a la de cambio (\u201cLa perestroika la hicimos entre <strong>Gorbachov<\/strong> y yo\u201d, dijo en cierta ocasi\u00f3n, e <em>Hijo del cambio<\/em> fue el t\u00edtulo en espa\u00f1ol de su primera biograf\u00eda). El hecho de retarse, reitera Kasparov, es el ingrediente esencial en la receta que conduce al \u00e9xito. Tendemos a pensar que si uno posee talento y trabaja con dedicaci\u00f3n, al final triunfar\u00e1; pero para el acaso mejor ajedrecista de todos los tiempos el talento y el esfuerzo s\u00f3lo nos permitir\u00e1n alcanzar un punto confortable a partir del cual, sin nuevos retos, no habr\u00e1 ya avance posible, y donde el \u00fanico cambio, en absoluto deseable, ser\u00eda el de ir hacia atr\u00e1s. Por supuesto en el camino hacia el \u00e9xito nos toparemos con m\u00e1s de un fracaso y m\u00e1s de dos, que el autor no elude: como un mantra, no se cansa de repetir que de los fracasos podemos, y hemos de, extraer ense\u00f1anzas que nos ayuden en el avance posterior. El ogro de Bak\u00fa es en esencia un vitalista, es decir un optimista natural, una de esas personas que en cada rev\u00e9s que sufre \u2013 escasos en el tablero, diarios en su actividad pol\u00edtica actual \u2013 ve, siguiendo la ense\u00f1anza de su \u00eddolo <strong>Churchill<\/strong>, una nueva oportunidad de la que sacar partido. Una vez cerrado, el libro deja el poso, lo quiera considerar o no as\u00ed su autor, que deja cualquier manual de autoayuda al uso: la vaga sensaci\u00f3n de haber asistido a una serie encadenada de recetas m\u00e1gicas sin las dosis concretas con que cocinarlas.<\/p>\n<p style=\"text-align: right;\">(<em>Suplemento cultural<\/em> <em>de El Norte de Castilla<\/em>, septiembre de 2007)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oscar Wilde ya advirti\u00f3 en La decadencia de la mentira c\u00f3mo la vida imita al arte, y ahora, m\u00e1s de cien a\u00f1os despu\u00e9s, el ex campe\u00f3n mundial de ajedrez metido a pol\u00edtico nos viene a descubrir en forma de manual de autoayuda c\u00f3mo la vida imita al ajedrez, que tras varias decenas de siglos a\u00fan [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,9],"tags":[44,296,505,534,773],"class_list":["post-25","post","type-post","status-publish","format-standard","hentry","category-cubos-con-hojas","category-antes-de-la-arrancada","tag-ajedrez","tag-ensayo","tag-kasparov","tag-libros","tag-resenas"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/25","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/comments?post=25"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/25\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/media?parent=25"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/categories?post=25"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/tags?post=25"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}