{"id":273,"date":"2012-01-22T19:35:26","date_gmt":"2012-01-22T18:35:26","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/enfaserem\/?p=273"},"modified":"2012-01-22T19:35:26","modified_gmt":"2012-01-22T18:35:26","slug":"poema-de-la-semana-19","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/2012\/01\/22\/poema-de-la-semana-19\/","title":{"rendered":"Poema de la semana"},"content":{"rendered":"<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"el cielo a medio hacer - transtr\u00f6mer\" src=\"\/\/4.bp.blogspot.com\/_-7qTwJUtan8\/TShOMkH7O7I\/AAAAAAAADbg\/xx6NYk0xGcM\/s1600\/el%2Bcielo%2Ba%2Bmedio%2Bhacer.jpg\" alt=\"\" width=\"231\" height=\"355\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>DESPU\u00c9S DE LA MUERTE DE ALGUIEN<\/p>\n<p>&nbsp;<\/p>\n<p>HUBO una vez un choque<\/p>\n<p>que dej\u00f3 tras de s\u00ed una larga, p\u00e1lida, reluciente cola de cometa.<\/p>\n<p>Esta nos alberga. Hace borrosas las im\u00e1genes de la TV.<\/p>\n<p>Sedimenta como gotas fr\u00edas en los tubos de ventilaci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p>Todav\u00eda se puede esquiar bajo el sol del invierno<\/p>\n<p>entre sotos, donde a\u00fan cuelgan hojas del a\u00f1o pasado.<\/p>\n<p>Parecen p\u00e1ginas arrancadas de viejas gu\u00edas telef\u00f3nicas<\/p>\n<p>\u2014los nombres de los abonados devorados por el fr\u00edo.<\/p>\n<p>&nbsp;<\/p>\n<p>A\u00fan sigue siendo hermoso sentir el latido del propio coraz\u00f3n.<\/p>\n<p>Pero a menudo la sombra se siente m\u00e1s verdadera que el cuerpo.<\/p>\n<p>El samurai parece insignificante<\/p>\n<p>junto a su armadura de negras escamas de drag\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: right;\"><strong>Tomas Transtr\u00f6mer<\/strong><\/p>\n<p style=\"text-align: right;\">(Traducci\u00f3n:<strong> Roberto Mascar\u00f3<\/strong>)<\/p>\n<p style=\"text-align: right;\"><em>El cielo a medio hacer<\/em><\/p>\n<p style=\"text-align: right;\">N\u00d3RDICA LIBROS<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; DESPU\u00c9S DE LA MUERTE DE ALGUIEN &nbsp; HUBO una vez un choque que dej\u00f3 tras de s\u00ed una larga, p\u00e1lida, reluciente cola de cometa. Esta nos alberga. Hace borrosas las im\u00e1genes de la TV. Sedimenta como gotas fr\u00edas en los tubos de ventilaci\u00f3n. &nbsp; Todav\u00eda se puede esquiar bajo el sol del invierno entre [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,12],"tags":[534,702,905],"class_list":["post-273","post","type-post","status-publish","format-standard","hentry","category-cubos-con-hojas","category-poema-de-la-semana","tag-libros","tag-poesia","tag-transtromer"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/comments?post=273"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/273\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/media?parent=273"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/categories?post=273"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/tags?post=273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}