{"id":283,"date":"2012-01-28T19:51:45","date_gmt":"2012-01-28T18:51:45","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/enfaserem\/?p=283"},"modified":"2012-01-28T19:51:45","modified_gmt":"2012-01-28T18:51:45","slug":"bop-de-oficio","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/2012\/01\/28\/bop-de-oficio\/","title":{"rendered":"Bop de oficio"},"content":{"rendered":"<p><a href=\"\/enfaserem\/wp-content\/uploads\/sites\/14\/2012\/01\/jesse_davis-e1327776259321.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-284\" title=\"jesse_davis\" src=\"\/enfaserem\/wp-content\/uploads\/sites\/14\/2012\/01\/jesse_davis-e1327776259321.jpg\" alt=\"\" width=\"150\" height=\"100\" \/><\/a>Con un aforo felizmente m\u00e1s poblado que en ocasiones anteriores, la Sala Borja de Valladolid acogi\u00f3 el pasado jueves el concierto del cuarteto del saxo alto <strong>Jesse Davis<\/strong> (Nueva Orleans, 1965), quien present\u00f3 su <em>bop<\/em> de altas revoluciones acompa\u00f1ado por la que es su secci\u00f3n r\u00edtmica patria favorita: <strong>Joan Monn\u00e9<\/strong> al piano y el contrabajo y la bater\u00eda de cuyo arte ya pudimos disfrutar en el concierto que en la Borja diera el saxo tenor <strong>Scott Hamilton<\/strong>, <strong>Ignasi Gonz\u00e1lez<\/strong> y <strong>Esteve Pi<\/strong>.<\/p>\n<p>El recital comenz\u00f3 con un homenaje a <strong>Tete Montoli\u00fa<\/strong>, con quien Davis comparti\u00f3 escenario en m\u00e1s de una ocasi\u00f3n como <em>sideman<\/em> y a quien calific\u00f3, no sin raz\u00f3n, de gran, gran, gran m\u00fasico. La v\u00eda elegida para el homenaje fue uno de los \u00eddolos de Tete, el inagotable <strong>Thelonious Monk<\/strong>, a quien el saxo de Davis barniz\u00f3 con los primeros de los \u2014muchos\u2014 ecos parkerianos que ofrecer\u00eda a lo largo de la noche. El cuarteto enlaz\u00f3 el blues con el <em>funky<\/em> y el <em>soul-jazz<\/em>, con la composici\u00f3n del pianista de Filadelfia <strong>Bobby Timmons<\/strong> <em>This here<\/em>, uno de esas melod\u00edas construida a partir de <em>riffs<\/em> infecciosos ante las que es imposible tanto mantener quieto el pie como no sonre\u00edr; Davis record\u00f3 con ella al que acaso sea, junto a Parker, su otra gran influencia musical, el orondamente irremplazable <strong><em>Cannonball<\/em> Adderley<\/strong>. Lo cual, por supuesto, no es en modo alguno ins\u00f3lito en un saxo alto. El conocimiento del legado de Parker y Adderley es por contra requisito imprescindible para quien decide hacer del alto su compa\u00f1ero de vida y trabajo; el problema surge si se considera que ese conocimiento es condici\u00f3n suficiente para el completo desarrollo de la personalidad musical propia, cuando es solo condici\u00f3n necesaria, una falla en la que no pocos se han quedado, y en la que algunos que la han superado siguen de vez en cuando volviendo a caer. En general, la actuaci\u00f3n del protagonista, sin dejar de ser disfrutable, dio la sensaci\u00f3n de resultar una faena de oficio; es innegable el dominio de Davis del instrumento \u2014ese uso flexible de la embocadura, esa digitaci\u00f3n vertiginosa\u2014, su caudal sonoro \u2014el micro le sobraba\u2014, pero en raras ocasiones transmiti\u00f3 el abandono que ha de exig\u00edrsele a un solista, y m\u00e1s aun a un volc\u00e1nico solista de <em>bop<\/em>, como lo prueban el uso excesivo de <em>licks<\/em> y citas con que salpic\u00f3 sus intervenciones.<\/p>\n<p>Los \u00e1nimos se templaron con una balada de <strong>Jimmy Dorsey<\/strong> que supuso el marco id\u00f3neo para disfrutar del poder solista de Joan Monn\u00e9, sin duda uno de los momentos m\u00e1s emotivos de la velada. Como acompa\u00f1ante, lo de Monn\u00e9 fue una clase magistral sin descanso, fuese cual fuese el tempo y el color del tema; al saxo de Davis supo leerlo \u2014conducirlo y enriquecerlo\u2014 sin interponerse jam\u00e1s en su camino, casi como si de un <strong>Wynton Kelly<\/strong> redivivo se tratase. Con un toque tan seguro como delicado, a Monn\u00e9 no le hace falta salirse del sector central del teclado salvo cuando la situaci\u00f3n, como en el solo que comentamos, lo pide: tiene t\u00e9cnica de sobra para correr escalas arriba y abajo de las ochenta y ocho, pero no se trata de epatar al personal porque s\u00ed; se trata de tener el buen gusto de tocar lo que corresponde en cada momento, de escuchar al compa\u00f1ero y responder en consecuencia.<\/p>\n<p>El <em>Evidence<\/em> de Monk, <em>Fallen feathers<\/em> (<strong>Quincy Jones<\/strong>) y <em>Eternal triangle<\/em> (<strong>Sonny Stitt<\/strong>) completaron un recital que recibi\u00f3 muchos aplausos, y hasta aullidos, de aprobaci\u00f3n, que se vieron recompensados con una jugosa propina latina.<\/p>\n<p style=\"text-align: right;\">(<em>El Norte de Castilla<\/em>, 28\/1\/2012)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con un aforo felizmente m\u00e1s poblado que en ocasiones anteriores, la Sala Borja de Valladolid acogi\u00f3 el pasado jueves el concierto del cuarteto del saxo alto Jesse Davis (Nueva Orleans, 1965), quien present\u00f3 su bop de altas revoluciones acompa\u00f1ado por la que es su secci\u00f3n r\u00edtmica patria favorita: Joan Monn\u00e9 al piano y el contrabajo [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,6],"tags":[194,465,469,610,773],"class_list":["post-283","post","type-post","status-publish","format-standard","hentry","category-ha-ocurrido-esta-ocurriendo-ocurrira","category-claves-sonoras","tag-concierto","tag-jazz","tag-jesse-davis","tag-musica","tag-resenas"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/283","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/comments?post=283"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/283\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/media?parent=283"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/categories?post=283"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/tags?post=283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}