{"id":598,"date":"2012-10-06T12:50:14","date_gmt":"2012-10-06T10:50:14","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/enfaserem\/?p=598"},"modified":"2012-10-06T12:50:14","modified_gmt":"2012-10-06T10:50:14","slug":"energetico-profesionalismo","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/2012\/10\/06\/energetico-profesionalismo\/","title":{"rendered":"Energ\u00e9tico profesionalismo"},"content":{"rendered":"<p><a href=\"\/enfaserem\/wp-content\/uploads\/sites\/14\/2012\/10\/elliott-murphy-21-12-10-e1349520481179.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-600\" title=\"elliott-murphy-21-12-10\" src=\"\/enfaserem\/wp-content\/uploads\/sites\/14\/2012\/10\/elliott-murphy-21-12-10-e1349520481179.jpg\" alt=\"\" width=\"193\" height=\"200\" \/><\/a>La fama tiene caprichos que el m\u00e9rito no entiende. La fama se entrega a veces \u2015tantas\u2015 a quien no merece su compa\u00f1\u00eda que lo m\u00e1s saludable ser\u00eda no prestarle atenci\u00f3n en absoluto. Lo cual no es f\u00e1cil para quien no recibe sus favores; puede que en s\u00ed no signifique nada, pero su significado indirecto es profundo: menos contratos, menos anticipos; en suma, menos libertad. La trayectoria musical de <strong>Elliott Murphy <\/strong>(Nueva York, 1949) encierra una paradoja peculiar. Con casi cuarenta a\u00f1os y treinta discos, saludados todos con fervor por las distintas esferas de la industria \u2015cr\u00edtica, otros m\u00fasicos\u2015, emparentado en sus comienzos con figuras que ya hace tiempo alcanzaron la condici\u00f3n de mito, <strong>Dylan<\/strong> o <strong>Springsteen<\/strong>, con una legi\u00f3n de seguidores fiel, su nombre sin embargo no ha abandonado nunca cierta marginalidad, incluso cierta oscuridad que le ha hecho impermeable a la atenci\u00f3n del gran p\u00fablico. Valladolid parece sin embargo uno de los nichos con una legi\u00f3n-Murphy asentada, y ayer el Teatro Cervantes mostr\u00f3 una ocupaci\u00f3n m\u00e1s que aceptable.<\/p>\n<p>Murphy present\u00f3, acompa\u00f1ado en cuarteto por <strong>The Normandy All Stars<\/strong> (dos guitarras electroac\u00fasticas, un bajo y una bater\u00eda, m\u00e1s las puntuales intervenciones a la arm\u00f3nica de EM), varios cortes de sus \u00faltimos LP\u2019s \u2014<em>Rain, rain, rain<\/em>; <em>Rock \u2018n Roll \u2018n Rock \u2018n Roll<\/em>; <em>You don\u2019t need to be more than yourself<\/em>\u2014 as\u00ed como un pu\u00f1ado de cl\u00e1sicos de su repertorio, <em>Everything I do leads me back to you<\/em>\u00a0 o <em>You never know you\u2019re in for<\/em>.<\/p>\n<p><a href=\"\/enfaserem\/wp-content\/uploads\/sites\/14\/2012\/10\/murphy-e1349520400743.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-599\" title=\"murphy\" src=\"\/enfaserem\/wp-content\/uploads\/sites\/14\/2012\/10\/murphy-e1349520400743.jpg\" alt=\"\" width=\"200\" height=\"133\" \/><\/a>En escena Murphy da un <strong>Jim Jarmusch <\/strong>melenudo, un \u00a0trovador country al que le gusta interpretar con un punto de teatralidad (esencial en los vocalistas de rock); como instrumentista, no espere encontrarse el oyente con el virtuosismo de un <strong>Ry Cooder<\/strong>: es un \u00ednterprete correcto, de un funcionalismo despegado, que deja los alardes sol\u00edsticos al guitarrista <strong>Olivier Durand<\/strong>. El punto fuerte \u2014el punto m\u00e1s fuerte\u2014 de Murphy se halla en la composici\u00f3n. En la mejor tradici\u00f3n del frondoso \u00e1rbol folk-rock americano \u2015prol\u00edfica, arriesgada, siempre mirando hacia delante sin olvidar de donde viene\u2015, logra dotar a sus composiciones de un equilibrio entre letra y m\u00fasica tan f\u00e1cil en apariencia como dif\u00edcil de alcanzar. Desde luego, la afinidad con Dylan est\u00e1 ah\u00ed, y Murphy no la ha negado nunca \u2015las afinidades son incluso instrumentales\u2015, pero reducirlo a mero calco del de Minnesota es como reducir a <strong>Elmo Hope <\/strong>a calco de <strong>Bud Powell<\/strong>. Son composiciones que por lo general rehuyen la sofisticaci\u00f3n, o digamos que su sofisticaci\u00f3n est\u00e1 precisamente en saber despojarse de arreglos fatuos, y de este modo llegar m\u00e1s directas al oyente. Las armon\u00edas retorcidas de <strong>Steely Dan<\/strong> est\u00e1n muy bien y sin duda asombran, pero hay veces en que despu\u00e9s de otra semana de mierda todo lo que le apetece a uno es batir unas cuantas palmas y pegar algunos gritos con un roncanrol pegadizo y sincopado.<\/p>\n<p>En este sentido, el recital de anoche produjo otra paradoja. El grupo dio la sensaci\u00f3n de haber salido con el papel demasiado aprendido, cada uno de sus miembros en su acotada casilla, y que el margen para la espontaneidad del momento se hab\u00eda reducido a la casi nada \u2014la mayor sorpresa se dio con un problema de empalme sonoro al final del concierto\u2014. Pr\u00e1cticamente todos los temas luc\u00edan el mismo patr\u00f3n \u2014estribillo vocal, solo de guitarra, vuelta al estribillo tocado de forma m\u00e1s encendida\u2014, el mismo <em>tempo<\/em> medio, el mismo tran-tran. Sin embargo, no dejaron por ello de mostrarse en todo momento como unos profesionales entregados y eficaces, y el p\u00fablico supo apreciarlo y agradecerlo, siguiendo los mandados de EM con entusiasmo. La energ\u00eda estuvo presente desde el primer hasta el \u00faltimo acorde, y se pudieron saborear en abundancia el tipo de emociones que solo es capaz de proporcionar el directo y son imposibles de reproducir en el sal\u00f3n de la casa propia por muy <em>hi-fi<\/em> que sea el equipo donde se ponga el ced\u00e9. En resumen, mucha carretera, mucha palma, y una sensaci\u00f3n de gratitud plena a la salida.<\/p>\n<p style=\"text-align: right;\">(<em>El Norte de Castilla<\/em>, 6\/12\/2012)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La fama tiene caprichos que el m\u00e9rito no entiende. La fama se entrega a veces \u2015tantas\u2015 a quien no merece su compa\u00f1\u00eda que lo m\u00e1s saludable ser\u00eda no prestarle atenci\u00f3n en absoluto. Lo cual no es f\u00e1cil para quien no recibe sus favores; puede que en s\u00ed no signifique nada, pero su significado indirecto es [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,6],"tags":[290,610,773,790,883],"class_list":["post-598","post","type-post","status-publish","format-standard","hentry","category-ha-ocurrido-esta-ocurriendo-ocurrira","category-claves-sonoras","tag-elliott-murphy","tag-musica","tag-resenas","tag-rock","tag-the-normandy-all-stars"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/comments?post=598"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/598\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/media?parent=598"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/categories?post=598"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/tags?post=598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}