{"id":649,"date":"2012-12-06T12:25:10","date_gmt":"2012-12-06T11:25:10","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/enfaserem\/?p=649"},"modified":"2012-12-06T12:25:10","modified_gmt":"2012-12-06T11:25:10","slug":"stop-suicidios","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/2012\/12\/06\/stop-suicidios\/","title":{"rendered":"Stop suicidios"},"content":{"rendered":"<p><a href=\"\/enfaserem\/wp-content\/uploads\/sites\/14\/2012\/12\/stop-e1354792975751.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-650\" title=\"stop\" src=\"\/enfaserem\/wp-content\/uploads\/sites\/14\/2012\/12\/stop.png\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>Sol\u00edamos pensar que el suicidio era un asunto de n\u00f3rdicos ociosos porque la falta de sol los condenaba a quedarse encerrados entre las cuatro paredes y el techo de sus casas. Ahora nos damos cuenta de que por lo menos los n\u00f3rdicos tienen o ten\u00edan casas en las que suicidarse, y que el no tenerla, el verse privado de pronto de ella, es causa m\u00e1s acuciante y expeditiva que la ociosidad. \u00bfNos damos cuenta? El aterrador crecimiento exponencial de los suicios derivados de deshaucios ha sido hasta el momento tratado casi siempre \u2015abrumado quiz\u00e1 por las mil y una historias de dolor y sufrimiento diarias de los que todav\u00eda siguen vivos\u2015 m\u00e1s como un da\u00f1o colateral, casi anecd\u00f3tico, de la crisis, que como lo que realmente es: el s\u00edntoma de una enfermedad social que, debido a su presencia continua, amenaza con asumirse de manera rutinaria, como otro dato negro de los muchos datos negros con que nos topamos cada d\u00eda. La rutina supone la ruina siempre, y entonces no habr\u00eda vuelta atr\u00e1s.<\/p>\n<p>Tampoco ayuda el tratamiento informativo oscurantista que se le concede a\u00fan al suicidio. Si la muerte se muestra hoy sin pudor alguno \u2015en alta definici\u00f3n y a la hora del postre\u2015, el suicidio sigue proscrito como el hijo bastardo de un Papa en la historia oficial del catolicismo. Para <strong>Camus<\/strong> el suicidio constitu\u00eda el problema filos\u00f3fico por excelencia. Camus ten\u00eda raz\u00f3n; m\u00e1s aun: si el objetivo de la filosof\u00eda es ense\u00f1ar a vivir bien, el que un hombre se prive voluntariamente de la potencia de bienestar ha de ser considerado un fracaso de la filosof\u00eda m\u00e1s que un fracaso del hombre. Fracaso, desahucio, suicidio. Las tres palabras tienen un eco similar, m\u00e1s all\u00e1 de su carga sem\u00e1ntica estricta. Y una vinculaci\u00f3n indudable. La ra\u00edz de la plaga, hoy, no tiene un vago origen psicol\u00f3gico sino algo tangible, f\u00edsico, ante lo que no caben filof\u00edas abstractas ni velos discretos. Alcanzar cierto estado de equilibrio feliz no es f\u00e1cil. Hacerlo sin techo y suelo es imposible.<\/p>\n<p style=\"text-align: right;\">(<em>El Norte de Castilla,<\/em> 6\/12\/2012)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sol\u00edamos pensar que el suicidio era un asunto de n\u00f3rdicos ociosos porque la falta de sol los condenaba a quedarse encerrados entre las cuatro paredes y el techo de sus casas. Ahora nos damos cuenta de que por lo menos los n\u00f3rdicos tienen o ten\u00edan casas en las que suicidarse, y que el no tenerla, [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,7],"tags":[245,259,529,604,839,853,935],"class_list":["post-649","post","type-post","status-publish","format-standard","hentry","category-ha-ocurrido-esta-ocurriendo-ocurrira","category-columnas","tag-deshaucios","tag-dinero","tag-libertad","tag-muerte","tag-sociedad","tag-suicidio","tag-vida"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/comments?post=649"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/649\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/media?parent=649"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/categories?post=649"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/tags?post=649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}