{"id":659,"date":"2013-01-03T19:54:57","date_gmt":"2013-01-03T18:54:57","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/enfaserem\/?p=659"},"modified":"2013-01-03T19:54:57","modified_gmt":"2013-01-03T18:54:57","slug":"petardos","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/2013\/01\/03\/petardos\/","title":{"rendered":"Petardos"},"content":{"rendered":"<p><a href=\"\/enfaserem\/wp-content\/uploads\/sites\/14\/2013\/01\/petardos-e1357239167585.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-660\" title=\"petardos\" src=\"\/enfaserem\/wp-content\/uploads\/sites\/14\/2013\/01\/petardos.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>Explotan imprevistos como tiros por la espalda. Quiebran el sue\u00f1o con la falta de respeto de las ventas por tel\u00e9fono. No tienen la verdad del grito ni el dolor del llanto, son atentados en miniatura que no demandan nada; tampoco lo proponen, ni reivindican: simplemente se tiran con la vaga intenci\u00f3n de causar un da\u00f1o gratuito, pero son tan in\u00fatiles que ni siquieran conceden el vil placer de presenciar ese potencial da\u00f1o que producen. Existe un problema que no saben acotar ni formular, y el boom de su estallido es solo el lamento de su propia impotencia, una bandera sonora en el desierto que nadie atiende. \u00a1Eh, que te he agredido, hazme caso!, parecen exigir, pero solo consiguen un silencio a\u00fan m\u00e1s solitario que el silencio anterior al boom. La propia vacuidad del petardo queda demostrada en que el petardo tirado por puro hast\u00edo no difiere del tirado por rabia ni con pretensi\u00f3n de <<divertirse>>. La prueba es que en cualquiera de los casos lo m\u00e1s que consiguen es el deseo de tirar otro petardo, que solo, si acaso, generar\u00e1 m\u00e1s ansiedad en quien lo tir\u00f3, m\u00e1s rabia y frustraci\u00f3n.<\/p>\n<p>El petardo es la met\u00e1fora callejera y directa del teledebate. Las ruedas de las as\u00ed llamadas tertulias son la puesta en escena del petardo como forma de expresi\u00f3n. El intercambio verbal no es sino un duelo por ver qui\u00e9n tira el petardo m\u00e1s gordo; no importa el tema a tratar ni lo dicho, y en \u00faltima instancia tampoco qu\u00e9 petardo era el m\u00e1s gordo, porque acto seguido otro tirar\u00e1 un nuevo petardo que ahogar\u00e1 el duelo anterior. El dedazo agresor que acompa\u00f1a al petardo verbal es un petardo gestual, y el sms que el espectador manda en directo y no dura en pantalla m\u00e1s de un parpadeo, un petardo desde la confortable retaguardia. Los cortes publicitarios son una sucesi\u00f3n de petardos mentirosos con un mensaje \u00fanico \u2014adquiera el producto y ser\u00e1 m\u00e1s feliz\u2014, y cuando el petardeo ha terminado, \u00bfqu\u00e9 nos queda?<\/p>\n<p>Y qu\u00e9 importa, mientras nos queden m\u00e1s petardos.<\/p>\n<p style=\"text-align: right;\">(<em>El Norte de Castilla<\/em>, 3\/1\/2013)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Explotan imprevistos como tiros por la espalda. Quiebran el sue\u00f1o con la falta de respeto de las ventas por tel\u00e9fono. No tienen la verdad del grito ni el dolor del llanto, son atentados en miniatura que no demandan nada; tampoco lo proponen, ni reivindican: simplemente se tiran con la vaga intenci\u00f3n de causar un da\u00f1o [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,7],"tags":[231,689,774,833,839,872],"class_list":["post-659","post","type-post","status-publish","format-standard","hentry","category-ha-ocurrido-esta-ocurriendo-ocurrira","category-columnas","tag-debate","tag-petardos","tag-respeto","tag-silencio","tag-sociedad","tag-television"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/comments?post=659"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/659\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/media?parent=659"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/categories?post=659"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/tags?post=659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}