{"id":661,"date":"2013-01-10T22:17:56","date_gmt":"2013-01-10T21:17:56","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/enfaserem\/?p=661"},"modified":"2013-01-10T22:17:56","modified_gmt":"2013-01-10T21:17:56","slug":"regalos","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/2013\/01\/10\/regalos\/","title":{"rendered":"Regalos"},"content":{"rendered":"<p><a href=\"\/enfaserem\/wp-content\/uploads\/sites\/14\/2013\/01\/regalos-e1357852633271.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-662\" title=\"regalos\" src=\"\/enfaserem\/wp-content\/uploads\/sites\/14\/2013\/01\/regalos.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>La ma\u00f1ana de Reyes nos devuelve, lo queramos o no, hayamos incluso adoptado ahora el papel de <strong>Melchor<\/strong> y no el de receptores, a la infancia. La memoria arraigada en la infancia termina aflorando con los catalizadores menos esperados, y a veces tambi\u00e9n con los, de tan esperados, adormecidos. La noche\/ma\u00f1ana de Reyes es uno de estos catalizadores adormecidos por la rutina del calendario, pero, como en el caso de los menos esperados, el resultado es el mismo: el brote sorprendente.<\/p>\n<p>Pero el brote de la memoria infantil, es decir la posesi\u00f3n por el ni\u00f1o que fuimos del adulto que somos, no nos puede hacer olvidar que al fin y al cabo la monta\u00f1a de regalos es solo un espejismo material, valga la contradicci\u00f3n, derivada de la dictadura del calendario. La rutina, incluso la rutina de periodicidad anual, hace que el brote termine perdiendo brillo. El regalo obligado es menos regalo que el regalo tra\u00eddo por el azar de un escaparate. Hay quien considera que ceder a la tentaci\u00f3n del azar es abandonarse al capricho, y que al capricho hay que castrarlo como se castra al pecado. No entienden o no quieren entender que en el capricho hay una ra\u00edz de deseo genuino, de genuina alegr\u00eda, y el que nos regalen algo en un d\u00eda de diario cualquiera supone la confirmaci\u00f3n de que en verdad le importamos a quien nos ha hecho el regalo, que el regalo es libre y no obligado, un acto cierto de amor. No quiere esto decir que no lo sean los tra\u00eddos por las fechas en rojo, pero en estos late siempre una suerte de obligaci\u00f3n, de temor al reproche \u2014reproche ajeno y tambi\u00e9n propio\u2014 en caso de no cumplirla.<\/p>\n<p>Al final todo se reduce a la creaci\u00f3n de ilusi\u00f3n, de una sensaci\u00f3n transitoria de felicidad que, con suerte, se prolongar\u00e1 cuando el regalo se utilice, si es que llega a utilizarse. Y el regalo que uno no espera siempre hace ilusi\u00f3n, incluso si no gusta especialmente. El deseo florece y la posesi\u00f3n marchita; con el regalo inesperado la posesi\u00f3n hace nacer el deseo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ma\u00f1ana de Reyes nos devuelve, lo queramos o no, hayamos incluso adoptado ahora el papel de Melchor y no el de receptores, a la infancia. La memoria arraigada en la infancia termina aflorando con los catalizadores menos esperados, y a veces tambi\u00e9n con los, de tan esperados, adormecidos. La noche\/ma\u00f1ana de Reyes es uno [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,7],"tags":[244,434,627,708,763,844],"class_list":["post-661","post","type-post","status-publish","format-standard","hentry","category-ha-ocurrido-esta-ocurriendo-ocurrira","category-columnas","tag-deseo","tag-ilusion","tag-noche-de-reyes","tag-posesion","tag-regalos","tag-sorpresa"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/comments?post=661"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/661\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/media?parent=661"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/categories?post=661"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/tags?post=661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}