{"id":669,"date":"2013-01-31T20:13:35","date_gmt":"2013-01-31T19:13:35","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/enfaserem\/?p=669"},"modified":"2013-01-31T20:13:35","modified_gmt":"2013-01-31T19:13:35","slug":"urdangarin-virtual","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/2013\/01\/31\/urdangarin-virtual\/","title":{"rendered":"Urdangarin virtual"},"content":{"rendered":"<p><a href=\"\/enfaserem\/wp-content\/uploads\/sites\/14\/2013\/01\/urdangarin-e1359659252178.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-670\" title=\"urdangarin\" src=\"\/enfaserem\/wp-content\/uploads\/sites\/14\/2013\/01\/urdangarin-e1359659252178.jpg\" alt=\"\" width=\"120\" height=\"103\" \/><\/a>La filantrop\u00eda del yerno le puede salir muy cara a don <strong>Juan Carlos,<\/strong> que, quiz\u00e1 harto pero desde luego no perezoso, puso sin dilaci\u00f3n manos a la obra para limpiar preventivamente el da\u00f1o que el Caso N\u00f3os pudiera tener sobre la Casa Real. En todas las familias hay un t\u00edo d\u00edscolo y un poco tarambana del que no se puede hablar, o solo en susurros y cuando los ni\u00f1os ya se han acostado. En esto la familia real parece que no es una excepci\u00f3n, y el yerno le ha salido rana al rey, pero sin conversi\u00f3n posible a pr\u00edncipe; por muchos ducados con que se vista la rana, rana se queda, y la realidad en este caso ha vencido a la magia del cuento. La \u00faltima medida ha sido la eliminaci\u00f3n digital del yerno de la web oficial.<\/p>\n<p>En una instituci\u00f3n tan dada a \u2015y lastrada por\u2015 los s\u00edmbolos, este es un gesto simb\u00f3lico, pleno de buena voluntad pero de eficacia dudosa. Acaso los asesores de la Casa han pensado, no sin raz\u00f3n, que hoy d\u00eda quienes no pertenecemos a las redes sociales y dem\u00e1s puntos de encuentro digital no existimos, que el rastro virtual es m\u00e1s real que el rastro fuera de la pantalla. Solo que hasta en internet, ep\u00edtome de horizontalidad y anonimato, tambi\u00e9n hay clases, y <strong>Urdangarin<\/strong> es esa excepci\u00f3n que confirma la norma general. Borrarlo de la web oficial es como tratar de achicar el agua de un barco inundado con el cuenco de las manos. La tozuda realidad en este caso no tiene nada de virtual, es una realidad f\u00edsica, material, de muchos millones, y un brochazo inform\u00e1tico no creemos que pueda borrar una vinculaci\u00f3n que todo el mundo sabe que existe, ni que minore la ansiedad por conocer la suerte de Urdangarin en el proceso. El duque adem\u00e1s de serlo ha de parecerlo, cierto, y los esfuerzos de la Casa Real son loables, pero ingenuos. Al final, todos los recortes del presupuesto y dem\u00e1s medidas para limpiar la imagen de la Corona quedar\u00e1n en muy poco ante el goteo negro de las revelaciones que el proceso judicial va generando.<\/p>\n<p style=\"text-align: right;\">(<em>El Norte de Castilla<\/em>, 31\/1\/2013)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La filantrop\u00eda del yerno le puede salir muy cara a don Juan Carlos, que, quiz\u00e1 harto pero desde luego no perezoso, puso sin dilaci\u00f3n manos a la obra para limpiar preventivamente el da\u00f1o que el Caso N\u00f3os pudiera tener sobre la Casa Real. En todas las familias hay un t\u00edo d\u00edscolo y un poco tarambana [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,7],"tags":[121,150,433,451,754,839,922],"class_list":["post-669","post","type-post","status-publish","format-standard","hentry","category-ha-ocurrido-esta-ocurriendo-ocurrira","category-columnas","tag-borrado","tag-caso-noos","tag-igualdad","tag-internet","tag-realidad","tag-sociedad","tag-urdangarin"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/comments?post=669"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/669\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/media?parent=669"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/categories?post=669"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/tags?post=669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}